{"id":5239,"date":"2025-04-15T06:10:37","date_gmt":"2025-04-15T06:10:37","guid":{"rendered":"https:\/\/amhazikaron.org\/research\/origine-et-genealogie-des-juifs-celebres\/"},"modified":"2026-07-01T14:22:20","modified_gmt":"2026-07-01T14:22:20","slug":"origine-et-genealogie-des-juifs-celebres","status":"publish","type":"research","link":"https:\/\/amhazikaron.org\/fr\/research\/origine-et-genealogie-des-juifs-celebres\/","title":{"rendered":"Origine et g\u00e9n\u00e9alogie des Juifs c\u00e9l\u00e8bres"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5239\" class=\"elementor elementor-5239 elementor-567\" data-elementor-post-type=\"research\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a5b2e46 e-con-full e-flex e-con e-parent\" data-id=\"a5b2e46\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c838764 e-con-full e-flex e-con e-child\" data-id=\"c838764\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d32fb3 elementor-widget elementor-widget-image\" data-id=\"6d32fb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amhazikaron.org\/fr\/dou-viennent-les-genies\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/Kafka2-1.jpg\" class=\"attachment-medium size-medium wp-image-5243\" alt=\"Franz Kafka\" srcset=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/Kafka2-1.jpg 300w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/Kafka2-1-150x150.jpg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-258f2e1 elementor-widget elementor-widget-text-editor\" data-id=\"258f2e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5 style=\"text-align: center;\"><a href=\"https:\/\/amhazikaron.org\/fr\/dou-viennent-les-genies\/\">D\u2019o\u00f9 viennent les g\u00e9nies<\/a><\/h5>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5571b07 e-con-full e-flex e-con e-child\" data-id=\"5571b07\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b2dc4ec elementor-widget elementor-widget-image\" data-id=\"b2dc4ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amhazikaron.org\/fr\/le-genre-wertheimer\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/05\/\u0412\u0435\u0440\u0442\u0433\u0435\u0439\u043c\u0435\u04402-300x300.webp\" class=\"attachment-medium size-medium wp-image-10867\" alt=\"Max Wertheimer\" srcset=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/05\/\u0412\u0435\u0440\u0442\u0433\u0435\u0439\u043c\u0435\u04402-300x300.webp 300w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/05\/\u0412\u0435\u0440\u0442\u0433\u0435\u0439\u043c\u0435\u04402-1024x1024.webp 1024w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/05\/\u0412\u0435\u0440\u0442\u0433\u0435\u0439\u043c\u0435\u04402-150x150.webp 150w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/05\/\u0412\u0435\u0440\u0442\u0433\u0435\u0439\u043c\u0435\u04402-768x768.webp 768w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/05\/\u0412\u0435\u0440\u0442\u0433\u0435\u0439\u043c\u0435\u04402-1536x1536.webp 1536w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/05\/\u0412\u0435\u0440\u0442\u0433\u0435\u0439\u043c\u0435\u04402-2048x2048.webp 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d5f9a4 elementor-widget elementor-widget-text-editor\" data-id=\"0d5f9a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5 style=\"text-align: center;\"><a href=\"https:\/\/amhazikaron.org\/fr\/le-genre-wertheimer\/\">Le lignage Wertheimer<\/a><\/h5>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-010f233 e-con-full e-flex e-con e-child\" data-id=\"010f233\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-544f792 elementor-widget elementor-widget-image\" data-id=\"544f792\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amhazikaron.org\/fr\/les-rois-du-sucre-et-le-retour-des-ages\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/Lazar_Brodsky2-300x300.jpg\" class=\"attachment-medium size-medium wp-image-5244\" alt=\"Lazar Brodsky\" srcset=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/Lazar_Brodsky2-300x300.jpg 300w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/Lazar_Brodsky2-150x150.jpg 150w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/Lazar_Brodsky2.jpg 651w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-625ec9b elementor-widget elementor-widget-text-editor\" data-id=\"625ec9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5 style=\"text-align: center;\"><a href=\"https:\/\/amhazikaron.org\/fr\/les-rois-du-sucre-et-le-retour-des-ages\/\">Les rois du sucre<br \/>et la nuit des temps<\/a><\/h5>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9b52bf9 e-con-full e-flex e-con e-child\" data-id=\"9b52bf9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb157dd elementor-widget elementor-widget-image\" data-id=\"eb157dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amhazikaron.org\/fr\/barons-juifs\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/\u0413\u0438\u043d\u0446\u0431\u0443\u0440\u04332-300x300.webp\" class=\"attachment-medium size-medium wp-image-5246\" alt=\"Gorazi Ginzburg\" srcset=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/\u0413\u0438\u043d\u0446\u0431\u0443\u0440\u04332-300x300.webp 300w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/\u0413\u0438\u043d\u0446\u0431\u0443\u0440\u04332-150x150.webp 150w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/\u0413\u0438\u043d\u0446\u0431\u0443\u0440\u04332.webp 405w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19753ad elementor-widget elementor-widget-text-editor\" data-id=\"19753ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><a href=\"https:\/\/amhazikaron.org\/fr\/barons-juifs\/\">Les barons juifs<\/a><\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f8a5bc e-con-full e-flex e-con e-child\" data-id=\"7f8a5bc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78febe4 elementor-widget elementor-widget-image\" data-id=\"78febe4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amhazikaron.org\/fr\/la-saga-des-pairies\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/I_L_Peretz_postcard2-300x300.jpg\" class=\"attachment-medium size-medium wp-image-5248\" alt=\"Itzhok-Leibusch Peretz\" srcset=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/I_L_Peretz_postcard2-300x300.jpg 300w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/I_L_Peretz_postcard2-150x150.jpg 150w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/I_L_Peretz_postcard2.jpg 405w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f01a2a elementor-widget elementor-widget-text-editor\" data-id=\"4f01a2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><a href=\"https:\/\/amhazikaron.org\/fr\/la-saga-des-pairies\/\">La saga des Peretz<\/a><\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c7c880b e-con-full e-flex e-con e-child\" data-id=\"c7c880b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6327a97 elementor-widget elementor-widget-image\" data-id=\"6327a97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amhazikaron.org\/fr\/une-chaine-interrompue\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/\u0428\u0442\u0438\u0433\u043b\u0438\u04462-300x300.png\" class=\"attachment-medium size-medium wp-image-5250\" alt=\"Alexander Shtiglitz\" srcset=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/\u0428\u0442\u0438\u0433\u043b\u0438\u04462-300x300.png 300w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/\u0428\u0442\u0438\u0433\u043b\u0438\u04462-150x150.png 150w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/\u0428\u0442\u0438\u0433\u043b\u0438\u04462.png 630w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0b9b53 elementor-widget elementor-widget-text-editor\" data-id=\"f0b9b53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><a href=\"https:\/\/amhazikaron.org\/fr\/une-chaine-interrompue\/\">La cha\u00eene bris\u00e9e&#8230;<\/a><\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-341700d e-con-full e-flex e-con e-child\" data-id=\"341700d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-571c21d elementor-widget elementor-widget-image\" data-id=\"571c21d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amhazikaron.org\/fr\/parente-et-destin\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/ejhenbaum-650x650-1-300x300.jpg\" class=\"attachment-medium size-medium wp-image-5252\" alt=\"Boris Eikhenbaum\" srcset=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/ejhenbaum-650x650-1-300x300.jpg 300w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/ejhenbaum-650x650-1-150x150.jpg 150w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/ejhenbaum-650x650-1.jpg 650w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da345a0 elementor-widget elementor-widget-text-editor\" data-id=\"da345a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><a href=\"https:\/\/amhazikaron.org\/fr\/parente-et-destin\/\">Lignage et destin<\/a><\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-42a4b7f e-con-full e-flex e-con e-child\" data-id=\"42a4b7f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f88f0b3 e-con-full e-flex e-con e-child\" data-id=\"f88f0b3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>D\u2019o\u00f9 viennent les g\u00e9nies Le lignage Wertheimer Les rois du sucreet la nuit des temps Les barons juifs La saga des Peretz La cha\u00eene bris\u00e9e&#8230; Lignage et destin<\/p>\n","protected":false},"featured_media":5253,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-5239","research","type-research","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Origine et g\u00e9n\u00e9alogie des Juifs c\u00e9l\u00e8bres - Am haZikaron<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amhazikaron.org\/fr\/research\/origine-et-genealogie-des-juifs-celebres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Origine et g\u00e9n\u00e9alogie des Juifs c\u00e9l\u00e8bres - Am haZikaron\" \/>\n<meta property=\"og:description\" content=\"D\u2019o\u00f9 viennent les g\u00e9nies Le lignage Wertheimer Les rois du sucreet la nuit des temps Les barons juifs La saga des Peretz La cha\u00eene bris\u00e9e&#8230; Lignage et destin\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amhazikaron.org\/fr\/research\/origine-et-genealogie-des-juifs-celebres\/\" \/>\n<meta property=\"og:site_name\" content=\"Am haZikaron\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jewage\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-01T14:22:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/famous-clr-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"946\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AmhaZikaron\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/research\\\/origine-et-genealogie-des-juifs-celebres\\\/\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/research\\\/origine-et-genealogie-des-juifs-celebres\\\/\",\"name\":\"Origine et g\u00e9n\u00e9alogie des Juifs c\u00e9l\u00e8bres - Am haZikaron\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/research\\\/origine-et-genealogie-des-juifs-celebres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/research\\\/origine-et-genealogie-des-juifs-celebres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/famous-clr-1.jpg\",\"datePublished\":\"2025-04-15T06:10:37+00:00\",\"dateModified\":\"2026-07-01T14:22:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/research\\\/origine-et-genealogie-des-juifs-celebres\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/research\\\/origine-et-genealogie-des-juifs-celebres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/research\\\/origine-et-genealogie-des-juifs-celebres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/famous-clr-1.jpg\",\"contentUrl\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/famous-clr-1.jpg\",\"width\":946,\"height\":630,\"caption\":\"Famous Jews cover\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/research\\\/origine-et-genealogie-des-juifs-celebres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Origine et g\u00e9n\u00e9alogie des Juifs c\u00e9l\u00e8bres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/\",\"name\":\"Am haZikaron\",\"description\":\"\u0418\u043d\u0441\u0442\u0438\u0442\u0443\u0442 \u043d\u0430\u0443\u043a\u0438, \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u044b \u0438 \u043d\u0430\u0441\u043b\u0435\u0434\u0438\u044f \u0435\u0432\u0440\u0435\u0439\u0441\u043a\u043e\u0433\u043e \u043d\u0430\u0440\u043e\u0434\u0430\",\"publisher\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#organization\",\"name\":\"Am haZikaron\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo.svg\",\"width\":48,\"height\":48,\"caption\":\"Am haZikaron\"},\"image\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jewage\",\"https:\\\/\\\/x.com\\\/AmhaZikaron\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Origine et g\u00e9n\u00e9alogie des Juifs c\u00e9l\u00e8bres - Am haZikaron","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amhazikaron.org\/fr\/research\/origine-et-genealogie-des-juifs-celebres\/","og_locale":"fr_FR","og_type":"article","og_title":"Origine et g\u00e9n\u00e9alogie des Juifs c\u00e9l\u00e8bres - Am haZikaron","og_description":"D\u2019o\u00f9 viennent les g\u00e9nies Le lignage Wertheimer Les rois du sucreet la nuit des temps Les barons juifs La saga des Peretz La cha\u00eene bris\u00e9e&#8230; Lignage et destin","og_url":"https:\/\/amhazikaron.org\/fr\/research\/origine-et-genealogie-des-juifs-celebres\/","og_site_name":"Am haZikaron","article_publisher":"https:\/\/www.facebook.com\/jewage","article_modified_time":"2026-07-01T14:22:20+00:00","og_image":[{"width":946,"height":630,"url":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/famous-clr-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AmhaZikaron","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/amhazikaron.org\/fr\/research\/origine-et-genealogie-des-juifs-celebres\/","url":"https:\/\/amhazikaron.org\/fr\/research\/origine-et-genealogie-des-juifs-celebres\/","name":"Origine et g\u00e9n\u00e9alogie des Juifs c\u00e9l\u00e8bres - Am haZikaron","isPartOf":{"@id":"https:\/\/amhazikaron.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amhazikaron.org\/fr\/research\/origine-et-genealogie-des-juifs-celebres\/#primaryimage"},"image":{"@id":"https:\/\/amhazikaron.org\/fr\/research\/origine-et-genealogie-des-juifs-celebres\/#primaryimage"},"thumbnailUrl":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/famous-clr-1.jpg","datePublished":"2025-04-15T06:10:37+00:00","dateModified":"2026-07-01T14:22:20+00:00","breadcrumb":{"@id":"https:\/\/amhazikaron.org\/fr\/research\/origine-et-genealogie-des-juifs-celebres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amhazikaron.org\/fr\/research\/origine-et-genealogie-des-juifs-celebres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/amhazikaron.org\/fr\/research\/origine-et-genealogie-des-juifs-celebres\/#primaryimage","url":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/famous-clr-1.jpg","contentUrl":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/famous-clr-1.jpg","width":946,"height":630,"caption":"Famous Jews cover"},{"@type":"BreadcrumbList","@id":"https:\/\/amhazikaron.org\/fr\/research\/origine-et-genealogie-des-juifs-celebres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/amhazikaron.org\/fr\/principal\/"},{"@type":"ListItem","position":2,"name":"Origine et g\u00e9n\u00e9alogie des Juifs c\u00e9l\u00e8bres"}]},{"@type":"WebSite","@id":"https:\/\/amhazikaron.org\/fr\/#website","url":"https:\/\/amhazikaron.org\/fr\/","name":"Am haZikaron","description":"\u0418\u043d\u0441\u0442\u0438\u0442\u0443\u0442 \u043d\u0430\u0443\u043a\u0438, \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u044b \u0438 \u043d\u0430\u0441\u043b\u0435\u0434\u0438\u044f \u0435\u0432\u0440\u0435\u0439\u0441\u043a\u043e\u0433\u043e \u043d\u0430\u0440\u043e\u0434\u0430","publisher":{"@id":"https:\/\/amhazikaron.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amhazikaron.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/amhazikaron.org\/fr\/#organization","name":"Am haZikaron","url":"https:\/\/amhazikaron.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/amhazikaron.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/logo.svg","contentUrl":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/logo.svg","width":48,"height":48,"caption":"Am haZikaron"},"image":{"@id":"https:\/\/amhazikaron.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jewage","https:\/\/x.com\/AmhaZikaron"]}]}},"_links":{"self":[{"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/research\/5239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/research"}],"about":[{"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/types\/research"}],"version-history":[{"count":2,"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/research\/5239\/revisions"}],"predecessor-version":[{"id":10868,"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/research\/5239\/revisions\/10868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/media\/5253"}],"wp:attachment":[{"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/media?parent=5239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}