{"id":4854,"date":"2016-03-01T12:36:00","date_gmt":"2016-03-01T12:36:00","guid":{"rendered":"https:\/\/amhazikaron.org\/souvenez-vous-de-votre-nom\/"},"modified":"2026-06-29T18:47:03","modified_gmt":"2026-06-29T18:47:03","slug":"souvenez-vous-de-votre-nom","status":"publish","type":"post","link":"https:\/\/amhazikaron.org\/fr\/souvenez-vous-de-votre-nom\/","title":{"rendered":"Rappelle-toi ton nom"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4854\" class=\"elementor elementor-4854 elementor-1593\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31c4f58 e-grid e-con-boxed e-con e-parent\" data-id=\"31c4f58\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fedf9be elementor-widget elementor-widget-image\" data-id=\"fedf9be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"305\" height=\"240\" src=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2016\/03\/\u043f\u043e\u043c\u043d\u0438_\u0438\u043c\u044f_\u0441\u0432\u043e\u0435.jpg\" class=\"attachment-large size-large wp-image-4855\" alt=\"Souviens-toi de ton nom\" srcset=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2016\/03\/\u043f\u043e\u043c\u043d\u0438_\u0438\u043c\u044f_\u0441\u0432\u043e\u0435.jpg 305w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2016\/03\/\u043f\u043e\u043c\u043d\u0438_\u0438\u043c\u044f_\u0441\u0432\u043e\u0435-300x236.jpg 300w\" sizes=\"(max-width: 305px) 100vw, 305px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b305b9 elementor-widget elementor-widget-text-editor\" data-id=\"7b305b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>Savez-vous l&rsquo;histoire de votre nom de famille ? Pouvez-vous croire que les environs regorgent de vos parents ? En qu\u00eate de ses racines, le chroniqueur de\u00a0Jewish.ru\u00a0s&rsquo;est retrouv\u00e9 \u00e0 l&rsquo;institut de Tel-Aviv \u00ab Le peuple de la m\u00e9moire \u00bb et a d\u00e9couvert pourquoi les l\u00e9gendes familiales sont plus importantes que les archives, comment apprendre que les Schiff sont en r\u00e9alit\u00e9 des Cohens qui ont voulu \u00eatre en Allemagne non pas une barque, mais un navire, et s&rsquo;il est effrayant de passer sous le bistouri d&rsquo;un chirurgien nomm\u00e9 Tsirioulnik (Barbier).<\/em><\/p>\n<\/p>\n<p>\u2014 L&rsquo;Institut\u00a0<span style=\"font-weight: bolder;\">\u00ab Am haZikaron \u00bb<\/span>\u00a0(\u00ab Le peuple de la m\u00e9moire \u00bb) a \u00e9t\u00e9 cr\u00e9\u00e9 d\u00e8s 1998 par\u00a0<span style=\"font-weight: bolder;\">Alexander Vidgop<\/span>. Il est originaire de L\u00e9ningrad, et la version sur l&rsquo;origine de sa famille qu&rsquo;il avait entendue de ses proches dans les ann\u00e9es 60\u201370 du si\u00e8cle dernier ne lui convenait pas, \u2014 raconte\u00a0<span style=\"font-weight: bolder;\">Malka Haguel<\/span>. \u2014 Avec une certaine dose de folie, il a commenc\u00e9 \u00e0 \u00ab creuser \u00bb l&rsquo;histoire des Vidgop et a vite compris que la r\u00e9alit\u00e9 diff\u00e9rait grandement de la l\u00e9gende familiale entendue. Apr\u00e8s avoir recueilli les r\u00e9cits de la bouche de 35 de ses parents, Alexander Vidgop a compris qu&rsquo;on ne pouvait pas construire un arbre g\u00e9n\u00e9alogique uniquement sur leurs t\u00e9moignages, et s&rsquo;est tourn\u00e9 vers diverses archives. Mais il s&rsquo;est av\u00e9r\u00e9 qu&rsquo;une partie des documents avait disparu, qu&rsquo;une autre \u00e9tait dans un \u00e9tat tel qu&rsquo;il \u00e9tait impossible de les d\u00e9chiffrer, et que certaines archives refusaient tout simplement de coop\u00e9rer. C&rsquo;est alors qu&rsquo;il a d\u00fb commencer \u00e0 d\u00e9velopper une m\u00e9thodologie ou, si l&rsquo;on veut, un syst\u00e8me de reconstitution de la g\u00e9n\u00e9alogie des familles juives dans une situation o\u00f9 il existe de nombreuses lacunes d&rsquo;information. C&rsquo;est pour \u00e9laborer cette m\u00e9thodologie que notre institut a \u00e9t\u00e9 cr\u00e9\u00e9 par la suite, et le travail dans cette direction se poursuit aujourd&rsquo;hui encore \u2014 parall\u00e8lement \u00e0 la reconstitution de l&rsquo;histoire de noms de famille juifs sp\u00e9cifiques. Aujourd&rsquo;hui, nous poss\u00e9dons d\u00e9j\u00e0 une banque de donn\u00e9es sur l&rsquo;origine et l&rsquo;histoire de milliers de familles juives, de sorte que nous pouvons avec une grande probabilit\u00e9 reconstruire l&rsquo;histoire familiale d&rsquo;une part importante de ceux qui souhaiteront nous adresser une telle demande.<\/p>\n<\/p>\n<p><em>\u00ab \u2014 Sur quoi se fonde cette m\u00e9thodologie ?<\/em><\/p>\n<\/p>\n<p> \u2014 Son principe directeur est qu&rsquo;aucune information, aucune tradition familiale ne peut \u00eatre rejet\u00e9e, aussi incroyable ou insignifiante qu&rsquo;elle puisse para\u00eetre \u00e0 premi\u00e8re vue. C&rsquo;est-\u00e0-dire qu&rsquo;il y a toujours un grain de v\u00e9rit\u00e9 dans de telles l\u00e9gendes. Par exemple, si une famille pr\u00e9tend que son nom provient d&rsquo;un g\u00e9n\u00e9ral de l&rsquo;arm\u00e9e napol\u00e9onienne, alors, \u00e0 d\u00e9faut de g\u00e9n\u00e9ral, un soldat de Napol\u00e9on s&rsquo;y trouvait \u00e0 coup s\u00fbr. Un n\u00e9gociant immens\u00e9ment riche, venu de Perse en Russie pour fonder une nouvelle dynastie juive, peut finalement s&rsquo;av\u00e9rer \u00eatre un petit marchand, mais il est bel et bien venu de Perse en Russie. C&rsquo;est pourquoi nous n&rsquo;ignorons jamais aucun r\u00e9cit, et bien s\u00fbr, la source d&rsquo;information la plus importante pour nous, ce sont les gens. Chacun d&rsquo;eux est capable de nommer ses cousins germains ou issus de germain et sait au moins quelque chose de l&rsquo;histoire familiale\u2026 \u00bb<\/p>\n<\/p>\n<p><em>\u00ab \u2014 Attendez, cela signifie-t-il que les r\u00e9cits oraux sont plus importants pour vous que les documents ?<\/em><\/p>\n<\/p>\n<p> \u2014 Oui, en premier lieu, ce sont les gens qui comptent pour nous. C&rsquo;est-to-dire que le nom de famille pouvait changer, mais la tradition familiale et les pr\u00e9noms adopt\u00e9s dans la famille se maintenaient. \u00bb<\/p>\n<\/p>\n<p>\u00ab \u2014 Il existe en effet de nombreuses variantes d&rsquo;un m\u00eame nom de famille juif, divergeant souvent consid\u00e9rablement les unes des autres, \u2014 intervient un autre collaborateur de l&rsquo;institut, \u00e9galement po\u00e8te, romancier et chercheur<span style=\"font-weight: bolder;\">\u00a0Daniel Kluger<\/span>. \u2014 Et au cours de notre travail, nous d\u00e9terminons pr\u00e9cis\u00e9ment si les porteurs de noms de famille homophones, ou parfois m\u00eame peu ressemblants, sont parents ou non. Prenons par exemple le c\u00e9l\u00e8bre nom Schiff, dont les membres sont des cohanim, c&rsquo;est-\u00e0-dire des descendants du grand pr\u00eatre Aaron. Au d\u00e9but, ils portaient naturellement le nom de Cohen ou Kohn, mais arriv\u00e9s en Allemagne, ils l&rsquo;ont transform\u00e9 en Kahn. Or, \u00ab Kahn \u00bb en allemand signifie \u00ab barque \u00bb. Cependant, par la suite, l&rsquo;une des branches de cette famille s&rsquo;est consid\u00e9rablement enrichie, et ses membres se sont indign\u00e9s : nous ne sommes pas une simple \u00ab barque \u00bb pour vous \u2014 nous sommes un grand navire, \u00ab Schiff \u00bb. Et un nouveau nom est n\u00e9. \u00bb<\/p>\n<\/p>\n<p>\u00ab \u2014 C&rsquo;est particuli\u00e8rement vrai pour les Juifs de Russie, \u2014 continue Malka. \u2014 En Russie, \u00e0 l&rsquo;\u00e9poque o\u00f9 les Juifs ont \u00e9t\u00e9 contraints de prendre des noms de famille, il arrivait fr\u00e9quemment que des parents tr\u00e8s proches adoptent des noms diff\u00e9rents. Par exemple, on exigeait de deux fr\u00e8res ayant d\u00e9j\u00e0 fond\u00e9 une famille que leurs noms diff\u00e8rent afin de ne pas les confondre. Ainsi, si l&rsquo;un des fr\u00e8res de la lign\u00e9e d&rsquo;Elioukim prenait par exemple le nom de Loukimson, l&rsquo;autre devait d\u00e9j\u00e0 prendre, disons, le nom de Loukimovitch. Des fr\u00e8res germains, deux piliers du hassidisme \u2014 le rabbi Elimelekh de Lizhensk et le rabbi Zusha d&rsquo;Anipoli \u2014 avaient \u00e9galement des noms diff\u00e9rents, mais cela n&rsquo;annule en rien le lien de parent\u00e9 entre leurs descendants. De plus, on cachait les enfants de la conscription des cantonistes en modifiant leur nom de famille. Parfois, les enfants \u00e9taient confi\u00e9s sous certaines conditions \u00e0 la famille de proches parents, par exemple \u00e0 une s\u0153ur sans enfant. C&rsquo;est pourquoi la source principale d&rsquo;information reste, bien entendu, les gens. Et plus ils sont \u00e2g\u00e9s, mieux c&rsquo;est, les femmes \u00e9tant g\u00e9n\u00e9ralement pr\u00e9f\u00e9rables aux hommes. \u00bb<\/p>\n<\/p>\n<p><em>\u00ab \u2014 Et pourquoi donc ?<\/em><\/p>\n<\/p>\n<p> \u2014 Parce que, comme le montrent les statistiques, les femmes connaissent toutes les histoires de famille bien mieux que les hommes. M\u00eame l&rsquo;histoire de la famille de leur mari, elles la connaissent souvent mieux que lui-m\u00eame, car elles communiquent davantage et de fa\u00e7on plus ouverte avec ses proches. Et quelles que soient les relations entre une belle-fille et sa belle-m\u00e8re, celle-ci finira toujours par lui raconter quelque chose. De plus, pour une raison obscure, ces r\u00e9cits se gravent bien mieux dans la m\u00e9moire des femmes que dans celle des hommes. C&rsquo;est donc sur la base de ces r\u00e9cits, ainsi qu&rsquo;\u00e0 partir de bases de donn\u00e9es en ligne totalement ouvertes, comme celle du mus\u00e9e Yad Vashem, que nous reconstituons l&rsquo;histoire de telle ou telle famille juive pour les 150 \u00e0 200 derni\u00e8res ann\u00e9es, et si nous avons de la chance, pour une p\u00e9riode encore plus longue. L&rsquo;histoire de sa migration, la g\u00e9ographie de la dispersion de ses membres, et ainsi de suite. Et ce n&rsquo;est qu&rsquo;\u00e0 la derni\u00e8re \u00e9tape de la recherche que nous nous tournons vers les archives pour pr\u00e9ciser les informations. \u00bb<\/p>\n<\/p>\n<p>\u00ab \u2014 J&rsquo;aimerais ajouter, \u2014 dit<span style=\"font-weight: bolder;\">\u00a0Nelly Rosenberg<\/span>, \u2014 que tr\u00e8s souvent, ces lacunes d&rsquo;information de la g\u00e9n\u00e9alogie juive dont nous parlons sont combl\u00e9es \u00e0 l&rsquo;aide de la litt\u00e9rature religieuse, des \u00e9crits des rabbins, et parfois du Talmud lui-m\u00eame. Pendant des si\u00e8cles, les repr\u00e9sentants de l&rsquo;\u00e9cole dite rationaliste de la g\u00e9n\u00e9alogie juive, de Hertz \u00e0 Dubnov, ont ni\u00e9 l&rsquo;importance de ces sources, les jugeant hautement incertaines et peu dignes de confiance. Mais d&rsquo;une part, il n&rsquo;est pas rare que les pr\u00e9faces et les d\u00e9dicaces de ces livres constituent une v\u00e9ritable mine d&rsquo;or pour la g\u00e9n\u00e9alogie juive \u2014 on y \u00e9num\u00e8re g\u00e9n\u00e9ralement tout le corpus des pr\u00e9noms ancestraux de cette famille. Et d&rsquo;autre part, il s&rsquo;av\u00e8re que ce qui \u00e9tait consid\u00e9r\u00e9 par les rationalistes comme un conte ou une fiction correspond en r\u00e9alit\u00e9 \u00e0 la v\u00e9rit\u00e9. Par exemple, les affirmations selon lesquelles telle ou telle famille descend du roi David ou de tel ou tel rabbin \u00e9minent mentionn\u00e9 dans le Talmud se trouvent confirm\u00e9es. Les pr\u00e9noms constituent une autre source importante pour restaurer les liens entre des familles juives portant parfois des noms diff\u00e9rents. Pour la simple raison que si les noms de famille pouvaient effectivement changer, un certain ensemble de pr\u00e9noms se transmettait de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration dans presque chaque famille juive. Nous le voyons d\u00e9j\u00e0 dans le Tanakh, \u00e0 l&rsquo;exemple des familles de cohanim et de l\u00e9vites. Par la suite, comme on le sait, il est devenu d&rsquo;usage au sein d&rsquo;une m\u00eame famille de donner les m\u00eames pr\u00e9noms. Chez les Juifs ashkenazes, ils \u00e9taient g\u00e9n\u00e9ralement attribu\u00e9s en l&rsquo;honneur de parents d\u00e9c\u00e9d\u00e9s ; chez les s\u00e9farades, en l&rsquo;honneur d&rsquo;un parent respect\u00e9 vivant ; chez les Juifs des montagnes, le premier-n\u00e9 recevait le pr\u00e9nom du p\u00e8re, ce qui devenait ensuite le nom de famille, mais le principe reste, comme on le voit, le m\u00eame. Au cours des derni\u00e8res d\u00e9cennies, chez les Juifs de l&rsquo;URSS, il est devenu courant de donner des pr\u00e9noms non juifs mais \u00e0 la sonorit\u00e9 proche, ou des pr\u00e9noms partageant la m\u00eame initiale, mais il est tout de m\u00eame possible de d\u00e9couvrir la v\u00e9rit\u00e9. \u00bb<\/p>\n<\/p>\n<p>\u00ab \u2014 Je tiens \u00e0 souligner que la mission de l&rsquo;institut ne consiste tout de m\u00eame pas \u00e0 reconstruire l&rsquo;histoire de chaque famille juive individuelle. Tous ces arbres g\u00e9n\u00e9alogiques se r\u00e9duisent en fin de compte \u00e0 certaines lign\u00e9es, et notre institut s&rsquo;occupe pr\u00e9cis\u00e9ment de l&rsquo;histoire des lign\u00e9es juives, de leur origine \u00e0 nos jours, \u2014 poursuit Malka Haguel. \u2014 Et c&rsquo;est \u00e0 travers l&rsquo;histoire des lign\u00e9es juives que l&rsquo;on peut reconstituer l&rsquo;histoire du peuple juif dans son ensemble. C&rsquo;est-\u00e0-dire que si toutes les g\u00e9n\u00e9alogies juives existantes s&rsquo;arr\u00eatent g\u00e9n\u00e9ralement \u00e0 l&rsquo;ann\u00e9e 1760, car avant cela les Juifs n&rsquo;avaient tout simplement pas de noms de famille, notre travail, lui, ne fait que commencer ici. \u00bb<\/p>\n<\/p>\n<p><em>\u00ab \u2014 Mais toute la question est de savoir combien il y en avait, de ces lign\u00e9es. On ne peut pas embrasser l&rsquo;infini<\/em>.<\/p>\n<\/p>\n<p> \u00bb\u00ab \u2014 C&rsquo;est bien l\u00e0 le fait : le nombre de lign\u00e9es juives est fini. Plus encore, il est relativement restreint. Nous ne pouvons pas encore donner de chiffre exact, mais il est d\u00e9j\u00e0 clair qu&rsquo;il n&rsquo;existe que quelques dizaines de grandes lign\u00e9es qui se sont ensuite ramifi\u00e9es et re-ramifi\u00e9es au cours de l&rsquo;histoire. \u00bb<\/p>\n<\/p>\n<p><em>\u00ab \u2014 Et pourtant, quel serait au moins un chiffre approximatif ?<\/em><\/p>\n<\/p>\n<p> \u2014 Diff\u00e9rents chercheurs parviennent \u00e0 des conclusions diverses. Par exemple, Bar-Ilan estime qu&rsquo;il existe environ 20 lign\u00e9es de Juifs ashkenazes. Autrement dit, toutes les personnes assises actuellement dans cette pi\u00e8ce appartiennent \u00e0 l&rsquo;une de ces lign\u00e9es et sont, selon toute vraisemblance, de lointains parents. \u00bb<\/p>\n<\/p>\n<p><em>\u00ab \u2014 Bon, pour les ashkenazes, c&rsquo;est plus ou moins clair. Ils ont \u00e9t\u00e9 frapp\u00e9s et pers\u00e9cut\u00e9s tout au long de l&rsquo;histoire. Mais qu&rsquo;en est-il des Juifs s\u00e9farades ?<\/em><\/p>\n<\/p>\n<p> \u2014 L\u00e0 aussi, en r\u00e9alit\u00e9, les lign\u00e9es sont tr\u00e8s peu nombreuses, et elles croisent souvent les lign\u00e9es ashkenazes. Il faut prendre en compte qu&rsquo;avant le 19e si\u00e8cle, 70 % des Juifs du monde entier \u00e9taient pr\u00e9cis\u00e9ment des Juifs ashkenazes. Ainsi, les lign\u00e9es sont effectivement peu nombreuses. Les noms de famille, bien s\u00fbr, sont beaucoup plus nombreux, car les lign\u00e9es se ramifiaient et les noms se modifiaient. Mais leur nombre est, l\u00e0 encore, fini. Je ne me risquerai pas \u00e0 donner un chiffre exact, mais il s&rsquo;agit d&rsquo;environ 20 000 noms de famille, pas plus. Sans compter, \u00e9videmment, leurs modifications phon\u00e9tiques. \u00bb<\/p>\n<\/p>\n<p>\u00ab \u2014 Un exemple classique est l&rsquo;histoire de la lign\u00e9e de Porto, \u2014 explique Daniel Kluger. \u2014 De Porto, alias Benveniste. Au cours de la ramification, certains sont revenus au nom d&rsquo;origine de la lign\u00e9e, Halevi, d&rsquo;autres sont rest\u00e9s Benveniste, tandis que d&rsquo;autres ont donn\u00e9 naissance au c\u00e9l\u00e8bre nom de famille du baron Ginzburg. Et lorsqu&rsquo;un des descendants d&rsquo;Halevi de G\u00e9rone a atteint la ville de Horitz (aujourd&rsquo;hui Hor\u0161ovsk\u00fd T\u00fdn \/ Horovice), il a donn\u00e9 naissance au nom de famille Gourevitch. C&rsquo;est pourquoi il est tr\u00e8s important de s&rsquo;appuyer sur la tradition familiale des pr\u00e9noms. Les pr\u00e9noms, comme cela a d\u00e9j\u00e0 \u00e9t\u00e9 dit, sont attribu\u00e9s en l&rsquo;honneur de parents respect\u00e9s. \u00bb<\/p>\n<\/p>\n<p>\u00ab \u2014 C&rsquo;est certain, les Juifs ne donnaient g\u00e9n\u00e9ralement pas \u00e0 leurs enfants le pr\u00e9nom du voisin ! \u2014 fait remarquer Malka Haguel. \u2014 Oui, \u043d\u043e aujourd&rsquo;hui, dans l&rsquo;Isra\u00ebl moderne, cette tradition se perd peu \u00e0 peu. Nos enfants pr\u00e9f\u00e8rent donner \u00e0 leurs enfants des pr\u00e9noms h\u00e9breux ou purement isra\u00e9liens, populaires en ce moment, souvent invent\u00e9s tout r\u00e9cemment. \u00bb<\/p>\n<\/p>\n<p>\u00ab \u2014 Je ne pense pas que cette tradition se perde, \u2014 r\u00e9pond Kluger. \u2014 Nos observations t\u00e9moignent du contraire. M\u00eame s&rsquo;il y a un certain recul pour c\u00e9der \u00e0 la mode, elle finira de toute fa\u00e7on par revenir. Il faut plut\u00f4t parler de sa modification. Un processus similaire s&rsquo;est d\u00e9j\u00e0 produit autrefois, lorsque les pr\u00e9noms juifs traditionnels \u00e9taient calqu\u00e9s sur la langue des peuples au milieu desquels les Juifs vivaient, puis se superposaient \u00e0 nouveau aux pr\u00e9noms juifs. C&rsquo;est ainsi que sont apparus tous ces Tzvi-Hirsch, Ari\u00e9-Leib, etc. \u00bb<\/p>\n<\/p>\n<p><em>\u00ab \u2014 Existe-t-il l&rsquo;histoire d&rsquo;au moins une lign\u00e9e juive que vous auriez reconstitu\u00e9e, pour ainsi dire, jusqu&rsquo;au bout ?<\/em><\/p>\n<\/p>\n<p> \u2014 Oui. C&rsquo;est l&rsquo;histoire de la lign\u00e9e des Friedman, que nous avons retrac\u00e9e jusqu&rsquo;aux gaonim de Babylone. Nous avons \u00e9galement reconstitu\u00e9 l&rsquo;histoire des lign\u00e9es Rothschild, Posner (alias Pevzner). Ces derniers, par exemple, se sont r\u00e9v\u00e9l\u00e9s avoir des racines s\u00e9farades. \u00bb<\/p>\n<\/p>\n<p>\u00ab \u2014 Je voudrais faire la remarque suivante, \u2014 intervient enfin le fondateur et directeur scientifique de l&rsquo;institut, Alexander Vidgop. \u2014 En retra\u00e7ant l&rsquo;histoire des lign\u00e9es, on voit involontairement se confirmer l&rsquo;id\u00e9e du Tanakh selon laquelle chaque lign\u00e9e juive a sa propre mission, ses propres m\u00e9tiers ancestraux qui se transmettent de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration. Et, en r\u00e8gle g\u00e9n\u00e9rale, les repr\u00e9sentants de ces lign\u00e9es atteignent des sommets consid\u00e9rables dans ces domaines. Prenons par exemple un nom de famille bien connu comme Tsirioulnik (Barbier). Son fondateur l&rsquo;a re\u00e7u parce qu&rsquo;il \u00e9tait m\u00e9decin, et depuis lors, de nombreux Tsirioulnik sont m\u00e9decins de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration. Ainsi, si vous vous retrouvez sur une table d&rsquo;op\u00e9ration et que vous \u00eates op\u00e9r\u00e9 par un chirurgien portant ce nom, vous pouvez \u00eatre presque certain d&rsquo;\u00eatre entre de bonnes mains. \u00bb<\/p>\n<\/p>\n<p><em>\u00ab \u2014 Et comment expliquez-vous l&rsquo;apparition chez les Juifs d&rsquo;une telle profusion de noms de famille purement russes ? Par exemple, d&rsquo;o\u00f9 viennent les Juifs nomm\u00e9s Ivanov ?<\/em><\/p>\n<\/p>\n<p> \u2014 Eh bien, Ivanov, c&rsquo;est tr\u00e8s simple, \u2014 sourit Kluger. \u2014 Ce nom est une d\u00e9formation du nom Evnov. Et Evnov vient du pr\u00e9nom Evno, celui-l\u00e0 m\u00eame que portait le fameux Azef. En revanche, avec le nom de famille juif Voronov (des Corbeaux), l&rsquo;histoire est plus int\u00e9ressante. Dans le Tanakh, les l\u00e9vites sont compar\u00e9s aux corbeaux \u2014 on dit qu&rsquo;ils s&rsquo;assemblent autour de la Torah et sont avides de son \u00e9tude, comme des corbeaux. D&rsquo;ailleurs, la c\u00e9l\u00e8bre l\u00e9gende selon laquelle le proph\u00e8te \u00c9lie, alors qu&rsquo;il se cachait dans une grotte, \u00e9tait nourri par des corbeaux, est tr\u00e8s probablement inspir\u00e9e du fait qu&rsquo;il \u00e9tait ravitaill\u00e9 par des l\u00e9vites. \u00c9lie lui-m\u00eame, comme on le sait, appartenait \u00e0 la lign\u00e9e des cohanim, donc remontait lui aussi aux l\u00e9vites. Un autre exemple int\u00e9ressant d&rsquo;origine de nom est Gelfand. C&rsquo;est-\u00e0-dire \u00ab \u00e9l\u00e9phant \u00bb. Ce nom a \u00e9t\u00e9 port\u00e9 aussi bien par de nombreux savants \u00e9minents que par la narodovoltsy Guessia Gelfand. Et le nom prend sa source \u00e0 Francfort, o\u00f9 l&rsquo;une des maisons portait, en guise de num\u00e9ro, l&rsquo;image d&rsquo;un \u00e9l\u00e9phant portant un fardeau. Et cela signifiait, selon la symbolique des cabalistes, que le ma\u00eetre de maison \u00e9tait un homme tr\u00e8s craignant D-ieu, qui portait le fardeau des commandements de la Torah comme cet \u00e9l\u00e9phant m\u00eame. \u00bb<\/p>\n<\/p>\n<p><em>\u00ab \u2014 Au fait, n&rsquo;avez-vous pas essay\u00e9 de corr\u00e9ler la g\u00e9n\u00e9alogie juive avec l&rsquo;anthropologie juive ? Je veux dire, est-il possible de d\u00e9terminer, \u00e0 l&rsquo;apparence d&rsquo;un Juif, \u00e0 quelle famille ou lign\u00e9e il appartient ?<\/em><\/p>\n<\/p>\n<p> \u2014 Nous ne nous en occupons pas, car c&rsquo;est un travail \u00e0 part, mais je vais vous raconter une histoire. Dans le cadre de nos projets, nous aidons les jeunes qui viennent via les projets \u00ab Taglit \u00bb \u00e0 toucher leurs racines, \u00e0 d\u00e9couvrir l&rsquo;histoire de leur famille. Ils s&rsquo;y consacrent ici de mani\u00e8re autonome, puis chacun re\u00e7oit un dossier contenant la partie de sa g\u00e9n\u00e9alogie qu&rsquo;il a r\u00e9ussi \u00e0 d\u00e9terrer, mais nous effectuons naturellement un travail pr\u00e9liminaire. Nous recevons les noms et les photos des participants, et tr\u00e8s souvent, des jeunes de pays diff\u00e9rents se r\u00e9v\u00e8lent \u00eatre des parents \u00e9loign\u00e9s, et parfois pas si \u00e9loign\u00e9s que cela. Pour beaucoup, c&rsquo;est un v\u00e9ritable choc. Un jour, nous voyons que Taglit, dans le cadre d&rsquo;un voyage, doit r\u00e9unir deux jeunes filles qui sont cousines au septi\u00e8me ou huiti\u00e8me degr\u00e9. L&rsquo;une d&rsquo;elles vit aux \u00c9tats-Unis, dans une famille ais\u00e9e. L&rsquo;autre vient de la province russe, d&rsquo;une famille de la classe moyenne. Toutes deux ont envoy\u00e9 leurs photos de leur bal de fin d&rsquo;ann\u00e9e. Lorsqu&rsquo;on les a pos\u00e9es c\u00f4te \u00e0 c\u00f4te, nous avons cru qu&rsquo;il s&rsquo;agissait de s\u0153urs germaines, pour ne pas dire de jumelles. Mais ce n&rsquo;est pas tout : toutes deux avaient choisi pour la soir\u00e9e la m\u00eame coiffure, des robes du m\u00eame mod\u00e8le et de la m\u00eame couleur ou presque, et jusqu&rsquo;au m\u00eame ton de rouge \u00e0 l\u00e8vres. C&rsquo;est-\u00e0-dire qu&rsquo;elles se ressemblaient non seulement physiquement, \u043d\u043e leurs go\u00fbts co\u00efncidaient \u00e9galement. \u00bb<\/p>\n<\/p>\n<p><em>\u00ab \u2014 Ainsi, Boulgakov avait raison : \u00ab le sang est une grande chose \u00bb ?<\/em><\/p>\n<\/p>\n<p> \u2014 Il semble bien que oui, \u2014 acquiesce Malka. \u00bb<\/p>\n<\/p>\n<p><em>\u00ab \u2014 Au fait, parlons un peu plus en d\u00e9tail de vos projets.<\/em><\/p>\n<\/p>\n<p> \u2014 Pour le travail avec les jeunes, nous avons trois projets principaux.\u00a0<span style=\"font-weight: bolder;\">\u00ab G\u00e9n\u00e9rations \u00bb<\/span>, dans le cadre duquel, comme cela a d\u00e9j\u00e0 \u00e9t\u00e9 dit, nous aidons les jeunes qui viennent via des programmes de jeunesse \u00e0 tenter de reconstituer l&rsquo;histoire de leur nom et de leur famille. Au cours d&rsquo;un autre projet \u2014\u00a0<span style=\"font-weight: bolder;\">\u00ab Rod&rsquo;N&rsquo;ia \u00bb<\/span>\u00a0\u2014 nous aidons \u00e0 reconstituer la g\u00e9n\u00e9alogie de Juifs vivant dans divers pays, en communiquant avec eux par Internet et en les associant simultan\u00e9ment au travail de recherche. Dans le cadre de ce projet, nous avons r\u00e9cemment rassembl\u00e9 tout un groupe de jeunes nomm\u00e9s Shapiro dans la ville allemande de Spire \u2014 car tous les Shapiro tirent leur origine d&rsquo;un anc\u00eatre commun ayant v\u00e9cu dans cette ville. C&rsquo;est ainsi que na\u00eet un sentiment tout \u00e0 fait singulier de lien entre les g\u00e9n\u00e9rations. Le troisi\u00e8me projet,\u00a0<span style=\"font-weight: bolder;\">\u00ab Sefer HaDorot \u00bb<\/span>\u00a0(\u00ab Le Livre des G\u00e9n\u00e9rations \u00bb), permet \u00e0 de jeunes Juifs vivant dans diff\u00e9rents pays de se lancer dans une recherche autonome sur l&rsquo;histoire de leur famille, pour obtenir en fin de compte ce fameux \u00ab Livre des G\u00e9n\u00e9rations \u00bb \u2014 avec des informations sur les origines de la famille, les parents, les migrations des anc\u00eatres, etc. \u00bb<\/p>\n<\/p>\n<p>\u00c9videmment, la conversation \u00e0 l&rsquo;institut\u00a0<span style=\"font-weight: bolder;\">\u00ab Am haZikaron \u00bb<\/span>\u00a0a \u00e9t\u00e9 longue, et la retranscrire en entier n&rsquo;aurait pas de sens. La g\u00e9n\u00e9alogie juive est un sujet par principe infini. Mais pour finir, je ne peux m&#8217;emp\u00eacher de me rappeler ma r\u00e9cente discussion avec un diplomate lituanien.\u00a0<em>\u00ab Voil\u00e0, \u2014 a-t-il dit en me tendant un magnifique album en cadeau. \u2014 Nous l&rsquo;avons publi\u00e9 pour le mill\u00e9naire de la Lituanie. Quand nous le pr\u00e9parions, nous \u00e9tions si fiers de l&rsquo;anciennet\u00e9 de notre peuple. Et ce n&rsquo;est qu&rsquo;en me retrouvant en Isra\u00ebl et en commen\u00e7ant \u00e0 lire des livres sur l&rsquo;histoire juive que j&rsquo;ai compris \u00e0 quel point nous nous trompions. Compar\u00e9s \u00e0 vous, les Juifs, nous, ainsi que les autres peuples europ\u00e9ens, ne sommes que des enfants qui s&rsquo;amusent encore dans un bac \u00e0 sable. \u00bb<\/em><\/p>\n<\/p>\n<p>Piotr Loukimson<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Entretien avec les auteurs d&rsquo;une m\u00e9thodologie r\u00e9volutionnaire d&rsquo;\u00e9tude des racines familiales juives<\/p>\n","protected":false},"author":2,"featured_media":4830,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[37],"tags":[],"class_list":["post-4854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorise"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rappelle-toi ton nom - Am haZikaron<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amhazikaron.org\/fr\/souvenez-vous-de-votre-nom\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rappelle-toi ton nom - Am haZikaron\" \/>\n<meta property=\"og:description\" content=\"Entretien avec les auteurs d&#039;une m\u00e9thodologie r\u00e9volutionnaire d&#039;\u00e9tude des racines familiales juives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amhazikaron.org\/fr\/souvenez-vous-de-votre-nom\/\" \/>\n<meta property=\"og:site_name\" content=\"Am haZikaron\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jewage\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-01T12:36:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-29T18:47:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/Jewish_ru_logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Annylan.al@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AmhaZikaron\" \/>\n<meta name=\"twitter:site\" content=\"@AmhaZikaron\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Annylan.al@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/souvenez-vous-de-votre-nom\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/souvenez-vous-de-votre-nom\\\/\"},\"author\":{\"name\":\"Annylan.al@gmail.com\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#\\\/schema\\\/person\\\/40e00d1b9f3b5c29118651ad59305791\"},\"headline\":\"Rappelle-toi ton nom\",\"datePublished\":\"2016-03-01T12:36:00+00:00\",\"dateModified\":\"2026-06-29T18:47:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/souvenez-vous-de-votre-nom\\\/\"},\"wordCount\":3512,\"publisher\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/souvenez-vous-de-votre-nom\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Jewish_ru_logo.png\",\"articleSection\":[\"Non cat\u00e9goris\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/souvenez-vous-de-votre-nom\\\/\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/souvenez-vous-de-votre-nom\\\/\",\"name\":\"Rappelle-toi ton nom - Am haZikaron\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/souvenez-vous-de-votre-nom\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/souvenez-vous-de-votre-nom\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Jewish_ru_logo.png\",\"datePublished\":\"2016-03-01T12:36:00+00:00\",\"dateModified\":\"2026-06-29T18:47:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/souvenez-vous-de-votre-nom\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/souvenez-vous-de-votre-nom\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/souvenez-vous-de-votre-nom\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Jewish_ru_logo.png\",\"contentUrl\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Jewish_ru_logo.png\",\"width\":500,\"height\":250,\"caption\":\"Jewish.ru\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/souvenez-vous-de-votre-nom\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rappelle-toi ton nom\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/\",\"name\":\"Am haZikaron\",\"description\":\"\u0418\u043d\u0441\u0442\u0438\u0442\u0443\u0442 \u043d\u0430\u0443\u043a\u0438, \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u044b \u0438 \u043d\u0430\u0441\u043b\u0435\u0434\u0438\u044f \u0435\u0432\u0440\u0435\u0439\u0441\u043a\u043e\u0433\u043e \u043d\u0430\u0440\u043e\u0434\u0430\",\"publisher\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#organization\",\"name\":\"Am haZikaron\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo.svg\",\"width\":48,\"height\":48,\"caption\":\"Am haZikaron\"},\"image\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jewage\",\"https:\\\/\\\/x.com\\\/AmhaZikaron\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#\\\/schema\\\/person\\\/40e00d1b9f3b5c29118651ad59305791\",\"name\":\"Annylan.al@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ef95949560f8695eed9a2da8924ecf522501807809879ea6faf949ac057ee712?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ef95949560f8695eed9a2da8924ecf522501807809879ea6faf949ac057ee712?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ef95949560f8695eed9a2da8924ecf522501807809879ea6faf949ac057ee712?s=96&d=mm&r=g\",\"caption\":\"Annylan.al@gmail.com\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rappelle-toi ton nom - Am haZikaron","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amhazikaron.org\/fr\/souvenez-vous-de-votre-nom\/","og_locale":"fr_FR","og_type":"article","og_title":"Rappelle-toi ton nom - Am haZikaron","og_description":"Entretien avec les auteurs d'une m\u00e9thodologie r\u00e9volutionnaire d'\u00e9tude des racines familiales juives","og_url":"https:\/\/amhazikaron.org\/fr\/souvenez-vous-de-votre-nom\/","og_site_name":"Am haZikaron","article_publisher":"https:\/\/www.facebook.com\/jewage","article_published_time":"2016-03-01T12:36:00+00:00","article_modified_time":"2026-06-29T18:47:03+00:00","og_image":[{"width":500,"height":250,"url":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/Jewish_ru_logo.png","type":"image\/png"}],"author":"Annylan.al@gmail.com","twitter_card":"summary_large_image","twitter_creator":"@AmhaZikaron","twitter_site":"@AmhaZikaron","twitter_misc":{"\u00c9crit par":"Annylan.al@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amhazikaron.org\/fr\/souvenez-vous-de-votre-nom\/#article","isPartOf":{"@id":"https:\/\/amhazikaron.org\/fr\/souvenez-vous-de-votre-nom\/"},"author":{"name":"Annylan.al@gmail.com","@id":"https:\/\/amhazikaron.org\/fr\/#\/schema\/person\/40e00d1b9f3b5c29118651ad59305791"},"headline":"Rappelle-toi ton nom","datePublished":"2016-03-01T12:36:00+00:00","dateModified":"2026-06-29T18:47:03+00:00","mainEntityOfPage":{"@id":"https:\/\/amhazikaron.org\/fr\/souvenez-vous-de-votre-nom\/"},"wordCount":3512,"publisher":{"@id":"https:\/\/amhazikaron.org\/fr\/#organization"},"image":{"@id":"https:\/\/amhazikaron.org\/fr\/souvenez-vous-de-votre-nom\/#primaryimage"},"thumbnailUrl":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/Jewish_ru_logo.png","articleSection":["Non cat\u00e9goris\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/amhazikaron.org\/fr\/souvenez-vous-de-votre-nom\/","url":"https:\/\/amhazikaron.org\/fr\/souvenez-vous-de-votre-nom\/","name":"Rappelle-toi ton nom - Am haZikaron","isPartOf":{"@id":"https:\/\/amhazikaron.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amhazikaron.org\/fr\/souvenez-vous-de-votre-nom\/#primaryimage"},"image":{"@id":"https:\/\/amhazikaron.org\/fr\/souvenez-vous-de-votre-nom\/#primaryimage"},"thumbnailUrl":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/Jewish_ru_logo.png","datePublished":"2016-03-01T12:36:00+00:00","dateModified":"2026-06-29T18:47:03+00:00","breadcrumb":{"@id":"https:\/\/amhazikaron.org\/fr\/souvenez-vous-de-votre-nom\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amhazikaron.org\/fr\/souvenez-vous-de-votre-nom\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/amhazikaron.org\/fr\/souvenez-vous-de-votre-nom\/#primaryimage","url":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/Jewish_ru_logo.png","contentUrl":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/Jewish_ru_logo.png","width":500,"height":250,"caption":"Jewish.ru"},{"@type":"BreadcrumbList","@id":"https:\/\/amhazikaron.org\/fr\/souvenez-vous-de-votre-nom\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/amhazikaron.org\/fr\/principal\/"},{"@type":"ListItem","position":2,"name":"Rappelle-toi ton nom"}]},{"@type":"WebSite","@id":"https:\/\/amhazikaron.org\/fr\/#website","url":"https:\/\/amhazikaron.org\/fr\/","name":"Am haZikaron","description":"\u0418\u043d\u0441\u0442\u0438\u0442\u0443\u0442 \u043d\u0430\u0443\u043a\u0438, \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u044b \u0438 \u043d\u0430\u0441\u043b\u0435\u0434\u0438\u044f \u0435\u0432\u0440\u0435\u0439\u0441\u043a\u043e\u0433\u043e \u043d\u0430\u0440\u043e\u0434\u0430","publisher":{"@id":"https:\/\/amhazikaron.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amhazikaron.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/amhazikaron.org\/fr\/#organization","name":"Am haZikaron","url":"https:\/\/amhazikaron.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/amhazikaron.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/logo.svg","contentUrl":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/logo.svg","width":48,"height":48,"caption":"Am haZikaron"},"image":{"@id":"https:\/\/amhazikaron.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jewage","https:\/\/x.com\/AmhaZikaron"]},{"@type":"Person","@id":"https:\/\/amhazikaron.org\/fr\/#\/schema\/person\/40e00d1b9f3b5c29118651ad59305791","name":"Annylan.al@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ef95949560f8695eed9a2da8924ecf522501807809879ea6faf949ac057ee712?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ef95949560f8695eed9a2da8924ecf522501807809879ea6faf949ac057ee712?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ef95949560f8695eed9a2da8924ecf522501807809879ea6faf949ac057ee712?s=96&d=mm&r=g","caption":"Annylan.al@gmail.com"}}]}},"_links":{"self":[{"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/posts\/4854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/comments?post=4854"}],"version-history":[{"count":3,"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/posts\/4854\/revisions"}],"predecessor-version":[{"id":10678,"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/posts\/4854\/revisions\/10678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/media\/4830"}],"wp:attachment":[{"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/media?parent=4854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/categories?post=4854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/tags?post=4854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}