{"id":4986,"date":"2025-04-13T15:13:20","date_gmt":"2025-04-13T15:13:20","guid":{"rendered":"https:\/\/amhazikaron.org\/histoire-de-linstitut\/"},"modified":"2026-07-27T19:51:16","modified_gmt":"2026-07-27T19:51:16","slug":"histoire-de-linstitut","status":"publish","type":"page","link":"https:\/\/amhazikaron.org\/fr\/a-propos-de-nous\/histoire-de-linstitut\/","title":{"rendered":"Histoire de l&rsquo;Institut"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4986\" class=\"elementor elementor-4986 elementor-78\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c7f4de e-flex e-con-boxed e-con e-parent\" data-id=\"8c7f4de\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ac2e27d e-con-full e-flex e-con e-child\" data-id=\"ac2e27d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a45a4a8 elementor-widget elementor-widget-image\" data-id=\"a45a4a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/history-001.jpg\" class=\"attachment-large size-large wp-image-4988\" alt=\"history illustration\" srcset=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/history-001.jpg 500w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/history-001-300x300.jpg 300w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/history-001-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f517bdb e-con-full e-flex e-con e-child\" data-id=\"f517bdb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34276fe elementor-widget elementor-widget-text-editor\" data-id=\"34276fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Comment tout a commenc\u00e9<\/b><\/p><p><span style=\"font-weight: 400;\">Cette histoire a commenc\u00e9 il y a pr\u00e8s de trente ans, lorsque le fondateur de l&rsquo;Institut \u00abAm haZikaron\u00bb, Alexandre Jonathan Vidgop, entreprit de reconstituer sa propre g\u00e9n\u00e9alogie.<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Parti d&rsquo;une liste ne comptant que 35 parents connus de lui, il parvint avec le temps \u00e0 r\u00e9tablir le lien avec plus de 1 500 autres membres de sa famille.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Au cours de ce travail, il d\u00e9couvrit un ph\u00e9nom\u00e8ne frappant : des parents qui, depuis plus de cent ans, ne soup\u00e7onnaient m\u00eame pas l&rsquo;existence les uns des autres, vivant dans des pays diff\u00e9rents et sur des continents diff\u00e9rents, suivaient souvent un parcours de vie \u00e9tonnamment semblable. Ils choisissaient les m\u00eames professions, manifestaient les m\u00eames inclinations et obtenaient fr\u00e9quemment des r\u00e9sultats presque identiques.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Ce qui, \u00e0 premi\u00e8re vue, aurait pu passer pour une co\u00efncidence invraisemblable donna l&rsquo;impulsion \u00e0 la cr\u00e9ation d&rsquo;un institut \u00e0 but non lucratif. Sa t\u00e2che principale devint l&rsquo;\u00e9tude syst\u00e9matique de la question de savoir si de telles r\u00e9gularit\u00e9s se rencontrent \u00e9galement dans d&rsquo;autres lign\u00e9es juives.<\/span><\/li><\/ul><p>\u00a0<\/p><p><b>La fondation de l&rsquo;Institut \u00abAm haZikaron\u00bb (1998)<\/b><\/p><p><span style=\"font-weight: 400;\">L&rsquo;Institut \u00abAm haZikaron\u00bb a \u00e9t\u00e9 officiellement fond\u00e9 en 1998 pour l&rsquo;\u00e9tude scientifique des liens entre les g\u00e9n\u00e9rations au sein du peuple juif. En dix ans d&rsquo;un travail minutieux, s&rsquo;appuyant sur une approche rigoureusement empirique, les chercheurs ont obtenu des r\u00e9sultats impressionnants :<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">ils ont reconstitu\u00e9 des arbres g\u00e9n\u00e9alogiques de familles juives dont les racines remontent jusqu&rsquo;\u00e0 900 ans ;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">ils ont mis en \u00e9vidence des r\u00e9gularit\u00e9s h\u00e9r\u00e9ditaires uniques gr\u00e2ce \u00e0 l&rsquo;analyse syst\u00e9matique d&rsquo;immenses ensembles de donn\u00e9es ;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">ils ont publi\u00e9 les r\u00e9sultats de leurs recherches dans des revues scientifiques reconnues ;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">ils ont re\u00e7u la m\u00e9daille \u00abZeiti Yerushalaim\u00bb (\u00abOlive de J\u00e9rusalem\u00bb) pour leur contribution exceptionnelle \u00e0 la pr\u00e9servation du patrimoine juif ;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">ils ont obtenu le soutien d&rsquo;un comit\u00e9 public de premier plan, compos\u00e9 de 55 laur\u00e9ats du prix Nobel.<\/span><\/li><\/ul><p>\u00a0<\/p><p><b>La d\u00e9couverte centrale : la \u00abmission\u00bb de la famille<\/b><\/p><p><span style=\"font-weight: 400;\">Les recherches de l&rsquo;Institut \u00abAm haZikaron\u00bb ont montr\u00e9 que les repr\u00e9sentants d&rsquo;une m\u00eame lign\u00e9e juive sont capables de conserver, au fil de nombreux si\u00e8cles, des particularit\u00e9s propres pr\u00e9cis\u00e9ment \u00e0 leur ligne familiale. Ces conclusions font \u00e9cho \u00e0 l&rsquo;id\u00e9e biblique selon laquelle chaque lign\u00e9e poss\u00e8de sa propre vocation \u2014 une mission particuli\u00e8re, transmise de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration et incarn\u00e9e dans l&rsquo;histoire de la famille. De si\u00e8cle en si\u00e8cle, les repr\u00e9sentants d&rsquo;une m\u00eame lign\u00e9e pr\u00e9sentent des r\u00e9gularit\u00e9s communes :<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Les domaines professionnels.<\/b><span style=\"font-weight: 400;\"> En r\u00e8gle g\u00e9n\u00e9rale, les descendants concentrent leurs efforts dans quatre ou cinq sph\u00e8res d&rsquo;activit\u00e9 d\u00e9termin\u00e9es et y atteignent souvent des sommets remarquables.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Le mode de vie.<\/b><span style=\"font-weight: 400;\"> On observe dans les familles des mod\u00e8les de comportement stables : certaines lign\u00e9es sont port\u00e9es aux migrations fr\u00e9quentes, tandis que d&rsquo;autres prennent racine au m\u00eame endroit pendant des si\u00e8cles ; dans certaines familles les divorces fr\u00e9quents deviennent la norme, dans d&rsquo;autres pr\u00e9dominent des unions d&rsquo;une exceptionnelle long\u00e9vit\u00e9.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>La nature du g\u00e9nie.<\/b><span style=\"font-weight: 400;\"> En d\u00e9veloppant la th\u00e9orie de la mission familiale, les chercheurs ont analys\u00e9 les g\u00e9n\u00e9alogies de personnes \u00e9minentes. Ils ont d\u00e9couvert des familles juives dans lesquelles, une fois toutes les quelques g\u00e9n\u00e9rations, apparaissent r\u00e9guli\u00e8rement des g\u00e9nies dans des domaines bien pr\u00e9cis (math\u00e9matiques, physique, commerce), exer\u00e7ant une influence colossale sur le cours de l&rsquo;histoire mondiale.<\/span><\/li><\/ul><p>\u00a0<\/p><p><b>Ce que cela signifie pour la jeunesse juive de la diaspora<\/b><\/p><p><span style=\"font-weight: 400;\">Ayant \u00e9largi ses recherches au domaine de la g\u00e9n\u00e9tique d\u00e9mographique et \u00e0 la reconstruction historique des communaut\u00e9s, l&rsquo;institut a cr\u00e9\u00e9 un outil \u00e9ducatif unique pour les jeunes Juifs qui ont perdu le lien avec leurs racines. Lors des s\u00e9minaires d&rsquo;\u00abAm haZikaron\u00bb, de nombreux participants \u00e9prouvent un v\u00e9ritable choc \u00e9motionnel lorsqu&rsquo;ils :<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">apprennent qui furent les fondateurs de leur lign\u00e9e et quelles sont les origines de leur famille ;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">d\u00e9couvrent les personnalit\u00e9s \u00e9minentes qui appartenaient \u00e0 leur propre ligne familiale ;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">sentent qu&rsquo;avec la restauration de la m\u00e9moire leur revient une part d&rsquo;eux-m\u00eames, et comprennent que le v\u00e9ritable chemin vers soi commence par l&rsquo;histoire de sa propre famille.<\/span><\/li><\/ul><p>\u00a0<\/p><p><b>Le concept cl\u00e9 : qu&rsquo;est-ce que le <\/b><b><i>yikhes<\/i><\/b><b> ?<\/b><\/p><p><span style=\"font-weight: 400;\">La mission principale de l&rsquo;Institut \u00abAm haZikaron\u00bb est de restaurer la m\u00e9moire familiale. Aucun mot n&rsquo;exprime cette id\u00e9e avec plus de justesse que le beau terme yiddish <\/span><i><span style=\"font-weight: 400;\">yikhes<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Il provient du mot h\u00e9breu <\/span><i><span style=\"font-weight: 400;\">yikhous<\/span><\/i><span style=\"font-weight: 400;\">, qui signifie \u00ablien de parent\u00e9\u00bb ou \u00aborigine\u00bb (tandis que le terme <\/span><i><span style=\"font-weight: 400;\">yohasin<\/span><\/i><span style=\"font-weight: 400;\"> d\u00e9signe la g\u00e9n\u00e9alogie en tant que telle).<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Le <\/span><i><span style=\"font-weight: 400;\">yikhes<\/span><\/i><span style=\"font-weight: 400;\"> est bien plus qu&rsquo;un aride arbre g\u00e9n\u00e9alogique fait de noms et de dates : c&rsquo;est l&rsquo;histoire vivante d&rsquo;une famille \u2014 ses origines, le lien entre ses g\u00e9n\u00e9rations, sa m\u00e9moire inalt\u00e9rable, ses traditions et son h\u00e9ritage.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Et c&rsquo;est pr\u00e9cis\u00e9ment le <\/span><i><span style=\"font-weight: 400;\">yikhes<\/span><\/i><span style=\"font-weight: 400;\"> qui, dans une mesure bien plus grande qu&rsquo;on ne le suppose habituellement, a d\u00e9termin\u00e9 les destins individuels et fa\u00e7onn\u00e9 le chemin historique de tout le peuple juif.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cette histoire a commenc\u00e9 il y a pr\u00e8s de 30 ans&#8230;<\/p>\n","protected":false},"author":1,"featured_media":4987,"parent":5406,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-4986","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire de l&#039;Institut - Am haZikaron<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amhazikaron.org\/fr\/a-propos-de-nous\/histoire-de-linstitut\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire de l&#039;Institut - Am haZikaron\" \/>\n<meta property=\"og:description\" content=\"Cette histoire a commenc\u00e9 il y a pr\u00e8s de 30 ans...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amhazikaron.org\/fr\/a-propos-de-nous\/histoire-de-linstitut\/\" \/>\n<meta property=\"og:site_name\" content=\"Am haZikaron\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jewage\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-27T19:51:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/history-1-clr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AmhaZikaron\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/a-propos-de-nous\\\/histoire-de-linstitut\\\/\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/a-propos-de-nous\\\/histoire-de-linstitut\\\/\",\"name\":\"Histoire de l'Institut - Am haZikaron\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/a-propos-de-nous\\\/histoire-de-linstitut\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/a-propos-de-nous\\\/histoire-de-linstitut\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/history-1-clr.jpg\",\"datePublished\":\"2025-04-13T15:13:20+00:00\",\"dateModified\":\"2026-07-27T19:51:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/a-propos-de-nous\\\/histoire-de-linstitut\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/a-propos-de-nous\\\/histoire-de-linstitut\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/a-propos-de-nous\\\/histoire-de-linstitut\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/history-1-clr.jpg\",\"contentUrl\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/history-1-clr.jpg\",\"width\":500,\"height\":333,\"caption\":\"close up of world famous Pisa clock in Piazza dei Cavalieri, Italy\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/a-propos-de-nous\\\/histoire-de-linstitut\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c0 propos de nous\",\"item\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/about\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Histoire de l&#8217;Institut\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/\",\"name\":\"Am haZikaron\",\"description\":\"\u0418\u043d\u0441\u0442\u0438\u0442\u0443\u0442 \u043d\u0430\u0443\u043a\u0438, \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u044b \u0438 \u043d\u0430\u0441\u043b\u0435\u0434\u0438\u044f \u0435\u0432\u0440\u0435\u0439\u0441\u043a\u043e\u0433\u043e \u043d\u0430\u0440\u043e\u0434\u0430\",\"publisher\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#organization\",\"name\":\"Am haZikaron\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo.svg\",\"width\":48,\"height\":48,\"caption\":\"Am haZikaron\"},\"image\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jewage\",\"https:\\\/\\\/x.com\\\/AmhaZikaron\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire de l'Institut - Am haZikaron","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amhazikaron.org\/fr\/a-propos-de-nous\/histoire-de-linstitut\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire de l'Institut - Am haZikaron","og_description":"Cette histoire a commenc\u00e9 il y a pr\u00e8s de 30 ans...","og_url":"https:\/\/amhazikaron.org\/fr\/a-propos-de-nous\/histoire-de-linstitut\/","og_site_name":"Am haZikaron","article_publisher":"https:\/\/www.facebook.com\/jewage","article_modified_time":"2026-07-27T19:51:16+00:00","og_image":[{"width":500,"height":333,"url":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/history-1-clr.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AmhaZikaron","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/amhazikaron.org\/fr\/a-propos-de-nous\/histoire-de-linstitut\/","url":"https:\/\/amhazikaron.org\/fr\/a-propos-de-nous\/histoire-de-linstitut\/","name":"Histoire de l'Institut - Am haZikaron","isPartOf":{"@id":"https:\/\/amhazikaron.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amhazikaron.org\/fr\/a-propos-de-nous\/histoire-de-linstitut\/#primaryimage"},"image":{"@id":"https:\/\/amhazikaron.org\/fr\/a-propos-de-nous\/histoire-de-linstitut\/#primaryimage"},"thumbnailUrl":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/history-1-clr.jpg","datePublished":"2025-04-13T15:13:20+00:00","dateModified":"2026-07-27T19:51:16+00:00","breadcrumb":{"@id":"https:\/\/amhazikaron.org\/fr\/a-propos-de-nous\/histoire-de-linstitut\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amhazikaron.org\/fr\/a-propos-de-nous\/histoire-de-linstitut\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/amhazikaron.org\/fr\/a-propos-de-nous\/histoire-de-linstitut\/#primaryimage","url":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/history-1-clr.jpg","contentUrl":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/history-1-clr.jpg","width":500,"height":333,"caption":"close up of world famous Pisa clock in Piazza dei Cavalieri, Italy"},{"@type":"BreadcrumbList","@id":"https:\/\/amhazikaron.org\/fr\/a-propos-de-nous\/histoire-de-linstitut\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/amhazikaron.org\/fr\/principal\/"},{"@type":"ListItem","position":2,"name":"\u00c0 propos de nous","item":"https:\/\/amhazikaron.org\/fr\/about\/"},{"@type":"ListItem","position":3,"name":"Histoire de l&#8217;Institut"}]},{"@type":"WebSite","@id":"https:\/\/amhazikaron.org\/fr\/#website","url":"https:\/\/amhazikaron.org\/fr\/","name":"Am haZikaron","description":"\u0418\u043d\u0441\u0442\u0438\u0442\u0443\u0442 \u043d\u0430\u0443\u043a\u0438, \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u044b \u0438 \u043d\u0430\u0441\u043b\u0435\u0434\u0438\u044f \u0435\u0432\u0440\u0435\u0439\u0441\u043a\u043e\u0433\u043e \u043d\u0430\u0440\u043e\u0434\u0430","publisher":{"@id":"https:\/\/amhazikaron.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amhazikaron.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/amhazikaron.org\/fr\/#organization","name":"Am haZikaron","url":"https:\/\/amhazikaron.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/amhazikaron.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/logo.svg","contentUrl":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/logo.svg","width":48,"height":48,"caption":"Am haZikaron"},"image":{"@id":"https:\/\/amhazikaron.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jewage","https:\/\/x.com\/AmhaZikaron"]}]}},"_links":{"self":[{"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/pages\/4986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/comments?post=4986"}],"version-history":[{"count":9,"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/pages\/4986\/revisions"}],"predecessor-version":[{"id":11178,"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/pages\/4986\/revisions\/11178"}],"up":[{"embeddable":true,"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/pages\/5406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/media\/4987"}],"wp:attachment":[{"href":"https:\/\/amhazikaron.org\/fr\/wp-json\/wp\/v2\/media?parent=4986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}