{"id":5215,"date":"2025-04-17T00:47:58","date_gmt":"2025-04-17T00:47:58","guid":{"rendered":"https:\/\/amhazikaron.org\/project\/parentesco\/"},"modified":"2025-08-15T05:39:07","modified_gmt":"2025-08-15T05:39:07","slug":"parentesco","status":"publish","type":"project","link":"https:\/\/amhazikaron.org\/es\/project\/parentesco\/","title":{"rendered":"Parentesco"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5215\" class=\"elementor elementor-5215 elementor-775\" data-elementor-post-type=\"project\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6baf4d7 e-flex e-con-boxed e-con e-parent\" data-id=\"6baf4d7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-77489d9 e-con-full e-flex e-con e-child\" data-id=\"77489d9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f0d521 elementor-widget elementor-widget-image\" data-id=\"6f0d521\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"946\" height=\"630\" src=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/rodnia-clr.jpg\" class=\"attachment-full size-full wp-image-5216\" alt=\"Rod&apos;N&apos;a cover\" srcset=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/rodnia-clr.jpg 946w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/rodnia-clr-300x200.jpg 300w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/rodnia-clr-768x511.jpg 768w\" sizes=\"(max-width: 946px) 100vw, 946px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-44c24c6 e-con-full e-flex e-con e-child\" data-id=\"44c24c6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a58c89f elementor-widget elementor-widget-text-editor\" data-id=\"a58c89f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Instituto <span class=\"in-accent\">Am a-Zikaron <\/span>se dedica a restaurar la historia de las familias jud\u00edas y a popularizar este tema. Nuestro sue\u00f1o es que cada jud\u00edo conozca sus ra\u00edces hist\u00f3ricas. Los ni\u00f1os que vienen a Israel en el marco del programa Taglit participan en nuestro seminario, donde reciben informaci\u00f3n inicial sobre sus or\u00edgenes familiares. Por iniciativa y con el apoyo de la Fundaci\u00f3n Ben\u00e9fica G\u00e9nesis, ampliamos el proyecto e hicimos un programa anual \u00abRod&#8217;N&#8217;ya\u00bb, en el que pueden participar j\u00f3venes de 18 a 35 a\u00f1os que hayan estado en Taglit. El programa \u00abRod&#8217;N&#8217;ya\u00bb est\u00e1 destinado a quienes han regresado de un viaje a Israel, fascinados por la idea de su propia judeidad, fascinados por el pa\u00eds. Queremos apoyar estos \u00e1nimos, intentar orientarlos en la direcci\u00f3n de alguna actividad comunitaria. Que el inter\u00e9s, que ha surgido en los ni\u00f1os durante 10 d\u00edas de estancia en Israel, no desapareci\u00f3 y despu\u00e9s de su partida, que han aprendido: y en su ciudad hay muchas personas que viven la vida jud\u00eda, y en cualquier gusto &#8211; y ultra-religiosa, y secular. Difundimos informaci\u00f3n sobre Rod&#8217;N&#8217;y a trav\u00e9s de las filiales de Hillel en todo el espacio postsovi\u00e9tico. El resultado fue la participaci\u00f3n de 200 personas en el primer a\u00f1o del proyecto.        <\/p><h4>Historia familiar \u00abpara dummies\u00bb<\/h4><p>\u00abRod&#8217;N&#8217;Ya\u00bb es un programa para quienes desean conocer su historia familiar, pero no tienen ni idea de c\u00f3mo abordarlo. Les explicamos a los participantes con todo detalle por d\u00f3nde deben empezar y qu\u00e9 deben buscar desde el principio. Por ejemplo, se puede aprender mucho de las fotos familiares. Una foto de un abuelo o bisabuelo con uniforme militar le dir\u00e1 en qu\u00e9 tropas sirvi\u00f3. Quiz\u00e1 era ingeniero militar o m\u00e9dico militar. Hay otros detalles poco perceptibles que aportan informaci\u00f3n muy valiosa. Por ejemplo, uno de los participantes en nuestro programa no sab\u00eda d\u00f3nde hab\u00eda nacido su bisabuela. Cuando mir\u00f3 su foto, encontr\u00f3 la direcci\u00f3n del estudio fotogr\u00e1fico de Nemirov. En general, hay much\u00edsimos detalles a los que una persona sin formaci\u00f3n simplemente no presta atenci\u00f3n.        <\/p><h4>Herramientas para trabajar con la historia<\/h4><p>Existen tres herramientas para encontrar las ra\u00edces familiares. La primera y principal es entrevistar a familiares, cercanos y lejanos, y a\u00fan mejor -muy lejanos-, sobre los que la persona no sab\u00eda nada: ellos son los que suelen tener la informaci\u00f3n m\u00e1s valiosa. El segundo recurso es la informaci\u00f3n de Internet, desde historias de memorias y libros hasta bases de datos hist\u00f3ricas, libros de registro, listas de enterramientos en cementerios digitalizadas por aficionados. Y, por \u00faltimo, el tercero son los archivos. Ense\u00f1amos a trabajar con ellos, explicamos cu\u00e1ndo tiene sentido buscar informaci\u00f3n en el registro civil y cu\u00e1ndo, en el archivo hist\u00f3rico. Tambi\u00e9n hay fuentes que no siempre est\u00e1n disponibles para el p\u00fablico rusohablante: la literatura rab\u00ednica escrita en hebreo. A lo largo de todo el proyecto, los participantes cuentan con la ayuda de investigadores profesionales: primero les ense\u00f1an a buscar informaci\u00f3n y luego les acompa\u00f1an, llev\u00e1ndoles pr\u00e1cticamente de la mano en todas las etapas.      <\/p><h4>Accidentes no aleatorios<\/h4><p>Un participante del proyecto de Mosc\u00fa viaj\u00f3 a Minsk para encontrar el certificado de matrimonio de su bisabuela en el archivo local. Cuando recibi\u00f3 una copia digital de una hoja del libro rab\u00ednico de registro de matrimonios, result\u00f3 que la segunda l\u00ednea de los registros de la hoja era una anotaci\u00f3n del registro de matrimonio de su bisabuela. Y la primera l\u00ednea era una inscripci\u00f3n similar relativa al bisabuelo de otro participante del mismo proyecto, \u00a1de Ekaterimburgo! Me gustan mucho este tipo de coincidencias, porque estoy segura de que no son realmente aleatorias.   <\/p><h4>Una mirada a trav\u00e9s de siete siglos<\/h4><p>Seis participantes del proyecto \u00abRod&#8217;N&#8217;Ya\u00bb pertenecen directa o indirectamente a la familia Rapoport. Y cada uno de ellos realiz\u00f3 una investigaci\u00f3n, finalizando con diferentes periodos del siglo XIX. Pero la llamativa familia rab\u00ednica Rapoport es conocida desde el siglo XIII, \u00a1es una familia con una historia asombrosa, un mont\u00f3n de personajes pintorescos que vivieron en un espacio enorme desde Alemania e Italia hasta Bielorrusia y Galitzia! Queremos que los participantes conecten con una u otra familia jud\u00eda a trav\u00e9s de la historia de su propia familia. Y les contamos qu\u00e9 son estas familias, qu\u00e9 han hecho los Rapoport o los Feldman durante los \u00faltimos siete siglos.    <\/p><h4>La metaf\u00edsica del despertar<\/h4><p>Existe un fen\u00f3meno interesante en nuestro trabajo. Personas que pertenecen a las mismas familias pero que no se conocen entre s\u00ed acuden de repente a nosotros al mismo tiempo. Mientras que este a\u00f1o tuvimos seis Rapoports, hace un par de a\u00f1os otro proyecto involucr\u00f3 a cinco personas de diferentes pa\u00edses con el apellido Derbaremdiker (\u00abMisericordioso\u00bb en yiddish). Todos ellos son descendientes del famoso tzadik jas\u00eddico Levi Itzkach de Berdichev. Le apodaban Derbaremdiker porque empezaba cada oraci\u00f3n con esta palabra. Hoy en d\u00eda, \u00a1s\u00f3lo hay un par de cientos de Derbaremdikers en el mundo! Y cuando cinco de ellos vinieron a nosotros a la vez, tuvimos la sensaci\u00f3n de que era el propio rabino quien hab\u00eda pisado la tierra de Jerusal\u00e9n. Esperamos con impaciencia el pr\u00f3ximo proyecto, \u00a1queremos averiguar qu\u00e9 familia jud\u00eda ser\u00e1 la siguiente en \u00abdespertar\u00bb!       <\/p><h4>Historia perdida<\/h4><p>A veces se pierden todos los hilos de la historia familiar. Es una tragedia interminable cuando un bisabuelo, debido a su deber de servicio o a las \u00f3rdenes que exist\u00edan en la URSS, no cont\u00f3 a nadie nada sobre su familia, sus parientes o sus or\u00edgenes hasta el final de su vida. Por desgracia, es dif\u00edcil trabajar en estos casos, porque los parientes son la principal fuente de informaci\u00f3n. A veces, en busca de la verdad, la gente encuentra a parientes muy lejanos a los que sus familiares no han visto en d\u00e9cadas. La peculiaridad de trabajar con ni\u00f1os de la CEI es que muchos de ellos no saben absolutamente nada de su ascendencia. Por ejemplo, nos llev\u00f3 mucho tiempo convencer a uno de los participantes de que era descendiente de una familia ucraniana jas\u00eddica extremadamente famosa, uno de los tzadik jas\u00eddicos m\u00e1s famosos. \u00c9l mismo estaba seguro de que proced\u00eda de una familia muy sencilla en la que s\u00f3lo hab\u00eda artesanos.      <\/p><h4>Tras las huellas de las antiguas comunidades<\/h4><p>Realizamos una expedici\u00f3n a los lugares de las antiguas comunidades jud\u00edas de Alemania. No visitamos lugares donde vivieron los antepasados particulares de alguien, sino lugares de asentamiento y caminos de migraci\u00f3n, las historias de sus familias antes de que se convirtieran en rusoparlantes. Y tambi\u00e9n pueblos con nombre: Landau, Oppenheim y otros. Durante una semana cubrimos el periodo comprendido entre los siglos V y XVIII, es decir, 13 siglos de historia jud\u00eda. Uno de los objetivos de nuestro proyecto es conectar a los participantes no s\u00f3lo con el juda\u00edsmo ruso, sino tambi\u00e9n con el mundo jud\u00edo global. Es importante ver con nuestros propios ojos el paisaje en el que existieron nuestros antepasados hace muchos siglos, y despertar en nuestros j\u00f3venes contempor\u00e1neos un sentimiento de conexi\u00f3n con este lugar, con este mundo, con la historia jud\u00eda.     <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aac041e elementor-widget elementor-widget-video\" data-id=\"aac041e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=XrPJoV985n8&amp;t=1s&amp;ab_channel=Serhii&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Expedici\u00f3n de investigaci\u00f3n por las rutas migratorias del pueblo jud\u00edo<\/p>\n","protected":false},"featured_media":5216,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"project-type":[79],"class_list":["post-5215","project","type-project","status-publish","has-post-thumbnail","hentry","project-type-proyectos-completados"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parentesco - Am haZikaron<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amhazikaron.org\/es\/project\/parentesco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parentesco - Am haZikaron\" \/>\n<meta property=\"og:description\" content=\"Expedici\u00f3n de investigaci\u00f3n por las rutas migratorias del pueblo jud\u00edo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amhazikaron.org\/es\/project\/parentesco\/\" \/>\n<meta property=\"og:site_name\" content=\"Am haZikaron\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jewage\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-15T05:39:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/rodnia-clr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"946\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AmhaZikaron\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/project\\\/parentesco\\\/\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/project\\\/parentesco\\\/\",\"name\":\"Parentesco - Am haZikaron\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/project\\\/parentesco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/project\\\/parentesco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/rodnia-clr.jpg\",\"datePublished\":\"2025-04-17T00:47:58+00:00\",\"dateModified\":\"2025-08-15T05:39:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/project\\\/parentesco\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amhazikaron.org\\\/es\\\/project\\\/parentesco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/project\\\/parentesco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/rodnia-clr.jpg\",\"contentUrl\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/rodnia-clr.jpg\",\"width\":946,\"height\":630,\"caption\":\"Rod'N'a cover\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/project\\\/parentesco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parentesco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/\",\"name\":\"Am haZikaron\",\"description\":\"\u0418\u043d\u0441\u0442\u0438\u0442\u0443\u0442 \u043d\u0430\u0443\u043a\u0438, \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u044b \u0438 \u043d\u0430\u0441\u043b\u0435\u0434\u0438\u044f \u0435\u0432\u0440\u0435\u0439\u0441\u043a\u043e\u0433\u043e \u043d\u0430\u0440\u043e\u0434\u0430\",\"publisher\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/#organization\",\"name\":\"Am haZikaron\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo.svg\",\"width\":48,\"height\":48,\"caption\":\"Am haZikaron\"},\"image\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jewage\",\"https:\\\/\\\/x.com\\\/AmhaZikaron\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parentesco - Am haZikaron","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amhazikaron.org\/es\/project\/parentesco\/","og_locale":"es_ES","og_type":"article","og_title":"Parentesco - Am haZikaron","og_description":"Expedici\u00f3n de investigaci\u00f3n por las rutas migratorias del pueblo jud\u00edo","og_url":"https:\/\/amhazikaron.org\/es\/project\/parentesco\/","og_site_name":"Am haZikaron","article_publisher":"https:\/\/www.facebook.com\/jewage","article_modified_time":"2025-08-15T05:39:07+00:00","og_image":[{"width":946,"height":630,"url":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/rodnia-clr.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AmhaZikaron","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/amhazikaron.org\/es\/project\/parentesco\/","url":"https:\/\/amhazikaron.org\/es\/project\/parentesco\/","name":"Parentesco - Am haZikaron","isPartOf":{"@id":"https:\/\/amhazikaron.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amhazikaron.org\/es\/project\/parentesco\/#primaryimage"},"image":{"@id":"https:\/\/amhazikaron.org\/es\/project\/parentesco\/#primaryimage"},"thumbnailUrl":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/rodnia-clr.jpg","datePublished":"2025-04-17T00:47:58+00:00","dateModified":"2025-08-15T05:39:07+00:00","breadcrumb":{"@id":"https:\/\/amhazikaron.org\/es\/project\/parentesco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amhazikaron.org\/es\/project\/parentesco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amhazikaron.org\/es\/project\/parentesco\/#primaryimage","url":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/rodnia-clr.jpg","contentUrl":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/rodnia-clr.jpg","width":946,"height":630,"caption":"Rod'N'a cover"},{"@type":"BreadcrumbList","@id":"https:\/\/amhazikaron.org\/es\/project\/parentesco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/amhazikaron.org\/es\/principal\/"},{"@type":"ListItem","position":2,"name":"Parentesco"}]},{"@type":"WebSite","@id":"https:\/\/amhazikaron.org\/es\/#website","url":"https:\/\/amhazikaron.org\/es\/","name":"Am haZikaron","description":"\u0418\u043d\u0441\u0442\u0438\u0442\u0443\u0442 \u043d\u0430\u0443\u043a\u0438, \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u044b \u0438 \u043d\u0430\u0441\u043b\u0435\u0434\u0438\u044f \u0435\u0432\u0440\u0435\u0439\u0441\u043a\u043e\u0433\u043e \u043d\u0430\u0440\u043e\u0434\u0430","publisher":{"@id":"https:\/\/amhazikaron.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amhazikaron.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amhazikaron.org\/es\/#organization","name":"Am haZikaron","url":"https:\/\/amhazikaron.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amhazikaron.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/logo.svg","contentUrl":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/logo.svg","width":48,"height":48,"caption":"Am haZikaron"},"image":{"@id":"https:\/\/amhazikaron.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jewage","https:\/\/x.com\/AmhaZikaron"]}]}},"_links":{"self":[{"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/project\/5215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/types\/project"}],"version-history":[{"count":1,"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/project\/5215\/revisions"}],"predecessor-version":[{"id":5218,"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/project\/5215\/revisions\/5218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/media\/5216"}],"wp:attachment":[{"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/media?parent=5215"}],"wp:term":[{"taxonomy":"project-type","embeddable":true,"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/project-type?post=5215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}