{"id":6208,"date":"2025-05-22T11:22:41","date_gmt":"2025-05-22T11:22:41","guid":{"rendered":"https:\/\/amhazikaron.org\/de-donde-vienen-los-genios\/"},"modified":"2025-08-15T05:49:15","modified_gmt":"2025-08-15T05:49:15","slug":"de-donde-vienen-los-genios","status":"publish","type":"page","link":"https:\/\/amhazikaron.org\/es\/de-donde-vienen-los-genios\/","title":{"rendered":"De d\u00f3nde vienen los genios"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6208\" class=\"elementor elementor-6208 elementor-2613\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de0e72d e-flex e-con-boxed e-con e-parent\" data-id=\"de0e72d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a830479 e-con-full e-flex e-con e-child\" data-id=\"a830479\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e5011d2 elementor-widget elementor-widget-image\" data-id=\"e5011d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"330\" height=\"440\" src=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/05\/Kafka.jpg\" class=\"attachment-large size-large wp-image-2444\" alt=\"Franz Kafka\" srcset=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/05\/Kafka.jpg 330w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/05\/Kafka-225x300.jpg 225w\" sizes=\"(max-width: 330px) 100vw, 330px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-20baa0d e-con-full e-flex e-con e-child\" data-id=\"20baa0d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-863b4e8 elementor-widget elementor-widget-text-editor\" data-id=\"863b4e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6 style=\"text-align: center;\">Franz Kafka<\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cfbe16d e-con-full e-flex e-con e-child\" data-id=\"cfbe16d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d3092d3 elementor-widget elementor-widget-text-editor\" data-id=\"d3092d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El nombre de Franz Kafka, hasta ahora, en nuestra opini\u00f3n, un genio nunca realmente apreciado, no dice mucho a la mayor\u00eda de los lectores sin pretensiones.<\/p><p>Su nombre, para la gran mayor\u00eda de los que lo han le\u00eddo o s\u00f3lo han o\u00eddo hablar de \u00e9l, provoca un ataque de hast\u00edo, lo asocian con algo oscuro, incomprensible, il\u00f3gico o, en el mejor de los casos, recuerda algunas profundidades secretas del subconsciente.<\/p><p>Sin embargo, el nombre de este escritor est\u00e1 ciertamente de moda y ning\u00fan lector que se precie puede admitir que no ha le\u00eddo a Franz Kafka, aunque, tras haber tropezado con el primer relato, haya fulminado para siempre el libro de este sorprendente autor.<\/p><p>Al mismo tiempo, o mejor dicho, a pesar de todas las actitudes contradictorias del p\u00fablico lector hacia este escritor, podemos afirmar sin lugar a dudas que Franz Kafka no s\u00f3lo es un escritor brillante, sino tambi\u00e9n, sin lugar a dudas, uno de los \u00fanicos profetas jud\u00edos de la llamada \u00abNueva Era\u00bb.  <\/p><p>Como escritor, provoc\u00f3 una revoluci\u00f3n completa en el pensamiento y en la literatura, dejando al descubierto el fondo de la conciencia, y como profeta tr\u00e1gico (\u00bfhab\u00eda alg\u00fan profeta optimista entre los jud\u00edos?) nos grit\u00f3 a todos sobre el horror de la Nueva Era europea, de la que, como uno de sus logros m\u00e1s impresionantes, la civilizaci\u00f3n europea moderna sigue estando orgullosa. La cat\u00e1strofe jud\u00eda, que los europeos (o mejor dicho, los alemanes, con el consentimiento y la participaci\u00f3n t\u00e1citos de otras naciones europeas) organizaron para nosotros, no fue m\u00e1s que una continuaci\u00f3n pesadillesca y l\u00f3gica del horror del que Kafka gritaba. <\/p><p>\u00bfDe d\u00f3nde vienen los genios, y de d\u00f3nde ven\u00eda Franz Kafka? En este estudio intentaremos basarnos en las declaraciones y trabajos de sus bi\u00f3grafos, en particular de eminencias como Claude David, Max Brod y Elias Canneti, de sus amigos, parientes, conocidos y de las mujeres que le amaron. <\/p><p>El propio Franz reconoc\u00eda muy bien en s\u00ed mismo dos l\u00edneas familiares. Y la primera es sin duda la rama Kafka, marcada, en su opini\u00f3n, por \u00abla fuerza, la salud, el buen apetito, la voz fuerte, el don de la palabra, la confianza en s\u00ed mismo, el sentimiento de superioridad sobre todos, la persistencia, el ingenio, el conocimiento de las personas y una cierta nobleza\u00bb. Obs\u00e9rvese, entre par\u00e9ntesis, cu\u00e1n fuertes cualidades positivas, incluso excelentes, dotaban a esta familia al propio Franz &#8211; mientras que con estos parientes, y principalmente con su padre Hermann Kafka, su relaci\u00f3n era dif\u00edcil, por no decir terrible. Estos parientes nunca pudieron comprenderle, y \u00e9l nunca pudo comprenderles a ellos.     <\/p><p>Otra rama es la l\u00ednea materna de la familia L\u00f6wy, a la que dota de cualidades algo diferentes, aparte de la misma \u00abperseverancia\u00bb, todo lo contrario: \u00absensibilidad, sentido de la justicia, inquietud\u00bb. En su famosa \u00abCarta a su padre\u00bb, que, seg\u00fan su bi\u00f3grafo, \u00abnunca ley\u00f3\u00bb, se declara abiertamente, incluso insiste en ello, como un L\u00f6wy, a lo sumo, \u00abcon algunos antecedentes de Kafka\u00bb. <\/p><p>\u00bfQui\u00e9nes son los Kafka? \u00bfY qu\u00e9 significa su propio apellido? Las respuestas a ambas preguntas son bastante prosaicas. Empecemos por esta \u00faltima. Como insisten los investigadores &#8211; \u00abel apellido Kafka en su sonido es claramente checo: Kafka &#8211; es un grajo, y el grajo servir\u00e1, en el futuro el emblema de su casa comercial\u00bb. Este apellido fue dado a la familia, muy probablemente, en la \u00e9poca de Jos\u00e9 II, es decir, seg\u00fan su famoso decreto de 1797, seg\u00fan el cual \u00abhasta el 1 de enero de 1798 todos los jud\u00edos del Imperio austroh\u00fangaro deb\u00edan adoptar apellidos\u00bb, obteniendo as\u00ed el estado civil. El apellido proced\u00eda, al parecer, del apodo del fundador de esta familia. Por qu\u00e9 surgi\u00f3 tal o cual apodo &#8211; no lo sabemos. Tal vez naci\u00f3 de &#8211; \u00abnegro como un grajo\u00bb.       <\/p><p>Franz odiaba su apellido, especialmente las dos \u00abk\u00bb. Entonces, \u00bfqui\u00e9nes son estas personas, apodadas en su d\u00eda con un apodo tan poco acertado como \u00abGalka\u00bb? Esto es lo que sabemos, a partir del estudio de David sobre estas personas fuertes, sanas, con excelente apetito y voz potente. \u00abLa familia de Kafka se distingu\u00eda por su estatura gigantesca. Se dice que el abuelo, Jacob Kafka, carnicero en Vossek, pod\u00eda levantar un saco de harina con los dientes. Todos en la familia eran altos, incluso las hermanas de Franz. Pero \u00e9l mismo se avergonzaba de su elevada estatura, que no le hac\u00eda sentirse fuerte, sino fr\u00e1gil, torpe y rid\u00edculo. En su genealog\u00eda Kafka no se remonta m\u00e1s all\u00e1 de su abuelo Jacob, el mismo que tuvo que esperar a la revoluci\u00f3n de 1848 para tener la oportunidad de casarse y viv\u00eda en el pueblo de Vossek.       <\/p><p>Vossek es un pueblo del sur de Bohemia. Estaba habitado por checos y jud\u00edos. La vida en Vossek se caracterizaba por una extrema miseria. Se encontr\u00f3 el hogar ancestral de Hermann Kafka: una choza con techo de paja. Todos dorm\u00edan en una habitaci\u00f3n: Jakob Kafka, sus cuatro hijos y sus dos hijas. El padre del escritor revivi\u00f3 repetidamente en su memoria los a\u00f1os dif\u00edciles de su infancia: el hambre, cuando no hab\u00eda suficientes patatas, el fr\u00edo, que le provocaba en los tobillos heridas abiertas que no cicatrizaban, a los siete a\u00f1os Hermann Kafka se vio obligado a ir de pueblo en pueblo, empujando una carretilla de mano, su hermana Julia fue enviada a una familia como cocinera. Como Franz recordaba las historias de su padre &#8211; \u00abella ten\u00eda que ir a hacer recados en medio del intenso fr\u00edo con su faldita empapada, la piel de las piernas agriet\u00e1ndose, la faldita hel\u00e1ndose y sec\u00e1ndose s\u00f3lo por la noche en la cama\u00bb.      <\/p><p>Hermann Kafka, sin embargo, reprochaba a sus hijos que no conocieran estos sufrimientos: \u00ab\u00a1Qui\u00e9n lo sabe hoy! \u00a1Qu\u00e9 pueden saber los ni\u00f1os al respecto! \u00a1Nadie ha sufrido as\u00ed! \u00bfC\u00f3mo puede entenderlo un ni\u00f1o moderno?\u00bb. Al mismo tiempo, el mismo bi\u00f3grafo expresa algunas dudas sobre la veracidad absoluta de estas historias, que se han convertido en una leyenda familiar entre los kafoks. \u00abA decir verdad, las fotograf\u00edas conservadas, que muestran a Jakob Kafka y a su esposa vestidos como aut\u00e9nticos burgueses y con aspecto de personas muy pr\u00f3speras, sugieren que esta extrema pobreza no fue siempre as\u00ed, o que la memoria embot\u00f3 poco a poco y mistific\u00f3 ligeramente el pasado\u00bb. <\/p><p>He aqu\u00ed una breve biograf\u00eda del padre de Franz. El pobre jud\u00edo Herman Kafka, tras haber servido tres a\u00f1os en el ej\u00e9rcito imperial, en 1881 llega a Praga y un a\u00f1o despu\u00e9s se casa con Julia L\u00f6wy, \u00abuna muchacha de una familia de ricos pa\u00f1eros de provincias, que al mismo tiempo eran propietarios de una cervecer\u00eda\u00bb. Hagamos caso al bi\u00f3grafo: \u00abJulia L\u00f6wy tra\u00eda sin duda una dote muy importante, y es dif\u00edcil imaginar que esta rica familia aceptara a un peque\u00f1o comerciante sin medios\u00bb.  <\/p><p>En 1881, sin embargo, Hermann abri\u00f3 una tienda de moda en la Zeltnerstrasse y el negocio empez\u00f3 a florecer. Hermann se hizo rico y pronto convirti\u00f3 la peque\u00f1a tienda en una gran empresa mayorista, que ahora estaba situada \u00aben la planta baja del magn\u00edfico palacio Kinski, en la Gran Plaza de la Ciudad Vieja\u00bb. Herman es \u00abrico\u00bb, \u00abexitoso\u00bb, \u00abrealizado\u00bb, \u00ablogr\u00f3 su objetivo\u00bb y, en cualquier caso, por delante de todos sus hermanos y hermanas. M\u00e1s concretamente, nada se sabe de las hermanas, Anna y Julia, parecen haber desaparecido en la oscuridad, mientras que los hermanos&#8230;.   <\/p><p>Su destino se traza con cierto detalle. Ludwig trabaj\u00f3 primero en la tienda de Hermann, luego se convirti\u00f3 en un peque\u00f1o agente de seguros y aparentemente no hizo nada m\u00e1s con su vida. Heinrich muri\u00f3 joven, su hija Irma, con mala salud y un marido infeliz, trabaj\u00f3 durante mucho tiempo en la misma tienda para su t\u00edo Hermann. Franz Kafka recordaba que ni siquiera en su funeral su padre encontr\u00f3 una palabra amable para ella. Lo \u00fanico que se le escap\u00f3 a Hermann fue: \u00abLa pobre Irma me leg\u00f3 un bonito cerdo\u00bb.    <\/p><p>El \u00faltimo hermano de Hermann, Philip, ten\u00eda un peque\u00f1o negocio en una atrasada ciudad checa. Uno de los hijos de Philip muere muy joven en 1901. Tres de sus otros hijos y dos de los hijos de Herman emigran. Cuatro de ellos a Estados Unidos, uno a Paraguay.   <\/p><p>\u00abAfortunado\u00bb para los est\u00e1ndares de la familia Kafka llega a ser s\u00f3lo un primo de Franz: Robert, el quinto hijo de Felipe. Se convierte en un abogado bastante popular y es admirado por Franz: \u00abMi primo es un hombre excelente. Cuando este Robert, de unos cuarenta a\u00f1os, ven\u00eda por la tarde a la piscina de Sophia -no pod\u00eda venir antes, era abogado, un hombre muy ocupado, m\u00e1s por el trabajo que por el placer-, cuando ven\u00eda por la tarde, despu\u00e9s de las cinco, se quitaba la ropa con unos movimientos r\u00e1pidos, se lanzaba al agua y nadaba con la potencia de una bella fiera salvaje, toda rebosante de agua, con los ojos centelleantes, y nadaba inmediatamente hacia la presa, era brillante.\u00bb En \u00abbrillante\u00bb Robert Franz admira todas aquellas cualidades que est\u00e1n ausentes en \u00e9l mismo. Sin embargo, recordando a Robert, a\u00f1ade: \u00abY seis meses despu\u00e9s muri\u00f3, torturado in\u00fatilmente por los m\u00e9dicos\u00bb.   <\/p><p>Por cierto, de la familia Kafka sali\u00f3 otro hombre a\u00fan m\u00e1s afortunado que Robert. Como escribe Claude David \u00abse trata de Bruno Kafka, cuyo nombre, sin embargo, nunca se menciona en el \u00abDiario\u00bb del escritor, ni en su correspondencia, era hijo de uno de los hermanos del abuelo Jacob. Ten\u00eda casi la misma edad que el escritor, pero su carrera tom\u00f3 un rumbo muy diferente. Hijo de un abogado, se convirti\u00f3 al cristianismo, fue profesor de derecho, decano de la facultad y luego rector de la universidad. Despu\u00e9s de la guerra, Bruno Kafka fue miembro del Parlamento, redactor jefe de Bohemia, uno de los principales peri\u00f3dicos de Praga, y, de no haber sido por su prematura muerte, probablemente habr\u00eda desempe\u00f1ado un papel importante en la historia de Checoslovaquia. Max Brod, que le odiaba, cuenta que ten\u00eda cierto parecido f\u00edsico con su primo Franz: \u00abCabello negro como la brea, ojos centelleantes, el mismo coraje en el rostro &#8211; incluso los movimientos indican la nobleza de una personalidad excepcional. S\u00f3lo que en Franz todo era m\u00e1s digno y gentil; en Bruno se acercaba a la caricatura, con tendencia al fraude ingenioso, a la violencia e incluso al sadismo\u00bb. As\u00ed, al menos, era como le parec\u00eda a Max Brod, que a menudo no se llevaba bien con Bruno. As\u00ed eran estos Kafka, cuya energ\u00eda envidiaba Franz, pero a los que no quer\u00eda pertenecer\u00bb.       <\/p><p>La familia L\u00f6wy, a la que pertenec\u00eda la madre del escritor, ten\u00eda incluso m\u00e1s \u00ab\u00e9xito\u00bb que los Kafki en t\u00e9rminos de perspicacia empresarial. Eran similares en algunos aspectos. Ambas familias estaban formadas por jud\u00edos asimilados, ambos \u00abproced\u00edan de comerciantes de provincias\u00bb.  <\/p><p>Sin embargo, los L\u00f6wy eran diferentes de los diligentes Kafok. En el ambiente de la familia L\u00f6wy a\u00fan quedaba algo de aire, un contragolpe, una brecha, aunque peque\u00f1a, en este r\u00edgido practicismo de tienda, cierta \u00abimpresi\u00f3n de inestabilidad\u00bb, algo que no se pod\u00eda programar. <\/p><p>Por ejemplo, hab\u00eda muchos solteros entre ellos, algo extremadamente at\u00edpico en este tipo de familias. En general, de los cinco hermanos y medio hermanos de la madre de la escritora, Julia (su padre se volvi\u00f3 a casar poco despu\u00e9s de la muerte de su joven esposa), s\u00f3lo dos crearon una familia. Uno de los hermanos, Alfred, que se fue a Espa\u00f1a y lleg\u00f3 a ser director de los ferrocarriles de Madrid, era, como se\u00f1ala el bi\u00f3grafo, \u00abuna celebridad familiar\u00bb. \u00abAl parecer, fue \u00e9l quien en \u00abEl proceso\u00bb se convirti\u00f3 en el prototipo del \u00abt\u00edo provinciano\u00bb, pomposo, imperioso, cuyos empe\u00f1os, sin embargo, acaban casi siempre en fracaso. A Kafka no le ca\u00eda mal, encontraba un lenguaje com\u00fan con su t\u00edo mucho mejor que con sus padres. Y lo que es m\u00e1s importante, Alfred L\u00f6wy era para \u00e9l el s\u00edmbolo del soltero\u00bb.     <\/p><p>El otro hermano de su madre y t\u00edo favorito de Franz, Siegfried L\u00f6wy, con el que suele ir de vacaciones a Trieste, ha elegido una profesi\u00f3n extra\u00f1a para la familia: la de m\u00e9dico rural. Tambi\u00e9n \u00e9l permanece soltero y, qued\u00e1ndose en el campo, contempla la naturaleza y el silencio. Franz escribe en su diario que tiene \u00abuna mente inhumanamente delgada, una mente de soltero, una mente de p\u00e1jaro que parece brotar de una garganta demasiado estrecha\u00bb. Y as\u00ed vive en el pueblo, profundamente arraigado, contento, como se siente uno cuando un ligero delirio, tomado por la melod\u00eda de la vida, le hace estar contento\u00bb.  <\/p><p>El otro t\u00edo de Franz, Josef, no hace menos, sino cosas a\u00fan m\u00e1s extravagantes: se va al fin del mundo, al ex\u00f3tico Congo, se casa con una francesa y se traslada a Par\u00eds. Los bi\u00f3grafos no tienen nada que decir sobre otro hermano de su madre, Richard L\u00f6wy, salvo que \u00abera un oscuro peque\u00f1o comerciante\u00bb. <\/p><p>El \u00faltimo hermano de Julia Kafka, Rudolf, tambi\u00e9n permanece soltero de por vida. Rudolf es considerado en la familia como un \u00abperdedor\u00bb, un \u00abbicho raro\u00bb, un \u00abhombre divertido\u00bb o, como escribe Franz, \u00abincomprensible, demasiado amable, demasiado modesto, solitario y, sin embargo, hablador\u00bb. Abraza el cristianismo, lo que ya era inexplicable de por s\u00ed, convive y choca con su padre toda su vida, y por todo ello ejerce de \u00absimple contable en una cervecer\u00eda\u00bb. Por cierto, uno de sus antepasados y de Franz, el hijo del tatarabuelo del escritor, Joseph, tambi\u00e9n renunci\u00f3 a la fe de sus padres, lo que le vali\u00f3 una actitud correspondiente en la familia. En general, podemos decir que Rudolf era una par\u00e1bola familiar. Cuando el peque\u00f1o Franz hac\u00eda algo que a su padre le parec\u00eda una estupidez impensable, Herman Kafka sol\u00eda exclamar: \u00ab\u00a1Te pareces a Rudolf!\u00bb. Al parecer, esta comparaci\u00f3n se hizo tan habitual en la familia que el propio Franz cre\u00eda en parte en ella. En cualquier caso, en 1922, tras la muerte de Rudolf, escribi\u00f3 en su diario: \u00abEl parecido con el t\u00edo R. es asombroso y m\u00e1s que eso: ambos son tranquilos (yo &#8211; menos), ambos son dependientes de sus padres (yo &#8211; m\u00e1s), enemistados con su padre, queridos por su madre&#8230;, ambos son t\u00edmidos, super modestos (\u00e9l &#8211; m\u00e1s), ambos se consideran nobles, buena gente, lo cual es bastante err\u00f3neo en mi caso y, por lo que s\u00e9, poco corresponde a la verdad en el suyo &#8230;.ambos son al principio hipocondr\u00edacos y luego realmente enfermos, ambos, aunque holgazanes, est\u00e1n bien provistos por el mundo (\u00e9l, como holgaz\u00e1n menor, est\u00e1 provisto de mucho peor, por lo que se puede comparar) ambos son funcionarios (\u00e9l es el mejor), ambos tienen las vidas m\u00e1s mon\u00f3tonas, ambos est\u00e1n poco desarrollados, ambos son j\u00f3venes hasta el final &#8211; la palabra \u00abjoven\u00bb es m\u00e1s precisa que \u00abpreservado\u00bb &#8211; ambos est\u00e1n cerca de la locura, \u00e9l, lejos de ser jud\u00edo, con un valor inaudito, con una desesperaci\u00f3n inaudita (por la que se puede juzgar cu\u00e1n grande es la amenaza de la locura), se salv\u00f3 en la iglesia, hasta el final &#8230; Tampoco es cierto que no fuera bondadoso, nunca not\u00e9 en \u00e9l ni rastro de avaricia, envidia, odio, codicia; y era demasiado d\u00e9bil para ayudar \u00e9l mismo a los dem\u00e1s. Era infinitamente m\u00e1s inocente que yo; no puede haber comparaci\u00f3n. En los detalles era una caricatura de m\u00ed, en lo esencial yo soy una caricatura de \u00e9l\u00bb. As\u00ed, Franz, como escribe Claude David, intent\u00f3 reconocerse en Rudolf, en su destino, que, seg\u00fan le pareci\u00f3 entonces al escritor, estaba destinado a \u00e9l y a la herencia de L\u00f6wy.         <\/p><p>Conociendo ahora el destino de este hombre brillante, podemos darnos cuenta de lo grandes que eran sus delirios sobre s\u00ed mismo. Pero Franz estaba casi seguro -le parec\u00eda que estaba anticipando su propia locura- recordaba al hermano de su abuela materna Esther, del que no sab\u00eda nada, salvo que siempre le hab\u00edan llamado \u00abel loco t\u00edo Nathan\u00bb.   <\/p><p>Franz sospechaba persistentemente de su propia locura, mientras que el mundo que le rodeaba estaba loco desde hac\u00eda mucho tiempo. Es posible que su sensaci\u00f3n de tragedia personal fuera tan fuerte porque era uno de los pocos profetas que reconoc\u00eda la locura del mundo que le rodeaba y, sin embargo, se culpaba a s\u00ed mismo de su incapacidad para estar a su altura. Era como un funambulista, bailando una extra\u00f1a danza impensable sobre el alambre, un funambulista no por elecci\u00f3n sino por obligaci\u00f3n. M\u00e1s all\u00e1 de los l\u00edmites del alambre, se celebraba la locura, una locura ordinaria, habitual y generalizada.   <\/p><p>Entonces, \u00bfde d\u00f3nde proced\u00eda el profeta en una familia compuesta casi al cien por cien por tenderos, comerciantes y cerveceros? En la genealog\u00eda de Franz Kafka hab\u00eda otra l\u00ednea familiar, envuelta en leyendas casi sagradas, en la que, como escribe Claude David, \u00abse perciben rastros de espiritualidad\u00bb. <\/p><p>Es una l\u00ednea de Porias. Porias es el apellido de la abuela del escritor. El propio Franz sab\u00eda muy poco sobre esta rama familiar, sobre todo algunas leyendas familiares que parec\u00edan casi leyendas despu\u00e9s de mucho tiempo. En su diario recoge de boca de otra persona una historia sobre su tatarabuelo Joseph Porias, que vivi\u00f3 en el siglo XVIII: \u00abera un hombre extremadamente culto, tan respetado por los cristianos como por los jud\u00edos. Durante un incendio, gracias a su piedad, ocurri\u00f3 un milagro: el fuego no toc\u00f3 su casa y \u00e9sta sobrevivi\u00f3, mientras que todas las casas de alrededor se quemaron.   <\/p><p>Como se\u00f1ala el bi\u00f3grafo, \u00abla madre de Kafka, sin embargo, conoc\u00eda a Adam Porias, su abuelo, hijo de Joseph, porque ella ten\u00eda seis a\u00f1os cuando \u00e9ste muri\u00f3. Era un rabino que tambi\u00e9n realizaba el rito de la circuncisi\u00f3n (es decir, un mohel), y tambi\u00e9n era pa\u00f1ero. Ella hablaba de \u00e9l como de un hombre \u00abmuy piadoso y muy culto, con una larga barba blanca\u00bb. Record\u00f3 c\u00f3mo tuvo que, cuando muri\u00f3, \u00abcoger los dedos del muerto y pedirle perd\u00f3n por todas las transgresiones que pudiera haber cometido con \u00e9l\u00bb. No ha olvidado que este abuelo practicaba escrupulosamente el ba\u00f1o prescrito por el canon religioso: \u00abSe ba\u00f1aba todos los d\u00edas en el r\u00edo, incluso en invierno. Para ello ten\u00eda que abrir un agujero en el hielo con un hacha\u00bb. \u00bfQu\u00e9 m\u00e1s sab\u00eda el escritor sobre la familia Porias? No mucho. Por ejemplo, que Sarah, la esposa del bisabuelo de Adam Porias, no pudo soportar la muerte de su hija, que falleci\u00f3 a los veintiocho a\u00f1os a causa del tifus: se arroj\u00f3 al Elba. Esto es todo, o casi todo, aparte del ambiente de leyendas, lo que se sab\u00eda de la familia Porias.      <\/p><p>Hemos emprendido nuestra propia investigaci\u00f3n sobre esta familia y he aqu\u00ed la informaci\u00f3n adicional que ha llegado a nuestro conocimiento. Pa(o)rias es un apellido de origen espa\u00f1ol o portugu\u00e9s. La migraci\u00f3n de esta rama familiar pas\u00f3 a trav\u00e9s de Italia a Bohemia y Chequia que han entrado como resultado en el Imperio Austroh\u00fangaro. Uno de los investigadores de una especie Porgesov ha realizado un examen fon\u00e9tico-ling\u00fc\u00edstico de la ortograf\u00eda y pronunciaci\u00f3n en diferentes pa\u00edses de Europa del apellido Parias. En italiano este apellido tiene la graf\u00eda Parjas o Parges, que se pronunciaba Parjas o Parias.    <\/p><p>Cuando la familia se traslad\u00f3 a pa\u00edses germ\u00e1nicos y eslavos, la ortograf\u00eda y la pronunciaci\u00f3n del apellido cambiaron. Las ramas de la familia cuyos nuevos documentos se copiaron de antiguos documentos italianos conservaron la ortograf\u00eda correcta, pero perdieron la pronunciaci\u00f3n original y como resultado se convirtieron en Parges y Porges. Las mismas familias cuyos documentos se compilaron a partir de informaci\u00f3n oral empezaron a escribir el apellido seg\u00fan las reglas de la fon\u00e9tica local, es decir, Porias y Parias. As\u00ed, de una familia Parjas (Parges) surgieron dos nuevos apellidos Parges y Parias, que, de hecho, son un mismo nombre gen\u00e9rico.   <\/p><p>Al investigar sobre esta familia, por fin pudimos responder a nuestra pregunta principal: de d\u00f3nde proced\u00eda Franz Kafka, este escritor y profeta \u00fanico. Result\u00f3 que la familia Parias (Parges) dio al mundo muchos rabinos famosos, talmudistas y, m\u00e1s tarde, ya en el siglo XX, escritores y figuras de la cultura. He aqu\u00ed s\u00f3lo algunos de ellos:  <\/p><p>Moshe, hijo de Israel Naftali Hirsch Porges naci\u00f3 en 1600 en Praga y muri\u00f3 en 1670 en Jerusal\u00e9n. Fue rabino en Praga y m\u00e1s tarde emisario de la comunidad asquenaz\u00ed en Jerusal\u00e9n. All\u00ed tambi\u00e9n recibi\u00f3 el apodo de Prager. La comunidad jud\u00eda de la Tierra Prometida se mantuvo en aquellos a\u00f1os gracias a las generosas donaciones de los jud\u00edos polacos. Durante los a\u00f1os de los pogromos de Khmelnitsky en Ucrania y Polonia, la situaci\u00f3n econ\u00f3mica de la comunidad asquenaz\u00ed en Eretz Israel se deterior\u00f3 bruscamente. Se decidi\u00f3 enviar a Mosh\u00e9 a Europa para recoger donativos. Mientras cumpl\u00eda su misi\u00f3n en 1650, Moshe escribi\u00f3 una peque\u00f1a obra ilustrada sobre la vida jud\u00eda en Israel: \u00abLos caminos de Si\u00f3n\u00bb. Esta obra s\u00f3lo se public\u00f3 una vez, pero se gan\u00f3 el coraz\u00f3n de los jud\u00edos europeos, que respondieron generosamente al talento del escritor: la misi\u00f3n estaba cumplida y los problemas econ\u00f3micos resueltos.       <\/p><p>Aaron hijo de Benjamin Porges (Porjes) naci\u00f3 en Praga en 1650. Como rabino de Praga, escribi\u00f3 una obra famosa, El recuerdo de Aar\u00f3n, sobre los antiguos ritos jud\u00edos relativos a la muerte y los difuntos. <\/p><p>Yosef hijo de Yehuda Leib Porges, un famoso autor que escribi\u00f3 en hebreo a principios del siglo XVIII.<\/p><p>En el siglo XIX trabajaron en Europa el dramaturgo Karl Porges, el pintor Ingatz Yosef Porges, el rabino y bibli\u00f3grafo Natan Porges, el compositor Heinrich Porges y su hija, la escritora, dramaturga y actriz Elsa Bernstein.<\/p><p>En el siglo XX, esta familia dio al mundo a Franz Kafka.<\/p><p>La familia Porias, como muchas otras familias jud\u00edas europeas, extendi\u00f3 sus ramas por el oc\u00e9ano Atl\u00e1ntico. All\u00ed, en Estados Unidos, Friedrich Porges estuvo en el origen de Hollywood, que crearon los hermanos Arthur e Irwin Porges, y Fred Astaire, el bailar\u00edn m\u00e1s famoso de su \u00e9poca, descendiente tambi\u00e9n de esta famosa familia, conquist\u00f3 los corazones con su baile. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Franz Kafka El nombre de Franz Kafka, hasta ahora, en nuestra opini\u00f3n, un genio nunca realmente apreciado, no dice mucho a la mayor\u00eda de los lectores sin pretensiones. Su nombre, para la gran mayor\u00eda de los que lo han le\u00eddo o s\u00f3lo han o\u00eddo hablar de \u00e9l, provoca un ataque de hast\u00edo, lo asocian con [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-6208","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>De d\u00f3nde vienen los genios - Am haZikaron<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amhazikaron.org\/es\/de-donde-vienen-los-genios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De d\u00f3nde vienen los genios - Am haZikaron\" \/>\n<meta property=\"og:description\" content=\"Franz Kafka El nombre de Franz Kafka, hasta ahora, en nuestra opini\u00f3n, un genio nunca realmente apreciado, no dice mucho a la mayor\u00eda de los lectores sin pretensiones. Su nombre, para la gran mayor\u00eda de los que lo han le\u00eddo o s\u00f3lo han o\u00eddo hablar de \u00e9l, provoca un ataque de hast\u00edo, lo asocian con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amhazikaron.org\/es\/de-donde-vienen-los-genios\/\" \/>\n<meta property=\"og:site_name\" content=\"Am haZikaron\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jewage\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-15T05:49:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/05\/Kafka.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"330\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AmhaZikaron\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"20 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/de-donde-vienen-los-genios\\\/\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/de-donde-vienen-los-genios\\\/\",\"name\":\"De d\u00f3nde vienen los genios - Am haZikaron\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/de-donde-vienen-los-genios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/de-donde-vienen-los-genios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Kafka.jpg\",\"datePublished\":\"2025-05-22T11:22:41+00:00\",\"dateModified\":\"2025-08-15T05:49:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/de-donde-vienen-los-genios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amhazikaron.org\\\/es\\\/de-donde-vienen-los-genios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/de-donde-vienen-los-genios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Kafka.jpg\",\"contentUrl\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Kafka.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/de-donde-vienen-los-genios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De d\u00f3nde vienen los genios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/\",\"name\":\"Am haZikaron\",\"description\":\"\u0418\u043d\u0441\u0442\u0438\u0442\u0443\u0442 \u043d\u0430\u0443\u043a\u0438, \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u044b \u0438 \u043d\u0430\u0441\u043b\u0435\u0434\u0438\u044f \u0435\u0432\u0440\u0435\u0439\u0441\u043a\u043e\u0433\u043e \u043d\u0430\u0440\u043e\u0434\u0430\",\"publisher\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/#organization\",\"name\":\"Am haZikaron\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo.svg\",\"width\":48,\"height\":48,\"caption\":\"Am haZikaron\"},\"image\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jewage\",\"https:\\\/\\\/x.com\\\/AmhaZikaron\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De d\u00f3nde vienen los genios - Am haZikaron","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amhazikaron.org\/es\/de-donde-vienen-los-genios\/","og_locale":"es_ES","og_type":"article","og_title":"De d\u00f3nde vienen los genios - Am haZikaron","og_description":"Franz Kafka El nombre de Franz Kafka, hasta ahora, en nuestra opini\u00f3n, un genio nunca realmente apreciado, no dice mucho a la mayor\u00eda de los lectores sin pretensiones. Su nombre, para la gran mayor\u00eda de los que lo han le\u00eddo o s\u00f3lo han o\u00eddo hablar de \u00e9l, provoca un ataque de hast\u00edo, lo asocian con [&hellip;]","og_url":"https:\/\/amhazikaron.org\/es\/de-donde-vienen-los-genios\/","og_site_name":"Am haZikaron","article_publisher":"https:\/\/www.facebook.com\/jewage","article_modified_time":"2025-08-15T05:49:15+00:00","og_image":[{"width":330,"height":440,"url":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/05\/Kafka.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AmhaZikaron","twitter_misc":{"Tiempo de lectura":"20 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/amhazikaron.org\/es\/de-donde-vienen-los-genios\/","url":"https:\/\/amhazikaron.org\/es\/de-donde-vienen-los-genios\/","name":"De d\u00f3nde vienen los genios - Am haZikaron","isPartOf":{"@id":"https:\/\/amhazikaron.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amhazikaron.org\/es\/de-donde-vienen-los-genios\/#primaryimage"},"image":{"@id":"https:\/\/amhazikaron.org\/es\/de-donde-vienen-los-genios\/#primaryimage"},"thumbnailUrl":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/05\/Kafka.jpg","datePublished":"2025-05-22T11:22:41+00:00","dateModified":"2025-08-15T05:49:15+00:00","breadcrumb":{"@id":"https:\/\/amhazikaron.org\/es\/de-donde-vienen-los-genios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amhazikaron.org\/es\/de-donde-vienen-los-genios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amhazikaron.org\/es\/de-donde-vienen-los-genios\/#primaryimage","url":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/05\/Kafka.jpg","contentUrl":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/05\/Kafka.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/amhazikaron.org\/es\/de-donde-vienen-los-genios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/amhazikaron.org\/es\/principal\/"},{"@type":"ListItem","position":2,"name":"De d\u00f3nde vienen los genios"}]},{"@type":"WebSite","@id":"https:\/\/amhazikaron.org\/es\/#website","url":"https:\/\/amhazikaron.org\/es\/","name":"Am haZikaron","description":"\u0418\u043d\u0441\u0442\u0438\u0442\u0443\u0442 \u043d\u0430\u0443\u043a\u0438, \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u044b \u0438 \u043d\u0430\u0441\u043b\u0435\u0434\u0438\u044f \u0435\u0432\u0440\u0435\u0439\u0441\u043a\u043e\u0433\u043e \u043d\u0430\u0440\u043e\u0434\u0430","publisher":{"@id":"https:\/\/amhazikaron.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amhazikaron.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amhazikaron.org\/es\/#organization","name":"Am haZikaron","url":"https:\/\/amhazikaron.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amhazikaron.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/logo.svg","contentUrl":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/logo.svg","width":48,"height":48,"caption":"Am haZikaron"},"image":{"@id":"https:\/\/amhazikaron.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jewage","https:\/\/x.com\/AmhaZikaron"]}]}},"_links":{"self":[{"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/pages\/6208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/comments?post=6208"}],"version-history":[{"count":1,"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/pages\/6208\/revisions"}],"predecessor-version":[{"id":6209,"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/pages\/6208\/revisions\/6209"}],"wp:attachment":[{"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/media?parent=6208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}