{"id":6206,"date":"2025-05-22T11:45:26","date_gmt":"2025-05-22T11:45:26","guid":{"rendered":"https:\/\/amhazikaron.org\/barones-judios\/"},"modified":"2025-08-15T05:49:05","modified_gmt":"2025-08-15T05:49:05","slug":"barones-judios","status":"publish","type":"page","link":"https:\/\/amhazikaron.org\/es\/barones-judios\/","title":{"rendered":"Barones jud\u00edos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6206\" class=\"elementor elementor-6206 elementor-2647\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-44a59c0 e-con-full e-flex e-con e-parent\" data-id=\"44a59c0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a27be91 e-con-full e-flex e-con e-child\" data-id=\"a27be91\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d9c8807 elementor-widget elementor-widget-image\" data-id=\"d9c8807\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"405\" height=\"608\" src=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/\u0413\u0438\u043d\u0446\u0431\u0443\u0440\u0433.webp\" class=\"attachment-large size-large wp-image-5229\" alt=\"Gorazi Ginzburg\" srcset=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/\u0413\u0438\u043d\u0446\u0431\u0443\u0440\u0433.webp 405w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/\u0413\u0438\u043d\u0446\u0431\u0443\u0440\u0433-200x300.webp 200w\" sizes=\"(max-width: 405px) 100vw, 405px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f4deec elementor-widget elementor-widget-text-editor\" data-id=\"1f4deec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6 style=\"text-align: center;\">Horace Ginzburg<\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b485b0e elementor-widget elementor-widget-text-editor\" data-id=\"b485b0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Esta historia comienza con un tal Jehiel de la ciudad portuguesa de Oporto. Esta ciudad principal de la provincia de Entre Duro e Minho era conocida en el siglo XV por su numerosa comunidad jud\u00eda. El 4 de diciembre de 1496, el rey promulg\u00f3 un decreto que ordenaba a todos los jud\u00edos abandonar Portugal bajo pena de muerte. El decreto establec\u00eda que \u00abning\u00fan cristiano, bajo amenaza de confiscaci\u00f3n de todos sus bienes, ocultar\u00e1 a un jud\u00edo en su posesi\u00f3n despu\u00e9s de la expiraci\u00f3n de un per\u00edodo determinado, y que ning\u00fan gobernante futuro, bajo ning\u00fan pretexto, permitir\u00e1 que los jud\u00edos se establezcan en el reino&#8230; Todos los ni\u00f1os jud\u00edos, de cuatro a veinte a\u00f1os, ser\u00e1n arrebatados a sus padres y convertidos a la fe cristiana.\u00bb Unos 20.000 fueron conducidos a la capital; \u00abcomo ovejas, fueron conducidos a un vasto palacio. Aqu\u00ed se anunci\u00f3 a los jud\u00edos que en adelante eran esclavos del rey, que dispondr\u00eda de ellos como mejor le pareciera.\u00bb   <\/p><p>Fue de este pa\u00eds de donde huy\u00f3 Jehiel. No se sabe c\u00f3mo, pero consigui\u00f3 llegar con su familia a la ciudad b\u00e1vara de Ulm, en pleno sur de Alemania. El lugar se llamaba originalmente \u00abHulma\u00bb. Fue construida por los romanos como puesto avanzado para sus legiones. Fue durante la \u00e9poca romana cuando surgi\u00f3 la primera comunidad jud\u00eda en la ciudad. Seg\u00fan los enciclopedistas, hubo incluso una carta recibida por la comunidad jud\u00eda de Ulm desde Jerusal\u00e9n a finales del siglo I d.C. Incluso se han conservado varias l\u00e1pidas con inscripciones jud\u00edas que datan de 1246. En 1281 ya se hab\u00eda construido una sinagoga en Ulm.       <\/p><p>En esta \u00e9poca, los jud\u00edos eran considerados propiedad de la corona real. En los siglos XII y XIII, todas las rutas comerciales hacia el sur y el este pasaban por Ulm. La ciudad se convirti\u00f3 en un centro de comercio y un punto de escala, lo que no pod\u00eda sino afectar a su desarrollo. Sin duda, los jud\u00edos desempe\u00f1aron un papel importante en \u00e9l como tenderos, artesanos, int\u00e9rpretes y comerciantes internacionales.   <\/p><p>En 1348, durante la epidemia de peste, la llamada \u00abpeste negra\u00bb, que asolaba Europa en aquella \u00e9poca, una turba de cristianos, que acusaba a los jud\u00edos de envenenar los pozos, organiz\u00f3 un pogromo en Ulm. El magistrado y el representante local de la autoridad real, que estaban obligados a proteger el \u00abbien real\u00bb, que entonces se consideraba que eran los jud\u00edos, se justificaron diciendo que \u00abtodas las medidas que hab\u00edan tomado eran impotentes para someter a la turba\u00bb. As\u00ed, los jud\u00edos de Ulm se vieron obligados a pagar impuestos especiales al magistrado para garantizar su seguridad. En esencia, se trataba de un aut\u00e9ntico chanchullo.   <\/p><p>Como escribe el profesor Pressel, al cabo de un tiempo se abri\u00f3 en la ciudad una yeshibot, que m\u00e1s tarde se hizo muy popular en el barrio. Tambi\u00e9n surgieron un ba\u00f1o jud\u00edo, un hospital y una sala especial para bodas y bailes. (Interesante en este sentido es la sala de baile mencionada en la enumeraci\u00f3n &#8211; esto s\u00f3lo confirma una vez m\u00e1s que no siempre tenemos una imagen correcta de la vida jud\u00eda en la \u00e9poca medieval). En 1383, el rey Wenzel, necesitado de dinero, orden\u00f3 a los jud\u00edos de la ciudad que depositaran la d\u00e9cima parte de su fortuna en el tesoro. Dos a\u00f1os m\u00e1s tarde, el magistrado de Ulm, hizo un trato con el rey &#8211; tom\u00f3 del rey por 40 mil florines para pagar los impuestos de los jud\u00edos de la ciudad. De este modo, los jud\u00edos pasaron a estar bajo la autoridad no s\u00f3lo del rey, sino tambi\u00e9n del gobierno local. Aprovech\u00e1ndose de ello, el magistrado anunci\u00f3 que todas las deudas contra\u00eddas con los jud\u00edos deb\u00edan ingresarse en el tesoro de la ciudad. El magistrado comenz\u00f3 entonces a destruir las deudas contra\u00eddas con los jud\u00edos.       <\/p><p>En 1425, se aprobaron decretos que prohib\u00edan a los jud\u00edos de Ulm tener sirvientes cristianos, salir a la calle durante las fiestas importantes y, a su vez, se prohibi\u00f3 a los cristianos utilizar los servicios de los m\u00e9dicos jud\u00edos. Otros tres a\u00f1os m\u00e1s tarde, los cristianos presentaron una acusaci\u00f3n de asesinato ritual contra los jud\u00edos de Ravensburg, cerca de Ulm. El proceso termin\u00f3 con la quema en la hoguera de varios jud\u00edos y la expulsi\u00f3n de todos los jud\u00edos de Ravensburg. Finalmente, en 1499, tras muchas peticiones, el rey Maximiliano I liber\u00f3 a la ciudad de la protecci\u00f3n de los jud\u00edos. Inmediatamente, el magistrado promulg\u00f3 un decreto por el que se expulsaba a todos los jud\u00edos de Ulm. Los jud\u00edos son desterrados para siempre y la ciudad, seg\u00fan los cristianos alemanes de la \u00e9poca, \u00abqueda finalmente libre de jud\u00edos\u00bb.     <\/p><p>Fue entonces cuando la familia de Jehiel y su hijo Eliezer Avraham, que m\u00e1s tarde recibir\u00eda el sobrenombre y luego el apellido de Ulma-G\u00fcnzburg, se vieron obligados a huir de Ulm, al igual que antes hab\u00edan huido de Oporto, en Portugal.<\/p><p>S\u00f3lo despu\u00e9s de 200 a\u00f1os consiguieron algunos jud\u00edos regresar y establecerse de nuevo en Ulm, pagando grandes sumas de dinero al magistrado por dicho permiso. Pero incluso a principios del siglo XX s\u00f3lo viv\u00edan all\u00ed 613 jud\u00edos. Por cierto, fue en esta ciudad, tan poco amistosa con los jud\u00edos, donde naci\u00f3 el gran Albert Einstein el 14 de marzo de 1879 en el seno de la familia del propietario de una peque\u00f1a tienda.  <\/p><p>Para concluir la historia jud\u00eda de esta ciudad, cabe se\u00f1alar que representa un ejemplo cl\u00e1sico casi t\u00edpico de la existencia de jud\u00edos en ciudades europeas desde la Alta Edad Media hasta la historia moderna. Muy a menudo los jud\u00edos fueron los primeros, junto con los romanos, en desarrollar estos lugares entonces absolutamente salvajes y b\u00e1rbaros, puestos avanzados convertidos poco a poco en fortalezas y ciudades, y gradualmente los nativos comenzaron a asentarse en ellos. Los jud\u00edos, en virtud de su energ\u00eda, educaci\u00f3n, conexiones comerciales, conocimiento de idiomas y habilidad comercial, contribu\u00edan a la prosperidad financiera de la ciudad, a lo que sol\u00eda seguir su privaci\u00f3n de derechos como no cristianos, acusaciones de todos los pecados capitales, desde libelos de sangre hasta despojo y peste, con la confiscaci\u00f3n obligatoria de todas las finanzas y propiedades; despu\u00e9s sol\u00eda seguir una serie de pogromos, y luego su expulsi\u00f3n de la ciudad.  <\/p><p>Por cierto, las interminables acusaciones a los jud\u00edos de que infectaban deliberadamente a los cristianos con la peste se basaban en la Edad Media en una observaci\u00f3n bastante simple: los propios jud\u00edos sufr\u00edan en realidad mucho menos de esta enfermedad, entonces mortal, que las naciones europeas circundantes. Pero esto no se deb\u00eda a razones m\u00edsticas, sino a que los jud\u00edos de la Edad Media eran los \u00fanicos que observaban estrictamente las normas religiosas y rituales de higiene, mientras que la poblaci\u00f3n local no s\u00f3lo no las cumpl\u00eda, sino que las consideraba \u00absalvajes y sat\u00e1nicas\u00bb. <\/p><p>Cada vez, sin embargo, los jud\u00edos trataban de regresar a las ciudades de las que hab\u00edan sido expulsados (Ulm no es una excepci\u00f3n en este sentido) no por nostalgia o amor a la poblaci\u00f3n local, sino por la desesperada situaci\u00f3n de personas privadas de su patria, perseguidas en toda Europa, impotentes e indefensas (los jud\u00edos no ten\u00edan derecho a portar armas). La historia descrita y desarrollada seg\u00fan el esquema desde el primer asentamiento, la prosperidad financiera hasta la privaci\u00f3n de derechos, los pogromos, la expulsi\u00f3n y el retorno, se repiti\u00f3 en casi todas las ciudades europeas con la precisi\u00f3n de un reloj, hasta finales del siglo XIX. Tras la siguiente expulsi\u00f3n, los jud\u00edos intentaban encontrar un nuevo lugar para vivir; los que no lo lograban, intentaban regresar de todas las formas posibles.  <\/p><p>Pero volvamos a nuestros h\u00e9roes. Como escribimos antes, Yechiel, junto con su hijo Eliezer Abraham, tuvo que huir de Ulm. Su familia tuvo suerte: llegaron a la ciudad m\u00e1s cercana, la suaba G\u00fcnzburg, y pudieron establecerse all\u00ed.  <\/p><p>Por cierto, poco despu\u00e9s se produjo un percance casi legal en la vida de los jud\u00edos de G\u00fcnzburgo. Las luchas y disputas sacudieron tanto a la comunidad local que los jud\u00edos apelaron al emperador Maximiliano II con una petici\u00f3n bastante inusual. Ped\u00edan que se reconociera oficialmente como rabino a Isaac ha-Levi, quien, de hecho, ya llevaba 30 a\u00f1os en el cargo. Pero, seg\u00fan la profunda convicci\u00f3n de los jud\u00edos locales, tal y como atestiguan los enciclopedistas, \u00abel rabino no pod\u00eda resolver las disputas que hab\u00edan surgido en aquel momento entre los miembros de la comunidad hasta que no fuera reconocido oficialmente\u00bb.   <\/p><p>Fue en esta \u00e9poca cuando el influyente y acaudalado Shimon ben Eliezer Ginzburg alcanz\u00f3 prominencia en la comunidad. Shimon era hijo del mismo Eliezer Abraham que se hab\u00eda visto obligado a abandonar la inh\u00f3spita Ulm. Shimon, que compart\u00eda el apodo de su padre, Ulm-G\u00fcnzburg, naci\u00f3 ya en G\u00fcnzburg en 1506. No s\u00f3lo era talmudista y figura p\u00fablica, sino que tambi\u00e9n ten\u00eda evidentes dotes comerciales. Su abanico de intereses comerciales era extremadamente amplio, realiz\u00f3 transacciones en muchos principados de Alemania, por no mencionar que viaj\u00f3 por toda Polonia por asuntos comerciales. En G\u00fcnzburg construy\u00f3 una sinagoga y abri\u00f3 un cementerio. Puede decirse que Shimon ben Eliezer era en aquella \u00e9poca el residente m\u00e1s c\u00e9lebre de la comunidad jud\u00eda de esa ciudad. En la segunda mitad de su vida, Shimon se traslad\u00f3 a B\u00fcrgau, donde tambi\u00e9n hizo mucho por la comunidad de all\u00ed. Muri\u00f3 en B\u00fcrgau en 1585. Shimon ben Eliezer G\u00fcnzburg es el antepasado directo de la mayor\u00eda de los Ginzburg modernos, incluidos los famosos barones rusos Ginzburg.         <\/p><p>El hijo de Shimon, Asher Aharon Lemel Ulma-Ginzburg vivi\u00f3 hasta el siglo XVII y muri\u00f3 en 1606 en un principado alem\u00e1n. El hijo de Asher &#8211; Yaakov Ulma-Ginzburg fue el rabino y maestro del famoso Rav Lipman Heller. Yaakov sobrevivi\u00f3 a su padre s\u00f3lo diez a\u00f1os y muri\u00f3 en 1616. Tambi\u00e9n tuvo un hijo, al que puso el nombre de su famoso abuelo, Shimon (Scholtes). Isaac (Isaac), el hijo de Shimon, naci\u00f3 en Worms, donde se cas\u00f3 (la tradici\u00f3n familiar ha conservado el nombre de su esposa, Golda). La familia se traslad\u00f3 pronto a Polonia. Vivieron en Vilna y en Pinsk. Generaciones enteras de esta familia se convirtieron en rabinos famosos.       <\/p><p>Naftali Hertz, descendiente de Shimon de G\u00fcnzburg, fue el primero de la familia en seguir los pasos de su antepasado tras un intervalo de doscientos a\u00f1os y dedicarse a los negocios. Y su hijo, el rabino Gabriel Yaakov de Vitebsk, se convirti\u00f3 en el padre del famoso bar\u00f3n jud\u00edo Joseph Yosel (Yevzel) Gintsburg. Comenzaremos nuestra narraci\u00f3n posterior con \u00e9l y su familia.  <\/p><p>As\u00ed, tenemos ante nosotros a una de las familias jud\u00edas m\u00e1s famosas de la Rusia de la \u00e9poca: la familia del bar\u00f3n Gintsburg. Los miembros de esta familia no s\u00f3lo pose\u00edan, como cre\u00edan los contempor\u00e1neos, una \u00abriqueza fabulosa\u00bb, sino que eran, como dice hoy en d\u00eda la prensa rusa, figuras de \u00abculto\u00bb para la inmensa mayor\u00eda de los jud\u00edos del Imperio ruso. En efecto, su enorme riqueza financiera, sus conexiones con la corte del zar y con el capital bancario internacional, as\u00ed como su generos\u00edsima filantrop\u00eda y su mecenazgo de las artes, constitu\u00edan una \u00abpar\u00e1bola en la lengua\u00bb y crearon un terreno propicio para la aparici\u00f3n de todo tipo de leyendas y an\u00e9cdotas hist\u00f3ricas.  <\/p><p>  El investigador V. Shtylveld cita en su art\u00edculo sobre esta familia una an\u00e9cdota ir\u00f3nica y triste sobre la relatividad incluso de la vida jud\u00eda m\u00e1s pr\u00f3spera en Rusia. \u00abEl bar\u00f3n Ginzburg, un famoso fil\u00e1ntropo que construy\u00f3 una sinagoga en San Petersburgo, viaj\u00f3 una vez en carruaje con Nicol\u00e1s II. Un hombre que pasaba por all\u00ed no pudo contener su sorpresa: all\u00ed hab\u00eda un jud\u00edo viajando con el zar. El hombre fue sorprendido y quiso llevarlo a la c\u00e1rcel por insultar al bar\u00f3n. Pero Ginzburg pidi\u00f3 que no castigaran al plebeyo e incluso le dio una pieza de oro. \u00bfPor qu\u00e9? Por no dejar que el bar\u00f3n olvidara que era jud\u00edo\u00bb.  <\/p><p>Esta an\u00e9cdota hist\u00f3rica es bastante indicativa para la Rusia de aquella \u00e9poca, aunque es probable que para Rusia (que, sin embargo, no es una excepci\u00f3n odiosa en este caso) lo sea para todas las \u00e9pocas y bajo cualquier poder. El capital financiero jud\u00edo siempre ha sido considerado (desde la Rusia zarista hasta la Rusia moderna) por la inmensa mayor\u00eda de la poblaci\u00f3n como \u00abrobado\u00bb, \u00abolig\u00e1rquico\u00bb o, en una versi\u00f3n suavizada, \u00abobtenido injustamente\u00bb, y en cualquier caso, seg\u00fan la creencia de la mayor\u00eda del pueblo, se utilizaba principalmente para el \u00abhagal jud\u00edo\u00bb, la \u00abconspiraci\u00f3n mundial\u00bb o \u00abcon el prop\u00f3sito de seguir robando al pueblo ruso\u00bb. Esta opini\u00f3n generalizada y propagada ha permanecido pr\u00e1cticamente inalterada durante los \u00faltimos dos siglos y medio, es decir, desde que los financieros jud\u00edos o, como se dice ahora en Rusia, los \u00aboligarcas\u00bb, se dieron a conocer en Rusia.  <\/p><p>En este sentido, a pesar de numerosos cataclismos hist\u00f3ricos, revoluciones y cambios cardinales de formaciones sociales enteras, la actitud de la mayor\u00eda del pueblo ruso hacia los capitalistas jud\u00edos, con el antisemitismo tradicional superpuesto, no ha sufrido cambios significativos. Al mismo tiempo, la opini\u00f3n sobre los multimillonarios, o como muchos los llamaban semidespectivamente &#8211; \u00abnuevos ricos\u00bb en el propio entorno jud\u00edo nunca ha sido un\u00edvoca. La parte pobre de la comunidad jud\u00eda, en su mayor\u00eda, los adoraba, se sent\u00eda orgullosa de ellos y contaba con su apoyo, lo cual, sin embargo, no era descabellado, ya que muchos de los ricos intentaban apoyar econ\u00f3micamente a su comunidad de todas las formas posibles. La intelectualidad jud\u00eda, por otro lado, aunque rend\u00eda homenaje a sus talentos comerciales, no s\u00f3lo no se inclinaba a idolatrarlos, sino que los trataba con mucha aversi\u00f3n, a menudo condenando y rechazando por completo su \u00abadoraci\u00f3n del becerro de oro\u00bb.   <\/p><p>Merece la pena citar un art\u00edculo de A. Lokshin dedicado a esta cuesti\u00f3n: \u00abLa reci\u00e9n nacida intelectualidad jud\u00eda de San Petersburgo era a menudo muy cr\u00edtica con sus compa\u00f1eros de tribu, los ricos. La irritaban al menos por su franco deseo de distanciarse de sus correligionarios pobres&#8230; Si el repentino ascenso de la \u00e9lite jud\u00eda de San Petersburgo era un misterio para los jud\u00edos de l\u00ednea, tambi\u00e9n se ve\u00eda como algo amenazador para los no jud\u00edos. Si los no jud\u00edos estaban dispuestos a explicar cualquier \u00e9xito jud\u00edo por la ayuda del Kagal, entonces (el h\u00e9roe de la novela de Levanda, un cierto nuevo rico jud\u00edo) insist\u00eda en las razones de la influencia comercial jud\u00eda: \u00ab&#8230;Tomamos \u00fanica y exclusivamente por nuestro temperamento, nuestro ascetismo y nuestra intensa e incansable actividad&#8230;\u00bb. En una \u00e9poca en la que los hombres de negocios de otras nacionalidades &#8211; ante todo gente corriente con pasiones y lujurias humanas, epic\u00fareos, fascinados y distra\u00eddos de los negocios que son la m\u00fasica, que son la pintura, que son las mujeres, los caballos, los perros, la caza, los deportes, el juego, nosotros, los hombres de negocios-jud\u00edos, no nos distraemos ni nos entretenemos con nada que no est\u00e9 directamente relacionado con el negocio\u00bb. En el final de esta novela de L. Levanda, el protagonista, reflexionando sobre las peculiaridades de la asimilaci\u00f3n jud\u00eda, esboza sus l\u00edmites: \u00ab&#8230;Seremos rusos, pero la pereza rusa, la despreocupaci\u00f3n rusa, el zabubismo, la impasibilidad y lo que se llama la amplia naturaleza rusa siempre nos seguir\u00e1n siendo ajenos\u00bb. <\/p><p>Por supuesto, teniendo en cuenta a los mayores financieros jud\u00edos de Rusia en el siglo XIX y de Rusia en los siglos XX y XXI, el investigador tiene sin duda muchas asociaciones y analog\u00edas. En ambas \u00e9pocas vemos la misma explosi\u00f3n capitalista desenfrenada, la misma excitaci\u00f3n, las mismas ambiciones, las mismas aspiraciones. S\u00f3lo han cambiado el escenario y el tiempo, y la propia acci\u00f3n se ha trasladado de la antigua capital del Estado ruso de San Petersburgo a la actual capital de la Federaci\u00f3n Rusa: Mosc\u00fa. Perm\u00edtanos una cita m\u00e1s extensa del art\u00edculo \u00abVentana a Rusia: los jud\u00edos en San Petersburgo\u00bb de A. Lokshin. \u00abNinguna otra comunidad jud\u00eda de Rusia contaba con gente tan rica y pr\u00f3spera. Petersburgo se convirti\u00f3 en poco tiempo en el lugar elegido por la plutocracia ruso-jud\u00eda; muchos de sus representantes desempe\u00f1aron un papel importante en las nacientes esferas de la banca privada, la especulaci\u00f3n burs\u00e1til y la construcci\u00f3n de ferrocarriles. Polina Vengerova, jud\u00eda residente en la capital y autora de las famosas memorias \u00abRecuerdos de una abuela\u00bb, probablemente no exager\u00f3 demasiado cuando escribi\u00f3 sobre la \u00e9poca de los a\u00f1os 60-70: \u00abNunca antes los jud\u00edos de San Petersburgo hab\u00edan llevado una vida tan pr\u00f3spera, ya que las finanzas de la capital estaban en parte en sus manos\u00bb. Un peri\u00f3dico jud\u00edo de San Petersburgo llam\u00f3 a la d\u00e9cada de 1860 \u00abla d\u00e9cada febril de la empresa privada\u00bb. Seg\u00fan un jud\u00edo, antiguo empleado de banca, \u00abse estaba produciendo una metamorfosis completa en los nativos de las zonas pobladas: el comerciante se convirti\u00f3 en banquero, el contratista &#8211; en empresario de altos vuelos, y sus empleados &#8211; en dandis metropolitanos. Muchos cuervos se pusieron plumas de pavo real; los advenedizos de Balta y Konotop se consideraron en poco tiempo &#8216;arist\u00f3cratas&#8217; y se rieron de los &#8216;provincianos'\u00bb. Este mordaz testimonio capta con precisi\u00f3n el papel cambiante de la \u00e9lite financiera jud\u00eda durante el periodo de r\u00e1pido desarrollo del capitalismo en Rusia. Los financieros jud\u00edos, al menos los que viv\u00edan en San Petersburgo, hicieron fortuna principalmente en el \u00e1mbito de las empresas estatales y mantuvieron estrechos v\u00ednculos con los funcionarios del gobierno.        <\/p><p>La casa bancaria Ginzburg es el ejemplo m\u00e1s llamativo de ello. Grandes comerciantes de vino, proveedores de alimentos y uniformes para el ej\u00e9rcito ruso durante la guerra de Crimea, Euzel Ginzburg y su hijo Horace establecieron su propio banco en San Petersburgo en 1859; posteriormente proporcionaron al Estado enormes pr\u00e9stamos para muchas necesidades gubernamentales, incluidas las relacionadas con la guerra ruso-turca de 1877-1878. Los hermanos Polyakov (Samuel, Yakov, Lazar) financiaron la construcci\u00f3n de ferrocarriles y como resultado fueron introducidos por Alejandro II en la nobleza hereditaria, lo que constitu\u00eda una gran rareza para los jud\u00edos. En 1871, Abraham Zak, que anteriormente hab\u00eda trabajado con los Gintsburg, se convirti\u00f3 en director del Banco de Contabilidad y Pr\u00e9stamos de San Petersburgo, uno de los mayores del imperio. El banco era propiedad del magnate jud\u00edo-polaco Leopold Kronenberg. Muchos otros pueden a\u00f1adirse a esta lista&#8230;\u00bb.     <\/p><p>Entonces, \u00bfqui\u00e9nes son estos famosos, mencionados en casi todos los art\u00edculos sobre el tema jud\u00edo sobre la Rusia del siglo XIX y famosos en su \u00e9poca por toda Europa \u00abbanqueros y defensores de los jud\u00edos\u00bb Barones Ginzburgs?<\/p><p>Empecemos por el principio. En 1812, en el momento en que el peque\u00f1o Joseph Yosel (en la pronunciaci\u00f3n rusa &#8211; Evzel u Osip) Gintsburg naci\u00f3 en la ciudad de Vitebsk en la familia del rabino Gabriel Yaakov Gintsburg y su esposa Leah Rashkis, nadie podr\u00eda haber adivinado que este infante estaba destinado por el destino a desempe\u00f1ar un papel tan destacado en la historia de los jud\u00edos del Estado ruso. Como recordar\u00e1 el lector, era una \u00e9poca turbulenta: fue entonces cuando Napole\u00f3n dirigi\u00f3 su famosa campa\u00f1a rusa, que comenz\u00f3 con tanto \u00e9xito y pronto termin\u00f3 en una derrota tan tr\u00e1gica. Como se\u00f1ala la Enciclopedia de Brockhaus y Ephron, Yosel recibi\u00f3 de ni\u00f1o una educaci\u00f3n jud\u00eda tradicional, y nadie pudo notar en \u00e9l ninguna capacidad extraordinaria en aquella \u00e9poca.   <\/p><p>A los 16 a\u00f1os (lo que era normal entonces) se cas\u00f3 con Rasa (en pronunciaci\u00f3n rusa &#8211; Rosa) Dynina. No eligi\u00f3 un camino espiritual, no se hizo rabino como su padre, sino que prefiri\u00f3 un destino completamente distinto. Comenz\u00f3 su carrera juvenil de forma bastante modesta y tradicional para aquellos tiempos: consigui\u00f3 un trabajo (gracias a las conexiones de su padre) como cajero de un gran terrateniente que se dedicaba a los sobornos. El payoff, seg\u00fan las enciclopedias, es \u00abun derecho exclusivo, presentado por el Estado a cambio de un cierto canon a particulares (payoffs), para recaudar cualquier impuesto o vender ciertos tipos de bienes (sal, vino, etc.)\u00bb. Muchos investigadores creen que el capitalismo en Rusia comenz\u00f3 realmente con los payoffs, o m\u00e1s bien con los payoffsmen, que fueron los primeros en descubrir este \u00abKlondike\u00bb de los negocios de la \u00e9poca.    <\/p><p>Cabe se\u00f1alar que Josel, aparte de muchas otras cualidades necesarias para el \u00e9xito de la actividad comercial, pose\u00eda una cualidad m\u00e1s, quiz\u00e1 una de las m\u00e1s valiosas en este campo: una intuici\u00f3n \u00fanica, que le distingu\u00eda de muchos aspirantes a comerciantes. Fue esta cualidad la que le permitir\u00eda convertirse en el futuro en uno de los hombres m\u00e1s ricos del pa\u00eds. Muy pronto se dio cuenta, por ejemplo, de que los pagos, esta \u00e1rea de actividad, conllevaban un enorme potencial financiero. Pronto empez\u00f3 a comprar por su cuenta, y con tanto \u00e9xito que a los 28 a\u00f1os no s\u00f3lo se hab\u00eda convertido en propietario de un s\u00f3lido capital, sino que tambi\u00e9n se hizo famoso como uno de los mejores compradores. Era propietario de compras en varias de las mayores provincias rusas &#8211; en las provincias de Kiev y Volyn. As\u00ed, habiendo ganado un capital decente, en 1833 ya recib\u00eda el t\u00edtulo de comerciante de Vitebsk del 1er gremio.     <\/p><p>Al mismo tiempo, procuraba pasar el mayor tiempo posible en San Petersburgo. El investigador V. Shtylveld escribe: \u00abAntes que otros comprendi\u00f3 la inevitabilidad de la capitalizaci\u00f3n de Rusia, la inevitabilidad de la revoluci\u00f3n, llevada a cabo desde arriba, por el propio monarca. No s\u00f3lo \u00e9l, por supuesto, se dio cuenta de la utilidad para los hombres de negocios de los v\u00ednculos con los c\u00edrculos pol\u00edticos &#8211; pero fue casi el primero en comprender que la apuesta no deb\u00eda hacerse por los bur\u00f3cratas dignatarios, ni por los c\u00edrculos liberales de la corte, enlistados bajo Nicol\u00e1s en desgracia. Por ello, el joven Gintsburg se apresur\u00f3 a establecer lazos comerciales y financieros con el pr\u00edncipe Alejandro de Hesse, hermano de la esposa del heredero al trono y general del ej\u00e9rcito ruso. Cuando Alejandro II subi\u00f3 al trono, sus grandes reformas se inspiraron en gran medida en la esposa del zar, Mar\u00eda de Hesse, y el favorito de su hermano, Eusel Ginzburg, cay\u00f3 inmediatamente en el c\u00edrculo de aquellos hombres de negocios que, como se dice hoy en d\u00eda, empezaron a crear la infraestructura de la nov\u00edsima econom\u00eda\u00bb. <\/p><p>En una actividad financiera tan turbulenta, por supuesto, no pod\u00eda prescindir de interminables intrigas de competidores, envidias e incluso simples denuncias. El historiador O. Budnitsky da un ejemplo de tal situaci\u00f3n. \u00abSu r\u00e1pido enriquecimiento (de Gintsburg) provoc\u00f3 una denuncia sobre \u00e9l, que lleg\u00f3 hasta el propio emperador. El informador an\u00f3nimo afirm\u00f3 que Gintsburg gan\u00f3 unos 8 millones de rublos en plata gracias a los sobornos. \u00abDesde que existe Rusia\u00bb, escribi\u00f3 el ansioso \u00abpatriota\u00bb, \u00abno ha habido ning\u00fan jud\u00edo que haya tenido una fortuna de un mill\u00f3n de rublos\u00bb. Los tiempos, sin embargo, eran liberales y reformadores. Alejandro II \u00abgarabate\u00f3\u00bb en la denuncia: \u00abD\u00e9jelo sin consecuencias\u00bb. Las conexiones de Evzel en la corte eran demasiado fuertes en aquella \u00e9poca.     <\/p><p>Sin embargo, aparte de sus fuertes conexiones palaciegas, Euzel se distingu\u00eda por otra cualidad que no siempre era caracter\u00edstica de los nuevos ricos. Esta cualidad, por banal o parad\u00f3jica que pueda sonar en el mundo de los negocios, es la honradez, o como les gustaba decirlo entonces: la \u00abfiabilidad\u00bb. De hecho, el principio fundamental de la actividad comercial de Evzel en Rusia, y pronto en Europa, no era un lema corriente para la Rusia de la \u00e9poca (y, sin embargo, probablemente, y no s\u00f3lo eso) &#8211; \u00abdecencia\u00bb. No era s\u00f3lo un lema: la palabra de Ginzburg en los c\u00edrculos comerciales de la \u00e9poca equival\u00eda a un pagar\u00e9. Muchos de sus contempor\u00e1neos escribieron sobre ello. Fue esta cualidad o este principio lo que m\u00e1s tarde le dio el ciento por uno y le permiti\u00f3 crear uno de los imperios financieros m\u00e1s exitosos del Imperio Ruso.     <\/p><p>Como se\u00f1ala O. Budnitsky \u00abPor los servicios prestados al gobierno, Euzel Gintsburg, junto con su mujer y sus hijos, obtuvo la ciudadan\u00eda de honor hereditaria por iniciativa del ministro de Finanzas F. P. Vronchenko en 1849. Durante la guerra de Crimea, Euzel Gintsburg organiz\u00f3 una compra de vino en la sitiada Sebastopol. Seg\u00fan el abogado de Gintsburg, abandon\u00f3 la ciudad \u00abuno de los \u00faltimos, casi simult\u00e1neamente con el comandante de la guarnici\u00f3n\u00bb.  <\/p><p>As\u00ed, a finales de la d\u00e9cada de 1850 Yosel, y ahora por fin &#8211; Eusel Ginzburg, se convierte en comerciante del primer gremio de San Petersburgo, y en 1874 se le concede el t\u00edtulo de consejero comercial. En este caso, su asombrosa intuici\u00f3n no s\u00f3lo no le falla, sino que por el contrario se agudiza a\u00fan m\u00e1s. Como se\u00f1ala el mismo Shtylveld &#8211; \u00abAntes que otros capitalistas de la \u00e9poca de Nikolaev, nuestro personaje comprendi\u00f3 la condena hist\u00f3rica del comercio de pago\u00bb. En 1863, dos a\u00f1os despu\u00e9s de la abolici\u00f3n de la servidumbre, los pagos ser\u00e1n anulados en Rusia y muchas esferas de actividad, que se dedicaban a los pagos quedar\u00e1n en manos del Estado, es decir, ser\u00e1n simplemente monopolizadas. Un gran n\u00famero de comerciantes, que se hab\u00edan enriquecido con sobornos como la levadura, quebrar\u00edan inmediatamente (y entre ellos muchos jud\u00edos). Cuatro a\u00f1os antes de este acontecimiento, en 1859, Evzel Ginzburg cambi\u00f3 bruscamente el rumbo de sus actividades financieras: cre\u00f3 una casa bancaria en San Petersburgo, que pronto se convirti\u00f3 en uno de los bancos m\u00e1s importantes de la capital.     <\/p><p>Como se\u00f1alan Brockhaus y Efron, Euzel Gintsburg se convierte en esa \u00e9poca no s\u00f3lo en uno de los mejores financieros de San Petersburgo, sino de toda Rusia. Muestra una fant\u00e1stica actividad en el desarrollo de las llamadas \u00abinstituciones de cr\u00e9dito\u00bb, o simplemente bancos: se convierte en uno de los fundadores del primer banco privado de Rusia, a saber, el Banco Comercial Privado de Kiev. A \u00e9ste le sigui\u00f3 la creaci\u00f3n del Banco Contable en Odessa y, posteriormente, del Banco Contable y de Pr\u00e9stamos en San Petersburgo. A trav\u00e9s de su casa bancaria de San Petersburgo se establecieron v\u00ednculos fiables entre las instituciones financieras de Europa Occidental y Rusia. Sus bancos, en el pleno sentido de estas palabras, podr\u00edan denominarse \u00abventanas financieras a Europa\u00bb. Adem\u00e1s, la casa bancaria de Ginzburg particip\u00f3 activamente en la grandiosa financiaci\u00f3n de las empresas ferroviarias (que surgieron en aquella \u00e9poca con extrema rapidez y seg\u00fan los contempor\u00e1neos \u00abcrecieron como setas despu\u00e9s de la lluvia\u00bb).     <\/p><p>Por cierto, durante toda su vida Euzel Ginzburg mantuvo v\u00ednculos con el pr\u00edncipe Alejandro de Hesse. \u00c9ste concedi\u00f3 a Eusel el t\u00edtulo de bar\u00f3n, t\u00edtulo que \u00abcon el m\u00e1s alto permiso\u00bb (y para aceptar el t\u00edtulo de nobleza incluso extranjero, era necesario obtener el permiso del zar ruso) se le permiti\u00f3 utilizar en Rusia de forma hereditaria. <\/p><p>Al mismo tiempo, si nos adentramos en la literatura hist\u00f3rica y de memorias de la \u00e9poca, cualquier menci\u00f3n de Euzel Ginzburg, as\u00ed como de sus hijos, que se encuentre en la historia jud\u00eda y rusa, siempre est\u00e1 relacionada no s\u00f3lo con sus t\u00edtulos, rangos, premios y sumas astron\u00f3micas de su fortuna, sino, incluso principalmente, con sus famosas actividades caritativas, as\u00ed como con su papel de \u00abbenefactor y defensor de la juder\u00eda rusa\u00bb. Y a pesar de que en la \u00e9poca en que su imperio financiero alcanzaba una escala enorme, el propio Euzel prefer\u00eda no vivir en Rusia, sino en Par\u00eds, pero, como escribe G. Sliozberg, que estuvo cerca de \u00e9l, \u00abcada estancia en San Petersburgo iba acompa\u00f1ada de alguna petici\u00f3n relativa a los derechos de los jud\u00edos\u00bb. <\/p><p>Como escribe en particular otro investigador de la historia de la familia Hintzburg, V. Shtylveld, \u00abse sabe que en el monumento a Bohdan Khmelnitsky en Kiev deb\u00edan estar grabadas unas palabras de Shevchenko: \u00abHai vivve Ukraina sin un jud\u00edo y sin una alta burgues\u00eda\u00bb. Y bajo los cascos del caballo se proyectaba la figura de un jud\u00edo. El bar\u00f3n Ginzburg consigui\u00f3 que se cambiara el proyecto por una buena suma de dinero\u00bb. \u00abDespu\u00e9s de la guerra de Crimea\u00bb, prosigue Sliozberg, \u00aba partir de 1858, Ginzburg hizo insistentes peticiones \u03bf conceder a los comerciantes jud\u00edos el derecho de residencia permanente fuera de la l\u00ednea de asentamiento. Para entonces sus peticiones en nombre de los jud\u00edos se hab\u00edan convertido en algo habitual: se convirti\u00f3 en \u00abel representante oficial de los jud\u00edos en la capital\u00bb. Gracias a sus intensos esfuerzos, el proyecto \u03bf que conced\u00eda a los comerciantes el derecho de residencia universal se plasm\u00f3 en una ley el 15 de marzo de 1859. Seg\u00fan Budnitsky: \u00abEn agosto de 1862, Evzel Ginzburg present\u00f3 una nota al bar\u00f3n Modest Korff, presidente del Comit\u00e9 Jud\u00edo del gobierno, en la que llamaba la atenci\u00f3n sobre los siguientes puntos de la legislaci\u00f3n relativa a los jud\u00edos, que contradec\u00edan la l\u00f3gica de la \u00absana econom\u00eda pol\u00edtica\u00bb: la restricci\u00f3n del derecho de residencia; la restricci\u00f3n en la producci\u00f3n del comercio y la adquisici\u00f3n de bienes ra\u00edces; la impotencia de los jud\u00edos que hab\u00edan recibido una educaci\u00f3n.\u00bb     <\/p><p>\u00abEn general, desde 1862\u00bb, atestigua la Enciclopedia Jud\u00eda, \u00abha presentado una serie de informes, demostrando la necesidad de desarrollar la educaci\u00f3n entre los jud\u00edos, de conceder derechos a las personas que se hab\u00edan graduado en las escuelas secundarias, y tambi\u00e9n a los artesanos. En 1863 fund\u00f3 la \u00abSociedad para la Difusi\u00f3n de la Ilustraci\u00f3n entre los Jud\u00edos\u00bb, que cost\u00f3 enormes esfuerzos; la actividad de esta sociedad se desarroll\u00f3 casi exclusivamente con los fondos de Gintsburg\u00bb. Bajo la influencia de los Ginzburg, se form\u00f3 la \u00abSociedad para la Formaci\u00f3n de los Jud\u00edos en el Trabajo Artesanal y Agr\u00edcola\u00bb (ORT), donde la gente pod\u00eda conseguir profesiones demandadas. (Por cierto, se trata de la misma ORT que se difundi\u00f3 en Israel, donde a\u00fan existe, y que tras la perestroika rusa se restableci\u00f3 en Rusia). Los Ginzburgo estaban especialmente atentos al talento. Ayudaron a \u00absalir al mundo\u00bb al futuro famoso escultor M. Antokolsky, a los brillantes violinistas Y. Heifetz y E. Tsimbalist. Tsimbalist. Marc Chagall y Samuel Marshak, en su primera juventud, tampoco se libraron de la atenci\u00f3n de la familia Gintsburg. Euzel Ginzburg, y m\u00e1s tarde su hijo, contaban con todo un equipo de asistentes que respond\u00edan a las llamadas personales de personas en apuros.       <\/p><p>La filantrop\u00eda de los Ginzburg no s\u00f3lo se extend\u00eda a los jud\u00edos. Pocos recuerdan que el mayor de los Gintsburg fue uno de los fundadores de la Sociedad Arqueol\u00f3gica de San Petersburgo, y el menor, Horace, de los Cursos Superiores Femeninos, que m\u00e1s tarde se llamaron \u00abBestuzhevsky\u00bb. El bar\u00f3n Evzel Ginzburg dej\u00f3 un legado, que se cuenta desde hace tiempo en la \u00abl\u00ednea sedentaria\u00bb: 50.000 dessiatins de tierra en la provincia de Taurida &#8211; para jud\u00edos pobres que quieran campesinizarse\u00bb. Brockhaus y Efron informan de que \u00absu preocupaci\u00f3n \u03bf el desarrollo del trabajo agr\u00edcola entre los jud\u00edos se expres\u00f3, entre otras cosas, en el establecimiento por su parte de un premio para los mejores agricultores jud\u00edos. Y en 1857 hab\u00eda establecido una beca para los jud\u00edos que estudiaban en la Academia Imperial de Medicina y Cirug\u00eda. A principios de los a\u00f1os setenta, cuando comenzaron a elaborarse propuestas para la introducci\u00f3n del servicio militar obligatorio general, Euzel, junto con su hijo Horace, se mostr\u00f3 especialmente en\u00e9rgico en su labor, que tuvo como resultado la equiparaci\u00f3n de los jud\u00edos con el resto de la poblaci\u00f3n en lo que respecta al servicio militar obligatorio. Por iniciativa suya se construy\u00f3 la famosa Sinagoga Coral, sobre cuya construcci\u00f3n se rompieron tantas lanzas verbales durante varios a\u00f1os en la capital del Estado ruso, y que sigue siendo la principal sinagoga de los jud\u00edos de la antigua Leningrado y actual San Petersburgo. Los famosos bancos de los barones Gintsburg siguen all\u00ed en primera fila.       <\/p><p>En los \u00faltimos a\u00f1os de su vida, Euzel apenas vino a Rusia, viviendo en Par\u00eds. All\u00ed falleci\u00f3 en 1878. Leg\u00f3 toda su enorme fortuna, incluida la casa bancaria \u00abI. E. Ginzburg\u00bb (y su \u00abcasa bancaria\u00bb en aquella \u00e9poca era como se dice ahora \u00abun holding diversificado\u00bb o \u00abun gigantesco grupo financiero\u00bb) a sus tres hijos: el ya mencionado Naftali Hertz (Horacio), Uri (Ur\u00edas) y Salom\u00f3n-David. La herencia estaba condicionada por dos puntos famosos &#8211; la conservaci\u00f3n de la fe de sus padres (algo que no todos los \u00aboligarcas\u00bb jud\u00edos del siglo XIX se atrevieron a hacer, al igual que los del siglo XX) y la conservaci\u00f3n de la ciudadan\u00eda rusa.     <\/p><p>Eusel Ginzburg tuvo cinco hijos. El a\u00f1o 1878 fue tr\u00e1gico para la familia Ginzburg. Los dos hijos mayores, Alexander Ziskind y Mathilde, murieron en Par\u00eds el mismo a\u00f1o que su padre. El m\u00e1s famoso seguidor y continuador de la obra de su padre tras su muerte fue su hijo &#8211; Naftali Herz (o como se le llamaba en ruso &#8211; Horace) Ginzburg. Fue el asociado y compa\u00f1ero m\u00e1s activo de su padre.    <\/p><p>Naci\u00f3 en Zvenigorodka, Ucrania, en 1833, era el segundo hijo (dos a\u00f1os menor que su hermano mayor Alexander), recibi\u00f3 una educaci\u00f3n casera (que inclu\u00eda hebreo, Tor\u00e1 y Talmud) y se cas\u00f3 con su prima Hana Rosenberg a la edad de 20 a\u00f1os. Siendo a\u00fan veintea\u00f1ero, Hertz se convirti\u00f3 en el ayudante m\u00e1s cercano de su padre en todos sus empe\u00f1os comerciales y sociales. Pronto pr\u00e1cticamente se hizo cargo de su casa bancaria, tomando nuevos rumbos en el desarrollo de los negocios. Se cree que fue gracias a Hertz que las actividades comerciales de los Ginzburgo se reorientaron hacia el nuevo \u00abKlondike\u00bb ruso: la miner\u00eda de oro en Siberia. En esta \u00e9poca, desde principios de los a\u00f1os 70 del siglo XIX en Rusia, en t\u00e9rminos americanos, comenz\u00f3 la \u00abfiebre del oro\u00bb. Pero en Rusia ocurri\u00f3 de forma diferente que en Am\u00e9rica &#8211; grandes empresas, casas bancarias y comerciantes \u00abmillonarios\u00bb se dedicaron a la miner\u00eda del oro, invirtiendo en esta zona enormes capitales y creando toda una nueva rama de negocio ramificada y extremadamente rentable &#8211; la industria del oro. Este auge del oro ruso de finales del siglo XIX fue extremadamente similar en su volumen y emoci\u00f3n al auge del petr\u00f3leo, la metalurgia y el aluminio de Rusia a finales del siglo XX, cuando las propiedades que hab\u00edan estado en manos del Estado durante setenta a\u00f1os empezaron a pasar a manos privadas.        <\/p><p>Horace, como su padre en su momento, vio con el tiempo todo el potencial financiero que se abr\u00eda en esta zona. Al cabo de un tiempo, la casa bancaria de los Ginzburg ya se hab\u00eda convertido en fundadora de una docena de minas. La lista de minas y empresas propiedad de los Gintsburg en aquella \u00e9poca ocupa m\u00e1s de media p\u00e1gina. Como escribe el historiador \u00aberan los Gintsburg quienes a principios de siglo encabezaban la lista de las personas m\u00e1s influyentes de la industria aur\u00edfera rusa\u00bb.   <\/p><p>Pero la miner\u00eda del oro no era ni mucho menos el \u00fanico \u00e1mbito de la actividad comercial de Horacio. Como se\u00f1ala Smetanin \u00abLos Ginzburgo ten\u00edan f\u00e1bricas de az\u00facar y grandes propiedades de tierra en las provincias de Kiev y Podolsk. Sus fincas hac\u00edan un uso extensivo de la maquinaria, los fertilizantes minerales y las rotaciones cient\u00edficas de cultivos. Tambi\u00e9n ten\u00edan propiedades de tierra en Crimea y las arrendaban. Pero en 1892 la casa bancaria ces\u00f3 sus operaciones. Esto no se consider\u00f3 quiebra, ya que pagaron a sus acreedores. Durante alg\u00fan tiempo despu\u00e9s, la familia sigui\u00f3 manteniendo una posici\u00f3n en la industria del oro. Pero tras el colapso de la casa bancaria se vieron obligados a entregar las minas a los brit\u00e1nicos\u00bb. Efectivamente, el negocio de los Ginzburg a finales del siglo XIX sufri\u00f3 un fuerte golpe financiero. As\u00ed describe esta situaci\u00f3n otro investigador, O. Budnitsky &#8211; \u00abEn 1892, en el momento de una fuerte ca\u00edda del rublo ruso, el Ministerio de Finanzas no ayud\u00f3 a la casa bancaria, cuyos fondos estaban invertidos en valores rusos &#8211; los Gintsburg se vieron obligados a abandonar las actividades bancarias y se concentraron en la industria del oro\u00bb. Sin embargo, incluso tras el cese de las operaciones activas de la casa bancaria y la reducci\u00f3n de los ingresos procedentes de la extracci\u00f3n de oro, la fortuna de los Gintsburgo se estim\u00f3 en su momento como una de las mayores fortunas financieras de Rusia.   <\/p><p>Al mismo tiempo, Horacio, al igual que su padre antes que \u00e9l, independientemente del \u00e9xito variable o constante de sus asuntos financieros, nunca ces\u00f3 en sus famosas actividades caritativas y sociales. Durante cuarenta a\u00f1os dirigi\u00f3 oficialmente la comunidad jud\u00eda de San Petersburgo en la capital (aunque de hecho dirigi\u00f3 toda la comunidad jud\u00eda de Rusia). La ya existente ORT en su rese\u00f1a hist\u00f3rica informa &#8211; \u00abGintsburg se mostr\u00f3 como un mecenas de las artes y un gran benefactor. En su casa se reun\u00edan los mejores representantes de los c\u00edrculos cient\u00edficos y del mundo del arte. M. M. Stasiulevich, K. D. Kaverin, V. D. Spasovich, profesores que abandonaron la universidad tras el levantamiento polaco de 1863, visitaron su casa. El famoso cr\u00edtico literario y musical V. V. Stasov y el c\u00e9lebre escritor I. S. Turgu\u00e9niev estuvieron cerca de Gintsburgo; M. E. Saltykov-Shchedrin, I. A. Goncharov, I. M. Kramskoi, V. M. Soloviev, A. G. Rubinstein visitaron su casa. El escultor M. Antokolsky gracias a Gintsburg consigui\u00f3 una educaci\u00f3n acad\u00e9mica. Es dif\u00edcil nombrar todos los casos en los que actu\u00f3 como intercesor, todas las empresas jud\u00edas que financi\u00f3. Con su dinero se publicaron libros en defensa de los jud\u00edos. Fue presidente de la JCE, aunque no aprobaba la emigraci\u00f3n, presidente de la Sociedad para la Ilustraci\u00f3n de los Jud\u00edos. Su esposa, Anna Hesselevna, estableci\u00f3 un orfanato en la isla Vasilevsky. Esta familia siempre ayud\u00f3 generosamente a las v\u00edctimas de incendios, malas cosechas, pogromos y otras calamidades en las zonas pobladas\u00bb.  <\/p><p>El investigador Shtydveld contin\u00faa con este tema: \u00ab\u00a1Bajo la direcci\u00f3n de Horace Ginzburg funcionaron 507 comit\u00e9s de emigraci\u00f3n! Con el dinero de los Ginzburg se cre\u00f3 la Sociedad Hist\u00f3rica y Etnogr\u00e1fica Jud\u00eda, que public\u00f3 miles de monumentos de antig\u00fcedades jud\u00edas y equip\u00f3 una expedici\u00f3n etnogr\u00e1fica, que reuni\u00f3 una colecci\u00f3n \u00fanica de objetos de la cultura material nacional &#8211; esta colecci\u00f3n form\u00f3 m\u00e1s tarde la base de todo un museo (cerrado a cal y canto bajo el r\u00e9gimen sovi\u00e9tico)\u00bb. Entre otras cosas, su dinero se utiliz\u00f3 para establecer muchas becas diferentes&#8230;.. <\/p><p>Al igual que su padre, Horace Ginzburg intercedi\u00f3 constantemente por los jud\u00edos, presentando notas al gobierno en varias ocasiones. Aunque a Ginzburg se le permiti\u00f3 reunir a representantes jud\u00edos en San Petersburgo para solicitar la mejora de la situaci\u00f3n de los jud\u00edos, en respuesta a la petici\u00f3n, el ministro del Interior, el conde N.P. Ignatiev, dijo: \u00abLa frontera occidental est\u00e1 abierta a los jud\u00edos. Ya tienen muchos derechos y no se obstaculizar\u00e1 su emigraci\u00f3n\u00bb.    <\/p><p>Ignatiev ten\u00eda raz\u00f3n: era m\u00e1s f\u00e1cil para un jud\u00edo abandonar Rusia definitivamente que trasladarse temporalmente de un peque\u00f1o pueblo a una ciudad. Al mismo tiempo, Rusia experimentaba la racha m\u00e1s amplia de pogromos jud\u00edos, lo que tambi\u00e9n favorec\u00eda la emigraci\u00f3n, algo de lo que muchos de los funcionarios rusos se alegraban abiertamente. <\/p><p>Mijail Beiser, en su libro \u00abJud\u00edos en San Petersburgo\u00bb, refiri\u00e9ndose al mismo Klyachko, describe las relaciones de los altos funcionarios rusos \u00abdue\u00f1os del poder\u00bb con el bar\u00f3n Ginzburg de forma notable. \u00abA principios de los a\u00f1os ochenta, los camareros del restaurante Donon, acostumbrados a no dejarse sorprender por nada, fueron testigos de escenas tan misteriosas como \u00e9sta: en el estudio, en la mesa con los restos de una suntuosa cena, dormitaba un general en uniforme desabrochado. Tres hombres paseaban por el pasillo. Dos de ellos eran evidentemente jud\u00edos: \u00abUno era alto, corpulento, con gafas y nariz de \u00e1guila; el otro era de baja estatura, con barba gris, un rostro inusualmente \u00e1gil y unos ojos inteligentes y brillantes, no para su edad\u00bb. El tercero, un hombre alto, delgado e incoloro, ten\u00eda un aspecto claramente burocr\u00e1tico. De repente, el peque\u00f1o se separ\u00f3 del grupo y entr\u00f3 cautelosamente de puntillas en el despacho. Acerc\u00e1ndose al general, levant\u00f3 silenciosamente el dobladillo de su uniforme con una mano, y con la otra se meti\u00f3 en su propio bolsillo. Los otros \u00abconspiradores\u00bb se asomaron por la puerta entreabierta. Cab\u00eda esperar que ahora apu\u00f1alaran a su Excelencia, o que pusieran veneno en su vino, o al menos que robaran algo. Nada de eso ocurri\u00f3. Al contrario, el peque\u00f1o jud\u00edo canoso sacaba un sobre de su bolsillo y lo dejaba caer en el bolsillo interior del uniforme del General. Luego abandonaba el despacho con la misma tranquilidad y se un\u00eda al resto de la compa\u00f1\u00eda. En pocos minutos los tres se asomaban a la habitaci\u00f3n. El general continu\u00f3 durmiendo. Entonces se repet\u00eda el procedimiento descrito y otro sobre desaparec\u00eda en el amplio bolsillo del gordo dormido. Y as\u00ed varias veces, hasta que por fin la persona importante se despertaba y llamaba al timbre. En ese momento, un tr\u00edo de \u00abconspiradores\u00bb entr\u00f3 ruidosamente en el despacho, saludando al general. \u00c9ste les sonri\u00f3: \u00abS\u00ed, he chupado un poco. Es hora de volver a casa. Muy satisfecho. Se har\u00e1 todo lo que se pueda hacer\u00bb. Despu\u00e9s se march\u00f3 con un funcionario delgado y servil.                  <\/p><p>\u00bfDe qu\u00e9 se trataba? \u00bfUna conspiraci\u00f3n antigubernamental? \u00bfLa venta de secretos del Estado Mayor a una potencia extranjera? \u00bfUn intento fallido de asesinato? \u00bfQui\u00e9nes son estas personas &#8211; participantes en los misteriosos sucesos? General durmiente &#8211; Ministro del Interior en el gobierno de Alejandro III Conde NP Ignatiev. El funcionario es su secretario. Un hombre alto y fornido &#8211; un famoso fil\u00e1ntropo, presidente de la junta de la comunidad jud\u00eda de San Petersburgo Horace Gintsburg. Un hombre peque\u00f1o y canoso &#8211; David Faddeyevich Feinberg, una destacada figura p\u00fablica jud\u00eda, uno de los organizadores de la construcci\u00f3n de la sinagoga de San Petersburgo y secretario de Gintsburg. Todo el espect\u00e1culo fue inventado por el propio Ignatiev para obtener sobornos de los jud\u00edos. Si al conde la suma le parec\u00eda insuficiente, el \u00absue\u00f1o\u00bb continuaba. El ministro finalmente \u00abdespertaba\u00bb cuando la \u00abcontribuci\u00f3n\u00bb le satisfac\u00eda por completo. Y era necesario complacer a Ignatiev, porque pod\u00eda evitar nuevas represiones contra los jud\u00edos (organizadas por \u00e9l). Por ejemplo, Ignatiev fue el iniciador de la nueva legislaci\u00f3n antijud\u00eda. Los antecedentes son los siguientes. En 1881, tras el asesinato del emperador Alejandro II, los pogromos se extendieron por todo el asedio. Muchos creyeron que estaban inspirados por el gobierno, que tem\u00eda el estallido de un movimiento revolucionario. Hubo tantos pogromos que Alejandro III propuso a Ignatiev que investigara sus causas y elaborara propuestas para evitarlos en el futuro. El conde elabor\u00f3 un informe, del que se desprend\u00eda que los pogromos eran culpa de &#8230; los propios jud\u00edos, que supuestamente explotaban sin piedad a los campesinos. Por lo tanto, se propuso desalojar a los jud\u00edos de los pueblos (no era una idea nueva, cabe se\u00f1alar).                   <\/p><p>El ministro no se compadec\u00eda de los jud\u00edos, pero era muy aficionado al dinero, del que siempre careci\u00f3. Por eso, antes de llevar el informe al Zar, Ignatiev se lo mostr\u00f3 a Ginzburg y le insinu\u00f3 que por dos millones de rublos (seg\u00fan otras fuentes, por un mill\u00f3n) podr\u00eda cambiarlo por completo. El bar\u00f3n no pudo conseguir la inaudita suma, pero a\u00fan as\u00ed por un soborno menor (unos cien mil rublos) la ley se relaj\u00f3 un poco. Desde el momento en que se introdujo la nueva legislaci\u00f3n, se prohibi\u00f3 a los jud\u00edos establecerse en los pueblos de la l\u00ednea sedentaria y adquirir bienes inmuebles en ellos. No se les permiti\u00f3 vender alcohol. A las asambleas de los pueblos se les concedi\u00f3 el derecho de expulsar del pueblo a cualquier jud\u00edo que hubiera vivido all\u00ed antes de la adopci\u00f3n de la nueva ley.\u00bb     <\/p><p>El conde Ignatiev no era el \u00fanico que despreciaba a los jud\u00edos y hac\u00eda todo lo posible por empeorar su situaci\u00f3n, al tiempo que aceptaba sobornos de ellos &#8211; esta forma de chantaje estaba muy extendida en Rusia. La mayor parte de la nobleza rusa sent\u00eda una aversi\u00f3n especialmente fuerte por gente como los Ginzburgo &#8211; por un lado pertenec\u00edan a la despreciada tribu jud\u00eda, y por otro ten\u00edan un rango nobiliario, lo que les pon\u00eda al mismo nivel (al menos seg\u00fan el protocolo) que la nobleza rusa, pero lo m\u00e1s importante es que dispon\u00edan de capitales colosales con los que la mayor parte de la aristocracia rusa ni siquiera pod\u00eda so\u00f1ar. Estos eran motivos suficientes para la envidia, la ira y el odio.  <\/p><p>Para comprender realmente cu\u00e1l era la verdadera actitud de la mayor\u00eda de la nobleza rusa hacia \u00abestos jud\u00edos advenedizos\u00bb, como algunos representantes de la corte de Su Majestad Imperial caracterizaron a los barones Gintsburg en su momento, merece la pena recurrir a la correspondencia entre el pr\u00edncipe V. P. Meshchersky y el entonces zar ruso Alejandro III. Meshchersky era un conocido publicista, escritor, autor de varios bestsellers de actualidad de la \u00e9poca, as\u00ed como editor y redactor jefe del peri\u00f3dico \u00abGrazhdanin\u00bb, al que proclamaba \u00abel \u00f3rgano del pueblo ruso, por encima de todos los partidos\u00bb. El ep\u00edgrafe de la carta de Meshchersky puede servir como frase de cartas anteriores intercambiadas entre el pr\u00edncipe y el zar: \u00abEs necesario dirigir todos los esfuerzos a detener la propagaci\u00f3n del intelectual jud\u00edo\u00bb. Y he aqu\u00ed el aspecto de otra carta al zar fechada el 5 de enero de 1885.  <\/p><p>\u00abS\u00e1bado<\/p><p>Ayer hubo una cena caracter\u00edstica en casa de Ober-Jude Ginzburg. Ginzburg es el jefe del partido jud\u00edo en Rusia, nadie lo duda. Es a la vez muy rico y muy inteligente. Pero lo triste es que su riqueza es cada vez mayor a medida que su inteligencia se refina para adquirir cada vez m\u00e1s influencia. Adem\u00e1s, es caracter\u00edstico e interesante que Ginzburg act\u00fae con un cinismo y una insolencia sorprendentes: no es ceremonioso para mostrar su desprecio por el pueblo ruso cuando lo necesita. En cuanto se conoci\u00f3 el nombramiento de Ignatieff para Siberia, Ginzburg le hizo una visita. La raz\u00f3n est\u00e1 clara. Ginzburg hab\u00eda adquirido muchas minas de oro en Siberia y hab\u00eda establecido all\u00ed grandes colonias jud\u00edas. Despu\u00e9s de sus visitas, Gintsburg convoca a Ignatiev a cenar. Ignatiev va y encuentra la cena de L\u00faculo. Entre los invitados hay varios generales del as; en tete el conde Pavel Shuvalov, luego Bobrikov, Anuchin; los dos \u00faltimos resultaron ser amis de la maison; Adelson, y por otro lado Ginzburgiat y el director general de las minas de oro de Ginzburg en Siberia. Ginzburg invita, pero no come \u00e9l mismo, para no deshonrarse con los rusos. Se sirve champ\u00e1n, \u00bfy qu\u00e9 es? Bobrikov propone varios brindis, y entre otros este brindis: a la salud del anfitri\u00f3n, como hombre nobil\u00edsimo, firme y constante en su camino, valiente trabajador, que nos ha demostrado que a pesar de la diferencia de religi\u00f3n, no hace distinci\u00f3n de nacionalidades, etc.             <\/p><p>Esos discursos vidriosos me repugnan. Ginzburg los escucha con una sonrisa que expresa: \u00abAlabadme, campesinos, ser\u00e9 libre de escucharos&#8230;\u00bb. <\/p><p>En esta carta personal, enviada al mism\u00edsimo emperador de Rusia y que parec\u00eda m\u00e1s bien una denuncia, se mezclaba todo: el odio y el desprecio hacia los jud\u00edos, la envidia hacia los altos funcionarios que recib\u00edan sobornos de ellos, su propia impotencia y el deseo infinito de hacer algo para fastidiar y molestar a ese maldito e inaccesible Ginzburg. Pero incluso esta denuncia, al parecer, no caus\u00f3 la impresi\u00f3n adecuada. Sin embargo, los tiempos cambiaron, los emperadores rusos, los funcionarios y los escritores cambiaron. S\u00f3lo una cosa no cambi\u00f3: su actitud hacia los jud\u00edos. Como escribi\u00f3 Kushner: \u00abCada \u00e9poca, es una \u00e9poca de hierro\u00bb. Podemos volver a una \u00e9poca posterior, al reinado del \u00faltimo zar ruso Nicol\u00e1s II, sucesor de Alejandro III, y ver que no hubo cambios fundamentales en la actitud de las autoridades hacia los jud\u00edos en Rusia en aquella \u00e9poca, o mejor dicho, hubo cambios, pero s\u00f3lo para peor. Nos permitiremos citar un pasaje del libro de Aaron Simanovich, el joyero de su corte imperial y secretario personal de Grigory Rasputin (por cierto, bastante ambiguo, complejo y en muchos sentidos una figura clave en el horizonte de la fiebre rusa de aquellos a\u00f1os). Muchos de los que han le\u00eddo las memorias de Simanovich sostienen que \u00e9ste enfatiza y exagera en extremo su propio papel en los acontecimientos de aquella \u00e9poca. Sin rebatir esta afirmaci\u00f3n, nos parece que merece la pena escuchar al memorialista, que describe el ambiente y los acontecimientos de aquellos a\u00f1os con bastante precisi\u00f3n. He aqu\u00ed lo que Simanovich escribe en sus memorias.        <\/p><p>\u00abPor supuesto, no necesito decir que en la resoluci\u00f3n de las peticiones jud\u00edas, que pronto se convirti\u00f3 en mi principal ocupaci\u00f3n y absorbi\u00f3 gran parte de mi tiempo, la amistad de Rasput\u00edn fue de gran valor para m\u00ed. Nunca me neg\u00f3 su ayuda. Es cierto que al principio mostr\u00f3 cierta moderaci\u00f3n en los asuntos jud\u00edos. Estaba m\u00e1s dispuesto a estar de acuerdo conmigo cuando se trataba de otros asuntos, y tuve la impresi\u00f3n de que ten\u00eda poco conocimiento de la cuesti\u00f3n jud\u00eda. Tambi\u00e9n me dec\u00eda a menudo que el zar se quejaba de los jud\u00edos. Como los ministros se quejaban constantemente de la dominaci\u00f3n jud\u00eda y de la participaci\u00f3n de los jud\u00edos en el movimiento revolucionario, la cuesti\u00f3n jud\u00eda preocupaba mucho al zar y no sab\u00eda c\u00f3mo abordarla.     <\/p><p>Fue una \u00e9poca corta pero muy peligrosa para los jud\u00edos. Yo ya hab\u00eda empezado a temer que Rasput\u00edn se convirtiera en un antisemita, y utilic\u00e9 toda mi habilidad y energ\u00eda para dirigir los pensamientos de Rasput\u00edn en otra direcci\u00f3n. En cierto sentido, tuve que contrastar mi influencia sobre Rasput\u00edn con la influencia del zar sobre Rasput\u00edn, porque el zar dedicaba a Rasput\u00edn todas sus preocupaciones y se quejaba constantemente de los jud\u00edos. La cuesti\u00f3n era si Rasput\u00edn entrar\u00eda en mis explicaciones sobre la cuesti\u00f3n jud\u00eda o creer\u00eda las quejas del zar. Los representantes de la juder\u00eda, a quienes cre\u00ed necesario iniciar en la formidable situaci\u00f3n que se hab\u00eda creado, se alarmaron mucho y me obligaron a tomar todas las medidas para impedir que Rasput\u00edn se pasara a los antisemitas. Todos ten\u00edamos claro que tal giro tendr\u00eda consecuencias terribles.     <\/p><p>En aquella \u00e9poca, Rasput\u00edn se encontraba ya en la cima de su fama y el zar estaba bastante bajo su influencia. Nicol\u00e1s era entonces aficionado a las organizaciones reaccionarias y \u00e9l mismo era miembro de la \u00abUni\u00f3n del Pueblo Ruso\u00bb, que organizaba los pogromos jud\u00edos. Si Rasput\u00edn se un\u00eda a las figuras reaccionarias que estaban muy por la labor, entonces para los jud\u00edos ser\u00edan los \u00faltimos tiempos. Tras una larga vacilaci\u00f3n, se puso de nuestro lado. Su sano razonamiento humano se impuso. Se convirti\u00f3 en amigo y benefactor de los jud\u00edos y apoy\u00f3 incondicionalmente mis esfuerzos por mejorar su situaci\u00f3n.     <\/p><p>Tuve muchas conferencias con representantes jud\u00edos y se me encomend\u00f3 la tarea de esforzarme y, si era posible, lograr la igualdad de los jud\u00edos. Esto tambi\u00e9n significaba que las formas y los medios que esboc\u00e9 y emple\u00e9 para lograr este objetivo eran reconocidos como correctos. Acept\u00e9 la tarea que se me hab\u00eda encomendado, pero la revoluci\u00f3n se me adelant\u00f3 a la hora de completarla. En cualquier caso, me siento orgulloso de haber estado destinado a ayudar a los jud\u00edos en una \u00e9poca tan dif\u00edcil y a aliviar su destino al menos parcialmente&#8230;..   <\/p><p>Rasput\u00edn se quejaba a menudo de la oposici\u00f3n de los ministros y otras personas influyentes hostiles a los jud\u00edos. A este respecto me pidi\u00f3 que le presentara a personas que pudieran darle informaci\u00f3n interesante sobre la cuesti\u00f3n jud\u00eda. <\/p><p>Me dijo, sin embargo, que en general el zar no era tan hostil a los jud\u00edos como se piensa com\u00fanmente. No obstante, la palabra \u00abjud\u00edo\u00bb tiene un efecto desagradable en la familia real. La aversi\u00f3n hacia los jud\u00edos es inculcada a los ni\u00f1os de la familia imperial desde peque\u00f1os por las ni\u00f1eras y otros sirvientes. Rasput\u00edn contaba que el ministro del Interior Maklakov, cuando jugaba con el heredero, intentaba intimidarle con las siguientes palabras: \u00ab\u00a1Espera, que te llevar\u00e1n los jud\u00edos! Por miedo, el heredero ante estas palabras incluso grit\u00f3\u00bb.    <\/p><p>Fue en estas condiciones de \u00abRusia antisemita de arriba abajo y de abajo arriba\u00bb en las que tuvieron que existir la gran poblaci\u00f3n jud\u00eda del imperio y los l\u00edderes de la comunidad, los barones Ginzburgs. Por supuesto, para dirigir la comunidad en aquella \u00e9poca y en aquellas condiciones hab\u00eda que ser una persona extremadamente extraordinaria. Y las leyendas, los rumores y los cotilleos siempre acompa\u00f1an la vida de las personas extraordinarias y famosas. Lo que no s\u00f3lo se contaba sobre los Hinzburg y, en particular, sobre Horacio, lo que no se contaban eran disputas y trifulcas en torno a estas personas: Algunos afirmaban que apoyaba a los revolucionarios y quer\u00eda derrocar con su dinero al r\u00e9gimen existente, otros, por el contrario, objetaban que era un leal \u00abservidor del zar\u00bb; algunos echaban espumarajos por la boca para demostrar que se opon\u00eda a la emigraci\u00f3n de los jud\u00edos de Rusia, mientras que otros sosten\u00edan con l\u00f3gica que Horacio gastaba enormes sumas de dinero en la \u00abSociedad de Colonizaci\u00f3n Jud\u00eda\u00bb junto con el bar\u00f3n Hirsch; algunos cotilleaban que Horacio era due\u00f1o de un har\u00e9n de amantes, mientras que otros afirmaban que era \u00abel m\u00e1s fiel de los maridos\u00bb. Los rumores y las habladur\u00edas \u00abcrec\u00edan sin barreras\u00bb: una parte de la comunidad jud\u00eda insist\u00eda en que el tiempo de Horacio hab\u00eda pasado y que estaba obsoleto como l\u00edder, que se necesitaban nuevas ideas y nuevas formas de luchar por la igualdad, mientras que otros miembros de la comunidad les disuad\u00edan, afirmando que en Rusia no hab\u00eda ni habr\u00eda nunca otra forma de conseguir nada que no fuera el dinero. Las discusiones al respecto no ten\u00edan fin.     <\/p><p>\u041e. Budnitsky en su art\u00edculo da, en particular, un ejemplo de ello: \u00abCorr\u00edan rumores de que Gintsburg financiaba la \u00abDruzhina Sagrada\u00bb, una sociedad secreta creada para combatir a los revolucionarios con sus propios m\u00e9todos, hasta el terrorismo. Al mismo tiempo, mantuvo estrechas relaciones con Mija\u00edl Stasiulevich, editor del peri\u00f3dico liberal \u00abOrden\u00bb publicado en 1881-1882, y le proporcion\u00f3 apoyo financiero. Sin embargo, las malas lenguas afirmaban que Horacio apoyaba al peri\u00f3dico no por predilecci\u00f3n hacia las ideas liberales, sino por simpat\u00eda hacia la esposa de Stasiulevich, de soltera Utina. Las mismas malas lenguas afirmaban que era dif\u00edcil encontrar una mujer m\u00e1s fea que el objeto de la pasi\u00f3n del banquero. Pero el amor, como es bien sabido, es un sentimiento misterioso\u00bb.     <\/p><p>Adem\u00e1s de los rumores m\u00e1s incre\u00edbles y difundidos sin cesar, adem\u00e1s del odio de los Cien Negros, de la aversi\u00f3n de las personas zaristas y de la inmensa mayor\u00eda del pueblo ruso, los ginzburgueses tambi\u00e9n se vieron sometidos a la cr\u00edtica constante de su propia comunidad. Y estas cr\u00edticas proced\u00edan de la parte m\u00e1s ilustrada y educada de la comunidad, es decir, su intelligentsia. He aqu\u00ed c\u00f3mo A. Lokshin describe esta situaci\u00f3n: \u00abTras la reorganizaci\u00f3n de la junta en 1869, literalmente toda la vida comunitaria de la capital pas\u00f3 a depender por completo de las donaciones voluntarias de varias familias jud\u00edas pr\u00f3speras. Los barones Ginzburgs, que estaban a la cabeza de la comunidad (primero Euzel y luego sus hijos Horace y David), formaban un poder que en realidad era hereditario. Ten\u00edan acceso a los m\u00e1s altos funcionarios del Estado y gozaban de una inmensa popularidad fuera de Pedro, como benefactores e intercesores. Es posible imaginar la posici\u00f3n de esta familia \u00fanica, por ejemplo, por el hecho de que entre ellos, en el habla com\u00fan, los jud\u00edos de San Petersburgo llamaban a Horace Ginzburg nada menos que \u00abpap\u00e1\u00bb. Ten\u00eda modales aristocr\u00e1ticos y, como muchos arist\u00f3cratas rusos, se sent\u00eda m\u00e1s natural hablando franc\u00e9s que ruso. Entre los invitados a la casa de moda de Ginzburg en el Malec\u00f3n Ingl\u00e9s pod\u00edan encontrarse famosos escritores y artistas rusos, generales, abogados, importantes funcionarios del gobierno. Cuando viajaban por sus extensas fincas en la provincia de Podolsk, los Ginzburg a menudo se ve\u00edan literalmente asediados por multitudes de jud\u00edos pobres que les ped\u00edan ayuda monetaria o intercesi\u00f3n de diversos tipos. En la mente popular, en la de la gente que anhelaba un protector poderoso, los diversos jud\u00edos ricos e influyentes de San Petersburgo, que casualmente llevaban los apellidos de Ginsberg, Ginzburg, Ginzburg o Gunzburg, se fund\u00edan en un \u00fanico \u00abbar\u00f3n Ginzburg\u00bb; era a \u00e9l a quien se atribu\u00edan todas las buenas acciones.      <\/p><p>Mientras tanto, la situaci\u00f3n en la comunidad segu\u00eda irritando a la intelectualidad jud\u00eda. \u00c9sta cre\u00eda que los mism\u00edsimos nuevos ricos, tal y como se describ\u00edan en la novela de Levanda, hab\u00edan cobrado vida y se hab\u00edan hecho con el control de la principal comunidad de jud\u00edos rusos. En un llamamiento abierto a los Ginzburgo y similares, los editores de \u00abRassvet\u00bb escribieron en 1880: \u00abLos jud\u00edos seguimos sin poder sacudirnos el triste legado de siglos que nos han impuesto desde el exterior &#8230;.. Todav\u00eda no podemos sacudirnos la desafortunada, pero desgraciadamente basada en tristes experiencias, convicci\u00f3n de que todo y en todas partes s\u00f3lo se puede conseguir con dinero. El dinero, y s\u00f3lo el dinero, nos salv\u00f3 del exilio, de las hogueras; el dinero nos dio honor y una posici\u00f3n privilegiada en algunos estados, y a\u00fan lo hace; \u00bfpor qu\u00e9, se pregunta, con dinero, s\u00f3lo con dinero, no podr\u00edamos arreglar los asuntos p\u00fablicos como es debido? Resulta, sin embargo, que no es posible, que dentro de la juder\u00eda tambi\u00e9n son necesarios otros resortes y motores&#8230; Nosotros, no obstante, no estamos en absoluto en contra de que nuestras celebridades financieras participen en los asuntos p\u00fablicos&#8230;.. S\u00f3lo estamos en contra de la participaci\u00f3n exclusiva en estos asuntos a sus expensas y a las de nadie m\u00e1s&#8230; S\u00f3lo los asuntos p\u00fablicos y los esfuerzos que no sean obra de individuos aislados, sino del pueblo en su conjunto, pueden tener verdadero \u00e9xito\u00bb.  <\/p><p>Este pasaje describe con gran exactitud el ambiente y la mentalidad de aquellos a\u00f1os. El sionismo y el movimiento revolucionario (ideas tan diferentes y contradictorias) acaparaban cada vez m\u00e1s la conciencia de los jud\u00edos de Rusia. Seg\u00fan los recuerdos de los contempor\u00e1neos, \u00abya nadie quiere la evoluci\u00f3n, \u00a1todos quieren alg\u00fan tipo de revoluci\u00f3n!\u00bb. Los barones Ginzburgs, que nunca hab\u00edan sido revolucionarios, sionistas o mon\u00e1rquicos se sent\u00edan en este ambiente cada vez m\u00e1s dif\u00edcil. La \u00e9poca de los magnates filantr\u00f3picos en Rusia estaba llegando a su fin. Dirigir la comunidad de un pa\u00eds que se derrumbaba ante los propios ojos era impensablemente dif\u00edcil. Los Ginzburgo se dieron cuenta de ello, pero no pudieron hacer nada. He aqu\u00ed c\u00f3mo se describe esta situaci\u00f3n en el ensayo hist\u00f3rico de la ORT dedicado a Horace Ginzburg.      <\/p><p>\u00abSin duda, se trataba de una persona excepcional. \u00bfPor qu\u00e9 entonces, por ejemplo, en las elecciones a la Primera Duma Estatal, Horace Ginzburg no se convirti\u00f3 en diputado jud\u00edo? \u00bfPor qu\u00e9 ni siquiera fue propuesto para este puesto y nadie acudi\u00f3 a \u00e9l para pedirle consejo? \u00bfQuiz\u00e1s olvidaron sus servicios al mundo jud\u00edo? Por supuesto que no. Simplemente, los tiempos hab\u00edan cambiado. Ginzburg era un l\u00edder jud\u00edo demasiado tradicional. De acuerdo con las ense\u00f1anzas jud\u00edas, cre\u00eda que los jud\u00edos deb\u00edan seguir estrictamente las leyes de su pa\u00eds de residencia. La lealtad al gobierno, al rey, era un principio sagrado para \u00e9l. \u00bfQu\u00e9 pod\u00eda hacer? Donar dinero, mucho dinero, aplacar de alguna manera a un funcionario, dar un soborno (como en la historia del conde Ignatiev). Y, por supuesto, suplicar, interceder.           <\/p><p>Un l\u00edder as\u00ed en la Rusia de principios del siglo XX ya no era aceptable para la mayor\u00eda de los jud\u00edos. La situaci\u00f3n pol\u00edtica del pa\u00eds estaba cambiando r\u00e1pidamente. El antisemitismo cobraba fuerza y estallaban terribles pogromos. Y la propia juder\u00eda hac\u00eda tiempo que hab\u00eda dejado de ser una comunidad monol\u00edtica para disgregarse en grupos que luchaban entre s\u00ed. Era necesario no pedir, sino exigir, gritar para ser escuchado. Para conseguir algo o al menos proteger el propio hogar, hab\u00eda que tomar las armas. El Estado no iba a proteger a los jud\u00edos de la arbitrariedad, sino que participaba \u00e9l mismo en esta arbitrariedad, viendo en una naci\u00f3n extranjera la causa de la propagaci\u00f3n de la revoluci\u00f3n y un chivo expiatorio adecuado. Nicol\u00e1s II, en un telegrama enviado en junio de 1907 a uno de los dirigentes de la Uni\u00f3n del Pueblo Ruso, dec\u00eda: \u00ab&#8230;. que la Uni\u00f3n del Pueblo Ruso sea para m\u00ed un apoyo fiable, que sirva de ejemplo de ley y orden para todos y en todo\u00bb.       <\/p><p>\u00bfQu\u00e9 pod\u00eda pedir el bar\u00f3n Ginzburg al Emperador, para quien la Uni\u00f3n del Pueblo Ruso era la base de la ley y el orden? Estaba claro para cualquier persona pensante de la \u00e9poca que la salvaci\u00f3n de los jud\u00edos estaba en la emigraci\u00f3n o en la lucha revolucionaria. No hab\u00eda lugar para el compromiso en una sociedad amargada y en crisis. Pero Ginzburg no simpatizaba ni con los revolucionarios (ni de izquierdas ni de derechas), ni con la emigraci\u00f3n, ni con el sionismo. Por eso, en las elecciones a la Duma Estatal, los jud\u00edos no votaron por \u00e9l, sino por los nuevos l\u00edderes que ten\u00edan el valor y la capacidad no de pedir, sino de exigir. El pueblo jud\u00edo, como los dem\u00e1s pueblos de Rusia, ya no quer\u00eda pedir nada. Lo consideraban humillante e in\u00fatil. La \u00e9poca de l\u00edderes como Horace Yevzelevich Gintsburg hab\u00eda pasado irrevocablemente\u00bb.       <\/p><p>Naftali Herz (Horacio) Ginzburg muri\u00f3 en 1909 en San Petersburgo, la capital del Estado ruso. En su testamento pidi\u00f3 ser enterrado en Par\u00eds, donde reposaban las cenizas de su padre, su hermana y sus hermanos. Como escribe Shtylveld \u00abCuando muri\u00f3, las figuras p\u00fablicas m\u00e1s destacadas de la comunidad jud\u00eda de la \u00e9poca le llamaron en el funeral \u00abla belleza de Israel\u00bb por su incesante preocupaci\u00f3n por su pueblo. Y el sionista Temkin habl\u00f3 all\u00ed \u00aben nombre de los remotos lugares de provincia\u00bb: \u00ab\u00bfPuede nombrar un solo lugar que en un momento de dolor no pidiera protecci\u00f3n al Bar\u00f3n? \u00bfPuede encontrar un solo jud\u00edo que, en un momento de desesperaci\u00f3n o amargo sufrimiento, no hubiera recurrido al Bar\u00f3n? Y el Bar\u00f3n fue, suplic\u00f3, intercedi\u00f3&#8230; \u00a1nunca rechaz\u00f3 a nadie!\u00bb.   <\/p><p>Por supuesto, tras la muerte de Horace, las actividades financieras y filantr\u00f3picas de la familia Ginzburg no cesaron. La familia qued\u00f3 encabezada por sus hijos. En su testamento, Horace escribi\u00f3 que \u00abdurante su vida don\u00f3 mucho a fines ben\u00e9ficos y por ello no lega sumas especiales para ellos, pero espera que sus hijos, siguiendo las tradiciones de la familia y de todo el pueblo jud\u00edo, contin\u00faen la causa de la caridad\u00bb. Y en efecto, como escriben los investigadores, \u00abHoracio result\u00f3 ser un visionario: los descendientes de los Ginzburgo siguen participando en actos caritativos\u00bb.   <\/p><p>No cabe duda de que la familia Ginzburg, m\u00e1s que ninguna otra, dej\u00f3 su huella en la historia jud\u00eda de Rusia. Esta familia ten\u00eda enormes conexiones en toda Europa. Los Ginzburg estaban emparentados con los famosos Rothschild franceses, con el bar\u00f3n Hirsch, con los banqueros alemanes Warburg de Hamburgo, con los banqueros Herzfelds de Budapest, Ashkenazi de Odessa, Rosenberg y Brodsky de Kiev. Los Ginzburg ten\u00edan una familia numerosa.   <\/p><p>Nos gustar\u00eda nombrar al menos a algunos de sus miembros en este art\u00edculo como muestra de gratitud por todo lo que esta familia hizo por los jud\u00edos de Rusia. S\u00f3lo Horace tuvo once hijos. He aqu\u00ed sus nombres y fechas de vida: Gabriel Jacob (1855-1926, Par\u00eds), David (1857-1910, San Petersburgo), Mordechai Maximilian (1859-?), Louise (1862-1921), Alexandre Moses (1863-1948), Abram Alfred (1865-1936, Par\u00eds), Mathilde (1865-1917), Isaac Dimitri (1870-1907), Benjamin Pierre (1872-1948), Vladimir Zeev Wolf (1873, Par\u00eds-1932, Par\u00eds) y Sarah Anna (1876-?).  <\/p><p>Alexander Ziskind (1831-1878), hermano mayor de Horace tuvo dos hijos, Michael y Gabriel Jacob.<\/p><p>Mathilde (1844-1878, Par\u00eds), su hermana menor tambi\u00e9n tuvo dos hijos, su hermano Salom\u00f3n David (1848-1905, Par\u00eds) tuvo cuatro, y Uri (1840-1914, Par\u00eds), otro de sus hermanos, tuvo 9 hijos.  <\/p><p>Casi todos estos 28 primos tuvieron sus propios hijos, y luego nietos y bisnietos. Numerosos descendientes de la familia recuerdan sus ra\u00edces y han conseguido recrear su extenso \u00e1rbol geneal\u00f3gico que se remonta al siglo XV. <\/p><p>En conclusi\u00f3n, hay que decir que todos los descendientes de los Ginzburgo abandonaron Rusia en diferentes momentos (la mayor\u00eda antes de la revoluci\u00f3n). As\u00ed pues, m\u00e1s de un siglo de vida de esta familia en el territorio del Imperio ruso ha llegado a su fin. Numerosos descendientes de los Gintsburg viven ahora en todo el mundo, desde Francia e Israel hasta Estados Unidos. Pero lo m\u00e1s probable es que la memoria de esta famosa familia siga siendo conservada por los jud\u00edos de Rusia.   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Horace Ginzburg Esta historia comienza con un tal Jehiel de la ciudad portuguesa de Oporto. Esta ciudad principal de la provincia de Entre Duro e Minho era conocida en el siglo XV por su numerosa comunidad jud\u00eda. El 4 de diciembre de 1496, el rey promulg\u00f3 un decreto que ordenaba a todos los jud\u00edos abandonar [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-6206","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Barones jud\u00edos - Am haZikaron<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amhazikaron.org\/es\/barones-judios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barones jud\u00edos - Am haZikaron\" \/>\n<meta property=\"og:description\" content=\"Horace Ginzburg Esta historia comienza con un tal Jehiel de la ciudad portuguesa de Oporto. Esta ciudad principal de la provincia de Entre Duro e Minho era conocida en el siglo XV por su numerosa comunidad jud\u00eda. El 4 de diciembre de 1496, el rey promulg\u00f3 un decreto que ordenaba a todos los jud\u00edos abandonar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amhazikaron.org\/es\/barones-judios\/\" \/>\n<meta property=\"og:site_name\" content=\"Am haZikaron\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jewage\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-15T05:49:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AmhaZikaron\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"58 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/barones-judios\\\/\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/barones-judios\\\/\",\"name\":\"Barones jud\u00edos - Am haZikaron\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/#website\"},\"datePublished\":\"2025-05-22T11:45:26+00:00\",\"dateModified\":\"2025-08-15T05:49:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/barones-judios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amhazikaron.org\\\/es\\\/barones-judios\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/barones-judios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Barones jud\u00edos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/\",\"name\":\"Am haZikaron\",\"description\":\"\u0418\u043d\u0441\u0442\u0438\u0442\u0443\u0442 \u043d\u0430\u0443\u043a\u0438, \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u044b \u0438 \u043d\u0430\u0441\u043b\u0435\u0434\u0438\u044f \u0435\u0432\u0440\u0435\u0439\u0441\u043a\u043e\u0433\u043e \u043d\u0430\u0440\u043e\u0434\u0430\",\"publisher\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/#organization\",\"name\":\"Am haZikaron\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo.svg\",\"width\":48,\"height\":48,\"caption\":\"Am haZikaron\"},\"image\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jewage\",\"https:\\\/\\\/x.com\\\/AmhaZikaron\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Barones jud\u00edos - Am haZikaron","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amhazikaron.org\/es\/barones-judios\/","og_locale":"es_ES","og_type":"article","og_title":"Barones jud\u00edos - Am haZikaron","og_description":"Horace Ginzburg Esta historia comienza con un tal Jehiel de la ciudad portuguesa de Oporto. Esta ciudad principal de la provincia de Entre Duro e Minho era conocida en el siglo XV por su numerosa comunidad jud\u00eda. El 4 de diciembre de 1496, el rey promulg\u00f3 un decreto que ordenaba a todos los jud\u00edos abandonar [&hellip;]","og_url":"https:\/\/amhazikaron.org\/es\/barones-judios\/","og_site_name":"Am haZikaron","article_publisher":"https:\/\/www.facebook.com\/jewage","article_modified_time":"2025-08-15T05:49:05+00:00","twitter_card":"summary_large_image","twitter_site":"@AmhaZikaron","twitter_misc":{"Tiempo de lectura":"58 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/amhazikaron.org\/es\/barones-judios\/","url":"https:\/\/amhazikaron.org\/es\/barones-judios\/","name":"Barones jud\u00edos - Am haZikaron","isPartOf":{"@id":"https:\/\/amhazikaron.org\/es\/#website"},"datePublished":"2025-05-22T11:45:26+00:00","dateModified":"2025-08-15T05:49:05+00:00","breadcrumb":{"@id":"https:\/\/amhazikaron.org\/es\/barones-judios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amhazikaron.org\/es\/barones-judios\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/amhazikaron.org\/es\/barones-judios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/amhazikaron.org\/es\/principal\/"},{"@type":"ListItem","position":2,"name":"Barones jud\u00edos"}]},{"@type":"WebSite","@id":"https:\/\/amhazikaron.org\/es\/#website","url":"https:\/\/amhazikaron.org\/es\/","name":"Am haZikaron","description":"\u0418\u043d\u0441\u0442\u0438\u0442\u0443\u0442 \u043d\u0430\u0443\u043a\u0438, \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u044b \u0438 \u043d\u0430\u0441\u043b\u0435\u0434\u0438\u044f \u0435\u0432\u0440\u0435\u0439\u0441\u043a\u043e\u0433\u043e \u043d\u0430\u0440\u043e\u0434\u0430","publisher":{"@id":"https:\/\/amhazikaron.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amhazikaron.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amhazikaron.org\/es\/#organization","name":"Am haZikaron","url":"https:\/\/amhazikaron.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amhazikaron.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/logo.svg","contentUrl":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/logo.svg","width":48,"height":48,"caption":"Am haZikaron"},"image":{"@id":"https:\/\/amhazikaron.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jewage","https:\/\/x.com\/AmhaZikaron"]}]}},"_links":{"self":[{"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/pages\/6206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/comments?post=6206"}],"version-history":[{"count":1,"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/pages\/6206\/revisions"}],"predecessor-version":[{"id":6207,"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/pages\/6206\/revisions\/6207"}],"wp:attachment":[{"href":"https:\/\/amhazikaron.org\/es\/wp-json\/wp\/v2\/media?parent=6206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}