{"id":3830,"date":"2025-04-17T00:47:58","date_gmt":"2025-04-17T00:47:58","guid":{"rendered":"https:\/\/amhazikaron.org\/project\/verwandtschaft\/"},"modified":"2025-08-08T21:41:28","modified_gmt":"2025-08-08T21:41:28","slug":"verwandtschaft","status":"publish","type":"project","link":"https:\/\/amhazikaron.org\/de\/project\/verwandtschaft\/","title":{"rendered":"Verwandtschaft"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3830\" class=\"elementor elementor-3830 elementor-775\" data-elementor-post-type=\"project\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6baf4d7 e-flex e-con-boxed e-con e-parent\" data-id=\"6baf4d7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-77489d9 e-con-full e-flex e-con e-child\" data-id=\"77489d9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f0d521 elementor-widget elementor-widget-image\" data-id=\"6f0d521\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"946\" height=\"630\" src=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/rodnia-clr.jpg\" class=\"attachment-full size-full wp-image-3831\" alt=\"Rod&apos;N&apos;a cover\" srcset=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/rodnia-clr.jpg 946w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/rodnia-clr-300x200.jpg 300w, https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/rodnia-clr-768x511.jpg 768w\" sizes=\"(max-width: 946px) 100vw, 946px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-44c24c6 e-con-full e-flex e-con e-child\" data-id=\"44c24c6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a58c89f elementor-widget elementor-widget-text-editor\" data-id=\"a58c89f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das <span class=\"in-accent\">Am a-Zikaron <\/span>Institut widmet sich der Wiederherstellung der Geschichte der j\u00fcdischen Familien und der Popularisierung dieses Themas. Unser Traum ist es, dass jeder Jude seine historischen Wurzeln kennt. Kinder, die im Rahmen des Taglit-Programms nach Israel kommen, nehmen an unserem Seminar teil, wo sie erste Informationen \u00fcber ihre famili\u00e4re Herkunft erhalten. Auf Initiative und mit Unterst\u00fctzung der Genesis Charitable Foundation haben wir das Projekt ausgeweitet und ein j\u00e4hrliches Programm &#8222;Rod&#8217;N&#8217;ya&#8220; ins Leben gerufen, an dem junge Menschen zwischen 18 und 35 Jahren, die an Taglit teilgenommen haben, teilnehmen k\u00f6nnen. Das &#8222;Rod&#8217;N&#8217;ya&#8220;-Programm ist f\u00fcr diejenigen gedacht, die von einer Reise nach Israel zur\u00fcckgekehrt sind, fasziniert von der Idee des eigenen J\u00fcdischseins, fasziniert von dem Land. Wir wollen diese Stimmungen unterst\u00fctzen und versuchen, sie in die Richtung einer gemeinschaftlichen Aktivit\u00e4t zu lenken. Dass das Interesse, das bei den Kindern w\u00e4hrend des 10-t\u00e4gigen Aufenthalts in Israel entstanden ist, nicht verschwindet und dass sie nach ihrer Abreise gelernt haben: und in ihrer Stadt gibt es viele Menschen, die j\u00fcdisches Leben leben, und das f\u00fcr jeden Geschmack &#8211; und ultra-religi\u00f6s, und s\u00e4kular. Wir verbreiteten Informationen \u00fcber Rod&#8217;N&#8217;y durch Hillel-Zweigstellen im gesamten postsowjetischen Raum. Das Ergebnis war die Teilnahme von 200 Personen im ersten Jahr des Projekts.        <\/p><h4>Familiengeschichte &#8222;f\u00fcr Dummies&#8220;<\/h4><p>&#8222;Rod&#8217;N&#8217;Ya&#8220; ist ein Programm f\u00fcr diejenigen, die etwas \u00fcber ihre Familiengeschichte erfahren m\u00f6chten, aber absolut keine Ahnung haben, wie sie es angehen sollen. Wir erkl\u00e4ren den Teilnehmern im Detail, wo sie anfangen sollten und wonach sie von Anfang an suchen m\u00fcssen. Sie k\u00f6nnen zum Beispiel eine Menge aus Familienfotos lernen. Ein Foto eines Gro\u00dfvaters oder Urgro\u00dfvaters in einer Milit\u00e4runiform verr\u00e4t Ihnen, in welchen Truppen er gedient hat. Vielleicht war er ein Milit\u00e4ringenieur oder ein Milit\u00e4rarzt. Es gibt noch andere, wenig beachtete Details, die \u00e4u\u00dferst wertvolle Informationen liefern. Einer unserer Programmteilnehmer wusste zum Beispiel nicht, wo seine Urgro\u00dfmutter geboren wurde. Als er sich ihr Foto ansah, fand er die Adresse des Fotostudios in Nemirov. Im Allgemeinen gibt es sehr viele Details, auf die ein unge\u00fcbter Mensch einfach nicht achtet.        <\/p><h4>Tools f\u00fcr die Arbeit mit der Geschichte<\/h4><p>Es gibt drei Methoden, um die Wurzeln der Familie zu finden. Das erste und wichtigste ist die Befragung von nahen und fernen Verwandten, und noch besser &#8211; sehr fernen Verwandten, von denen die Person nichts wusste: Sie sind es, die in der Regel die wertvollsten Informationen haben. Die zweite Ressource sind Informationen aus dem Internet, von Memoiren und B\u00fcchern bis hin zu historischen Datenbanken, Meldeb\u00fcchern, von Enthusiasten digitalisierten Listen von Beerdigungen auf Friedh\u00f6fen. Und schlie\u00dflich sind die Archive die dritte Quelle. Wir lehren, wie man mit ihnen arbeitet, erkl\u00e4ren, wann es sinnvoll ist, im Standesamt nach Informationen zu suchen, und wann &#8211; im historischen Archiv. Es gibt auch Quellen, die der russischsprachigen \u00d6ffentlichkeit nicht immer zug\u00e4nglich sind: rabbinische Literatur in hebr\u00e4ischer Sprache. W\u00e4hrend des gesamten Projekts werden die Teilnehmer von professionellen Forschern unterst\u00fctzt: Sie bringen ihnen zun\u00e4chst bei, wie man nach Informationen sucht, und begleiten sie dann, indem sie sie praktisch in allen Phasen an die Hand nehmen.      <\/p><h4>Nicht zuf\u00e4llige Unf\u00e4lle<\/h4><p>Ein Projektteilnehmer aus Moskau reiste nach Minsk, um im dortigen Archiv die Heiratsurkunde seiner Urgro\u00dfmutter zu finden. Als er die digitale Kopie eines Blattes aus dem rabbinischen Buch der Heiratsregistrierung erhielt, stellte sich heraus, dass die zweite Zeile in den Aufzeichnungen auf dem Blatt ein Eintrag \u00fcber die Heiratsregistrierung seiner Urgro\u00dfmutter war. Und die erste Zeile war ein \u00e4hnlicher Eintrag \u00fcber den Urgro\u00dfvater eines anderen Teilnehmers desselben Projekts &#8211; aus Jekaterinburg! Ich mag solche Zuf\u00e4lle sehr, denn ich bin sicher, dass sie nicht wirklich zuf\u00e4llig sind.   <\/p><h4>Ein Blick durch sieben Jahrhunderte<\/h4><p>Sechs Teilnehmer des Projekts &#8222;Rod&#8217;N&#8217;Ya&#8220; geh\u00f6ren direkt oder indirekt zur Familie Rapoport. Und jeder von ihnen hat eine Recherche durchgef\u00fchrt, die mit verschiedenen Perioden des XIX Jahrhunderts endet. Jahrhundert bekannt ist. Es handelt sich um eine Familie mit einer erstaunlichen Geschichte, mit vielen schillernden Pers\u00f6nlichkeiten, die in einem riesigen Gebiet von Deutschland und Italien bis nach Wei\u00dfrussland und Galizien lebten! Wir m\u00f6chten, dass die Teilnehmer \u00fcber die Geschichte ihrer eigenen Familie eine Verbindung zu der einen oder anderen j\u00fcdischen Familie herstellen. Und wir erz\u00e4hlen ihnen, was diese Familien sind, was die Rapoports oder Feldmans in den letzten sieben Jahrhunderten getan haben.    <\/p><h4>Die Metaphysik des Erwachens<\/h4><p>Bei unserer Arbeit gibt es ein interessantes Ph\u00e4nomen. Menschen, die zu denselben Familien geh\u00f6ren, aber nichts voneinander wissen, wenden sich pl\u00f6tzlich zur gleichen Zeit an uns. W\u00e4hrend wir in diesem Jahr sechs Rapoports hatten, ging es bei einem anderen Projekt vor ein paar Jahren um f\u00fcnf Personen aus verschiedenen L\u00e4ndern mit dem Nachnamen Derbaremdiker (&#8222;Barmherzig&#8220; auf Jiddisch). Sie alle sind Nachkommen des ber\u00fchmten chassidischen Zaddik Levi Itzkach aus Berditschew. Er hatte den Spitznamen Derbaremdiker, weil er jedes Gebet mit diesem Wort begann. Heute gibt es nur noch ein paar hundert Derbaremdiker auf der Welt! Und als f\u00fcnf von ihnen auf einmal zu uns kamen, hatten wir das Gef\u00fchl, dass es der Rabbi selbst war, der einen Fu\u00df auf das Land Jerusalem gesetzt hatte. Wir freuen uns schon auf das n\u00e4chste Projekt. Wir wollen herausfinden, welche j\u00fcdische Familie als n\u00e4chste &#8222;erwacht&#8220;!       <\/p><h4>Verlorene Geschichte<\/h4><p>Manchmal gehen alle F\u00e4den der Familiengeschichte verloren. Es ist eine nicht enden wollende Trag\u00f6die, wenn ein Urgro\u00dfvater aufgrund seiner Dienstpflicht oder aufgrund der in der UdSSR geltenden Befehle bis zu seinem Lebensende niemandem etwas \u00fcber seine Familie, seine Verwandten oder seine Herkunft erz\u00e4hlt hat. Leider ist es schwierig, in solchen F\u00e4llen zu arbeiten, denn die Verwandten sind die Hauptinformationsquelle. Manchmal finden die Menschen auf der Suche nach der Wahrheit sehr weit entfernte Verwandte, die ihre Familien seit Jahrzehnten nicht mehr gesehen haben. Die Besonderheit bei der Arbeit mit Kindern aus der GUS besteht darin, dass viele von ihnen \u00fcberhaupt nichts \u00fcber ihre Abstammung wissen. Wir haben zum Beispiel lange gebraucht, um einen der Teilnehmer davon zu \u00fcberzeugen, dass er ein Nachkomme einer \u00e4u\u00dferst ber\u00fchmten chassidischen ukrainischen Familie war, einer der ber\u00fchmtesten chassidischen Tzaddiks. Er selbst war sich sicher, dass er aus einer sehr einfachen Familie stammte, in der es au\u00dfer Handwerkern niemanden gab.      <\/p><h4>Auf den Spuren der alten Gemeinschaften<\/h4><p>Wir haben eine Expedition zu den St\u00e4tten alter j\u00fcdischer Gemeinden in Deutschland durchgef\u00fchrt. Wir besuchten nicht die Orte, an denen jemandes besondere Vorfahren lebten, sondern die Orte der Ansiedlung und die Wege der Migration, die Geschichten ihrer Familien, bevor sie russischsprachig wurden. Und auch &#8211; St\u00e4dte mit Namen &#8211; Landau, Oppenheim und andere. Eine Woche lang haben wir den Zeitraum vom V. bis zum XVIII. Jahrhundert abgedeckt, also 13 Jahrhunderte j\u00fcdischer Geschichte. Eines der Ziele unseres Projekts ist es, die Teilnehmer nicht nur mit dem russischen Judentum, sondern auch mit der globalen j\u00fcdischen Welt zu verbinden. Es ist wichtig, die Landschaft, in der unsere Vorfahren vor vielen Jahrhunderten lebten, mit eigenen Augen zu sehen und in unseren jungen Zeitgenossen ein Gef\u00fchl der Verbundenheit mit diesem Ort, mit dieser Welt, mit der j\u00fcdischen Geschichte zu wecken.     <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aac041e elementor-widget elementor-widget-video\" data-id=\"aac041e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=XrPJoV985n8&amp;t=1s&amp;ab_channel=Serhii&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Forschungsexpedition entlang der Migrationsrouten des j\u00fcdischen Volkes<\/p>\n","protected":false},"featured_media":3831,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"project-type":[53],"class_list":["post-3830","project","type-project","status-publish","has-post-thumbnail","hentry","project-type-abgeschlossene-projekte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verwandtschaft - Am haZikaron<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amhazikaron.org\/de\/project\/verwandtschaft\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verwandtschaft - Am haZikaron\" \/>\n<meta property=\"og:description\" content=\"Forschungsexpedition entlang der Migrationsrouten des j\u00fcdischen Volkes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amhazikaron.org\/de\/project\/verwandtschaft\/\" \/>\n<meta property=\"og:site_name\" content=\"Am haZikaron\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jewage\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-08T21:41:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/rodnia-clr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"946\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AmhaZikaron\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/de\\\/project\\\/verwandtschaft\\\/\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/de\\\/project\\\/verwandtschaft\\\/\",\"name\":\"Verwandtschaft - Am haZikaron\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/de\\\/project\\\/verwandtschaft\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/de\\\/project\\\/verwandtschaft\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/rodnia-clr.jpg\",\"datePublished\":\"2025-04-17T00:47:58+00:00\",\"dateModified\":\"2025-08-08T21:41:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/de\\\/project\\\/verwandtschaft\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amhazikaron.org\\\/de\\\/project\\\/verwandtschaft\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/de\\\/project\\\/verwandtschaft\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/rodnia-clr.jpg\",\"contentUrl\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/rodnia-clr.jpg\",\"width\":946,\"height\":630,\"caption\":\"Rod'N'a cover\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/de\\\/project\\\/verwandtschaft\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/amhazikaron.org\\\/de\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verwandtschaft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/de\\\/\",\"name\":\"Am haZikaron\",\"description\":\"\u0418\u043d\u0441\u0442\u0438\u0442\u0443\u0442 \u043d\u0430\u0443\u043a\u0438, \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u044b \u0438 \u043d\u0430\u0441\u043b\u0435\u0434\u0438\u044f \u0435\u0432\u0440\u0435\u0439\u0441\u043a\u043e\u0433\u043e \u043d\u0430\u0440\u043e\u0434\u0430\",\"publisher\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amhazikaron.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/de\\\/#organization\",\"name\":\"Am haZikaron\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/amhazikaron.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo.svg\",\"width\":48,\"height\":48,\"caption\":\"Am haZikaron\"},\"image\":{\"@id\":\"https:\\\/\\\/amhazikaron.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jewage\",\"https:\\\/\\\/x.com\\\/AmhaZikaron\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verwandtschaft - Am haZikaron","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amhazikaron.org\/de\/project\/verwandtschaft\/","og_locale":"de_DE","og_type":"article","og_title":"Verwandtschaft - Am haZikaron","og_description":"Forschungsexpedition entlang der Migrationsrouten des j\u00fcdischen Volkes","og_url":"https:\/\/amhazikaron.org\/de\/project\/verwandtschaft\/","og_site_name":"Am haZikaron","article_publisher":"https:\/\/www.facebook.com\/jewage","article_modified_time":"2025-08-08T21:41:28+00:00","og_image":[{"width":946,"height":630,"url":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/rodnia-clr.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AmhaZikaron","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/amhazikaron.org\/de\/project\/verwandtschaft\/","url":"https:\/\/amhazikaron.org\/de\/project\/verwandtschaft\/","name":"Verwandtschaft - Am haZikaron","isPartOf":{"@id":"https:\/\/amhazikaron.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amhazikaron.org\/de\/project\/verwandtschaft\/#primaryimage"},"image":{"@id":"https:\/\/amhazikaron.org\/de\/project\/verwandtschaft\/#primaryimage"},"thumbnailUrl":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/rodnia-clr.jpg","datePublished":"2025-04-17T00:47:58+00:00","dateModified":"2025-08-08T21:41:28+00:00","breadcrumb":{"@id":"https:\/\/amhazikaron.org\/de\/project\/verwandtschaft\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amhazikaron.org\/de\/project\/verwandtschaft\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/amhazikaron.org\/de\/project\/verwandtschaft\/#primaryimage","url":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/rodnia-clr.jpg","contentUrl":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/rodnia-clr.jpg","width":946,"height":630,"caption":"Rod'N'a cover"},{"@type":"BreadcrumbList","@id":"https:\/\/amhazikaron.org\/de\/project\/verwandtschaft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/amhazikaron.org\/de\/home\/"},{"@type":"ListItem","position":2,"name":"Verwandtschaft"}]},{"@type":"WebSite","@id":"https:\/\/amhazikaron.org\/de\/#website","url":"https:\/\/amhazikaron.org\/de\/","name":"Am haZikaron","description":"\u0418\u043d\u0441\u0442\u0438\u0442\u0443\u0442 \u043d\u0430\u0443\u043a\u0438, \u043a\u0443\u043b\u044c\u0442\u0443\u0440\u044b \u0438 \u043d\u0430\u0441\u043b\u0435\u0434\u0438\u044f \u0435\u0432\u0440\u0435\u0439\u0441\u043a\u043e\u0433\u043e \u043d\u0430\u0440\u043e\u0434\u0430","publisher":{"@id":"https:\/\/amhazikaron.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amhazikaron.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/amhazikaron.org\/de\/#organization","name":"Am haZikaron","url":"https:\/\/amhazikaron.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/amhazikaron.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/logo.svg","contentUrl":"https:\/\/amhazikaron.org\/wp-content\/uploads\/2025\/04\/logo.svg","width":48,"height":48,"caption":"Am haZikaron"},"image":{"@id":"https:\/\/amhazikaron.org\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jewage","https:\/\/x.com\/AmhaZikaron"]}]}},"_links":{"self":[{"href":"https:\/\/amhazikaron.org\/de\/wp-json\/wp\/v2\/project\/3830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amhazikaron.org\/de\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/amhazikaron.org\/de\/wp-json\/wp\/v2\/types\/project"}],"version-history":[{"count":3,"href":"https:\/\/amhazikaron.org\/de\/wp-json\/wp\/v2\/project\/3830\/revisions"}],"predecessor-version":[{"id":3847,"href":"https:\/\/amhazikaron.org\/de\/wp-json\/wp\/v2\/project\/3830\/revisions\/3847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amhazikaron.org\/de\/wp-json\/wp\/v2\/media\/3831"}],"wp:attachment":[{"href":"https:\/\/amhazikaron.org\/de\/wp-json\/wp\/v2\/media?parent=3830"}],"wp:term":[{"taxonomy":"project-type","embeddable":true,"href":"https:\/\/amhazikaron.org\/de\/wp-json\/wp\/v2\/project-type?post=3830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}